{"id":28893,"date":"2010-06-02T12:19:00","date_gmt":"2010-06-02T16:19:00","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=28893"},"modified":"2010-06-02T12:19:00","modified_gmt":"2010-06-02T16:19:00","slug":"projeto-senarrondon-%e2%80%93-inscricao-ate-23-de-junho","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/projeto-senarrondon-%e2%80%93-inscricao-ate-23-de-junho\/28893","title":{"rendered":"Projeto Senar\/Rondon \u2013 inscri\u00e7\u00e3o at\u00e9 23 de junho"},"content":{"rendered":"<p>Est\u00e3o abertas at\u00e9 o dia 23 de junho as inscri\u00e7\u00f5es para o <strong><em>Projeto SENAR\/Rondon<\/em><\/strong>, uma iniciativa do Instituto CNA, ligado \u00e0 Confedera\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Brasil (CNA), que vai selecionar estudantes de ensino superior para trabalhos volunt\u00e1rios em escolas p\u00fablicas rurais. Os interessados em participar do processo seletivo devem preencher um formul\u00e1rio e enviar tamb\u00e9m uma carta de inten\u00e7\u00f5es com as a\u00e7\u00f5es que pretendem desenvolver nas cidades, bem como uma carta de recomenda\u00e7\u00e3o da coordena\u00e7\u00e3o do curso que est\u00e1 matriculado. O formul\u00e1rio, o edital e outras informa\u00e7\u00f5es podem ser obtidos no Canal do Produtor (<a href=\"http:\/\/www.canaldoprodutor.com.br\/projeto-senar-rondon\" target=\"_blank\">www.canaldoprodutor.com.br\/projeto-senar-rondon<\/a>).<\/p>\n<p>O objetivo \u00e9 oferecer a estes universit\u00e1rios oportunidades de realiza\u00e7\u00e3o de a\u00e7\u00f5es de interc\u00e2mbio t\u00e9cnico e cultural como atividade extracurricular durante o per\u00edodo de f\u00e9rias.<\/p>\n<p>O processo seletivo destina-se exclusivamente a estudantes universit\u00e1rios maiores de 18 anos e que estejam cursando pelo menos o 5\u00ba per\u00edodo nas \u00e1reas de Pedagogia, Servi\u00e7o Social, Agronomia, Veterin\u00e1ria, Enfermagem e Engenharia Civil. Eles v\u00e3o atuar na Bahia (BA), Distrito Federal (DF), Minas Gerais (MG), Mato Grosso do Sul (MS), Par\u00e1 (PA), Pernambuco (PE), Paran\u00e1 (PR), Rio de Janeiro (RJ), Rio Grande do Sul (RS) e Tocantins (TO). N\u00e3o haver\u00e1 taxa de inscri\u00e7\u00e3o.<\/p>\n<p>Todas as a\u00e7\u00f5es ter\u00e3o por objetivo melhorar as condi\u00e7\u00f5es de desempenho dos alunos das escolas rurais, promovendo o acesso ao conhecimento e a intera\u00e7\u00e3o, com envolvimento dos pais e da comunidade. Ser\u00e3o 17 dias de atividades. A primeira turma do Projeto SENAR\/Rondon sai a campo entre os dias 16 de julho e 1\u00ba e agosto deste ano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e3o abertas at\u00e9 o dia 23 de junho as inscri\u00e7\u00f5es para o Projeto SENAR\/Rondon, uma iniciativa do Instituto CNA, ligado \u00e0 Confedera\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Brasil (CNA), que vai selecionar estudantes de ensino superior para trabalhos volunt\u00e1rios em escolas p\u00fablicas rurais. Os interessados em participar do processo seletivo devem preencher um formul\u00e1rio e [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,370,353,295],"tags":[],"class_list":{"0":"post-28893","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-inscricao","8":"category-oportunidades","9":"category-vestibular","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/28893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=28893"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/28893\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=28893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=28893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=28893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}