{"id":28560,"date":"2010-05-26T12:09:04","date_gmt":"2010-05-26T16:09:04","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=28560"},"modified":"2010-05-26T12:09:31","modified_gmt":"2010-05-26T16:09:31","slug":"historias-de-sobrevivencia-em-nova-serie-do-animal-planet","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/historias-de-sobrevivencia-em-nova-serie-do-animal-planet\/28560","title":{"rendered":"Hist\u00f3rias de sobreviv\u00eancia em nova s\u00e9rie do Animal Planet"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-28561\" title=\"animal planet\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/animal-planet.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/animal-planet.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/animal-planet-250x160.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/animal-planet-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>A cada ano cerca de 100 mil pessoas s\u00e3o mortas por conta de agress\u00f5es cometidas por animais selvagens. Ainda assim muitas conseguem sobreviver aos mais brutais ferimentos, como mordidas venenosas e ferr\u00f5es letais. O <strong><em>Animal Planet<\/em><\/strong> apresenta a s\u00e9rie <strong><em>Os Sobreviventes (I&#8221;m Alive<\/em><\/strong>), que reconstitui ataques assustadores e quase fatais de animais ferozes ao ser humano.<\/p>\n<p>Com estreia na segunda-feira, 7 de junho, \u00e0s 22h, a nova s\u00e9rie relata ainda quais as solu\u00e7\u00f5es adotadas e os rem\u00e9dios que foram cruciais para a sobreviv\u00eancia dessas pessoas. Tamb\u00e9m \u00e9 avaliado se as atitudes e a personalidade de cada v\u00edtima podem fazer a diferen\u00e7a entre a vida e a morte. A cada epis\u00f3dio de OS SOBREVIVENTES, o telespectador ter\u00e1 acesso a dicas que poder\u00e3o ajud\u00e1-lo a salvar sua pr\u00f3pria vida ao se deparar com a f\u00faria animal.<\/p>\n<p>Veja abaixo a descri\u00e7\u00e3o dos epis\u00f3dios de Os Sobreviventes:<\/p>\n<p>Epis\u00f3dio 1: Jornadas<\/p>\n<p>Estreia: segunda-feira, 7 de junho, \u00e0s 22h<\/p>\n<p>Duas extraordin\u00e1rias hist\u00f3rias de sobreviventes nos mais distantes cantos da Terra. Ap\u00f3s ser mordido por uma aranha vi\u00fava negra, o adolescente Mike Makens luta durante sete dias contra dores agudas, at\u00e9 que sua fam\u00edlia arrisca tudo para contrabandear um ant\u00eddoto ilegal nos Estados Unidos, para conter os efeitos do veneno da aranha. No outro lado do planeta, Jeremy McGill est\u00e1 longe da fam\u00edlia e dos amigos ap\u00f3s ter sido atacado por um elefante selvagem na China, deixando-o entre a vida e a morte.<\/p>\n<p>Epis\u00f3dio 2: Adversidades<\/p>\n<p>Estreia: segunda-feira, 14 de junho, \u00e0s 22h<\/p>\n<p>Da Fl\u00f3rida e da \u00c1frica do Sul chegam duas hist\u00f3rias de sobreviv\u00eancia. Ap\u00f3s ter sido atacado por um tubar\u00e3o nas \u00e1guas rasas da costa da Fl\u00f3rida, Craig Hutto, de 16 anos, enfrenta uma terr\u00edvel batalha pela sobreviv\u00eancia, enquanto sua fam\u00edlia se esfor\u00e7a para ajud\u00e1-lo. Numa reserva animal, um casamento quase tem um final tr\u00e1gico quando o pai da noiva \u00e9 atacado por um leopardo. Piet van der Walt e sua fam\u00edlia enfrentam terr\u00edvel prova\u00e7\u00e3o, longe de quaisquer recursos m\u00e9dicos no cora\u00e7\u00e3o das savanas da \u00c1frica.<\/p>\n<p>Epis\u00f3dio 3: Campos de Batalha<\/p>\n<p>Estreia: segunda-feira, 21 de junho, \u00e0s 22h<\/p>\n<p>De uma zona de guerra a uma fazenda familiar, o perigo surge de v\u00e1rias formas. Em miss\u00e3o ao Iraque, a sargento Monique Munro-Harris \u00e9 picada por um escorpi\u00e3o. A ferroada pode ser fatal, o que exige uma arriscada retirada a\u00e9rea pelo territ\u00f3rio inimigo. Em uma reserva de le\u00f5es de propriedade de um amigo da fam\u00edlia, o adolescente Dane Keiser transforma-se em presa de tr\u00eas enormes felinos. Enquanto sua m\u00e3e assiste a tudo sem poder fazer nada, Dane \u00e9 arrastado para dentro da arena onde luta pela vida.<\/p>\n<p>Epis\u00f3dio 4: Salvos<\/p>\n<p>Estreia: segunda-feira, 28 de junho, \u00e0s 22h<\/p>\n<p>Brandon sabe que est\u00e1 em desvantagem, e a \u00fanica motiva\u00e7\u00e3o que o mant\u00e9m na luta \u00e9 pensar em sua filhinha beb\u00ea. No Hawaii, Tonga Loumoli faz um mergulho noturno com seu antigo parceiro, quando um peixe-agulha o ataca no peito. Gravemente ferido, sua \u00fanica chance de sobreviv\u00eancia \u00e9 que seu companheiro consiga arrast\u00e1-lo por mais de 1.500 metros em mar aberto at\u00e9 a margem.<\/p>\n<p>SERVI\u00c7O: Os Sobreviventes<\/p>\n<p>Canal: Animal Planet<\/p>\n<p>Estreia: segunda-feira, 7 de junho, \u00e0s 22h<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>O Animal Planet \u00e9 a \u00fanica marca global que oferece conte\u00fado envolvente, informativo e de alta qualidade dedicado totalmente ao mundo animal. O canal explora a rela\u00e7\u00e3o \u00fanica que existe entre os animais e os seres humanos, proporcionando entretenimento e informa\u00e7\u00e3o, atrav\u00e9s de plataformas m\u00faltiplas. O Animal Planet est\u00e1 dispon\u00edvel em mais de 315 milh\u00f5es de domic\u00edlios ao redor do mundo. Na Am\u00e9rica Latina, o canal foi lan\u00e7ado em outubro de 1997, como resultado de uma joint venture entre a Discovery Communications e a BBC Worlwide.<\/p>\n<p>\u00a92010 Discovery Communications, LLC. Animal Planet e o logotipo do Animal Planet s\u00e3o marcas da Discovery Communications, LLC. Todos os direitos reservados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cada ano cerca de 100 mil pessoas s\u00e3o mortas por conta de agress\u00f5es cometidas por animais selvagens. Ainda assim muitas conseguem sobreviver aos mais brutais ferimentos, como mordidas venenosas e ferr\u00f5es letais. O Animal Planet apresenta a s\u00e9rie Os Sobreviventes (I&#8221;m Alive), que reconstitui ataques assustadores e quase fatais de animais ferozes ao ser [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":28561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22,343],"tags":[],"class_list":{"0":"post-28560","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-televisao","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/animal-planet.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/28560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=28560"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/28560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/28561"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=28560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=28560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=28560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}