{"id":27778,"date":"2010-05-12T16:49:37","date_gmt":"2010-05-12T20:49:37","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=27778"},"modified":"2010-05-12T16:49:37","modified_gmt":"2010-05-12T20:49:37","slug":"inscricoes-premio-microsoft-educadores-inovadores-2010","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/inscricoes-premio-microsoft-educadores-inovadores-2010\/27778","title":{"rendered":"Inscri\u00e7\u00f5es &#8211; pr\u00eamio Microsoft Educadores Inovadores 2010"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-27779\" title=\"microsoft inscricao educadores inovadores premio 2010\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/microsoft-inscricao-educadores-inovadores-premio-2010.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/microsoft-inscricao-educadores-inovadores-premio-2010.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/microsoft-inscricao-educadores-inovadores-premio-2010-250x160.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/microsoft-inscricao-educadores-inovadores-premio-2010-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Est\u00e3o abertas at\u00e9 o dia 02 de julho as <strong><em>inscri\u00e7\u00f5es <\/em><\/strong>para a quinta edi\u00e7\u00e3o do <strong><em>Pr\u00eamio Microsoft Educadores Inovadores 2010<\/em><\/strong>, que valoriza e reconhece os melhores projetos educacionais desenvolvidos por professores brasileiros que utilizem tecnologia em processos de ensino e aprendizagem.\u00a0Para concorrer, basta acessar o site <a href=\"http:\/\/www.educadoresinovadores.com.br\/\" target=\"_blank\"><strong><em>www.educadoresinovadores.com.br<\/em><\/strong><\/a><strong><em> <\/em><\/strong>e seguir as instru\u00e7\u00f5es. Educadores de todo o Brasil podem se inscrever nas seguintes categorias: \u00a01) Ensino B\u00e1sico &#8211;\u00a0Podem se inscrever duplas de educadores e gestores da rede p\u00fablica de ensino, independentemente de sua \u00e1rea de atua\u00e7\u00e3o (ex. Portugu\u00eas, Matem\u00e1tica, F\u00edsica etc.), Secretarias Municipais ou Estaduais de Ensino, incluindo os N\u00facleos de Tecnologia Educacional (NTEs ou NRTEs), escolas p\u00fablicas (municipais, estaduais ou federais), institui\u00e7\u00f5es de ensino sem fins lucrativos (ONGs, Funda\u00e7\u00f5es etc.).<br \/>\n\u00b7Inova\u00e7\u00e3o em Comunidade<\/p>\n<p>\u00b7Inova\u00e7\u00e3o em Colabora\u00e7\u00e3o<\/p>\n<p>\u00b7Inova\u00e7\u00e3o em Conte\u00fado<\/p>\n<p>2) Ensino T\u00e9cnico &#8211;\u00a0Podem se inscrever individualmente educadores que lecionem disciplinas relacionadas \u00e0 Tecnologia da Informa\u00e7\u00e3o em escolas t\u00e9cnicas p\u00fablicas.<\/p>\n<p>\u00b7Educador Inovador de TI &#8211; Escolas T\u00e9cnicas<\/p>\n<p>Todos os projetos finalistas nas categorias de Ensino B\u00e1sico estar\u00e3o automaticamente concorrendo na categoria Educador Inovador, cuja vota\u00e7\u00e3o para escolha dos finalistas contar\u00e1 novamente com o voto popular online.<\/p>\n<p>Premia\u00e7\u00e3o<\/p>\n<p>O Pr\u00eamio Educadores Inovadores conta com tr\u00eas etapas. At\u00e9 o dia 19 de julho, doze projetos ser\u00e3o escolhidos e participar\u00e3o da etapa nacional do Pr\u00eamio que ser\u00e1 realizado em S\u00e3o Paulo no m\u00eas de agosto.<\/p>\n<p>Aqueles que apresentarem os melhores trabalhos ser\u00e3o premiados com um Notebook contendo o sistema operacional Microsoft Windows e o pacote de aplicativos Office. Assim, poder\u00e3o dar continuidade na cria\u00e7\u00e3o de novas id\u00e9ias, beneficiando cada vez mais pessoas e compartilhando o gosto e o conhecimento pela tecnologia educacional.<\/p>\n<p>Ap\u00f3s a etapa nacional, os respons\u00e1veis pelos projetos vencedores nas categorias destinadas \u00e0 educa\u00e7\u00e3o b\u00e1sica concorrer\u00e3o com seus trabalhos no F\u00f3rum Regional da Microsoft, que ser\u00e1 realizado em algum pa\u00eds da Am\u00e9rica Latina. Os classificados nessa etapa ir\u00e3o participar do Microsoft Worldwide Innovative Teachers Forum que, esse ano, ser\u00e1 realizado na \u00c1frica do Sul.<\/p>\n<p>Em 2009, o F\u00f3rum Mundial foi sediado pela primeira vez no Brasil, em Salvador (BA), e premiou dois educadores brasileiros: o professor Lucr\u00e9cio Filho de Oliveira, de Formoso do Araguaia (TO) e o educador Alex Vieira dos Santos. Na etapa nacional da premia\u00e7\u00e3o foram recebidos mais de 700 trabalhos.<\/p>\n<p>Para acompanhar as novidades do Pr\u00eamio, confira: www.educadoresinovadores.com.br<\/p>\n<p>Mais informa\u00e7\u00f5es no Blog: http:\/\/educadoresinovadores.spaces.live.com<\/p>\n<p>Siga no Twitter: www.twitter.com\/eduinova<\/p>\n<p>Parcerias<\/p>\n<p>A Microsoft desenvolve parcerias com diversas empresas brasileiras, como a Vitae Futurekids\/ Planeta Educa\u00e7\u00e3o, de S\u00e3o Jos\u00e9 dos Campos (SP), que faz parte do seleto grupo da Microsoft denominado &#8220;empresas do bem&#8221;. Elas trabalham com programas de cidadania e inclus\u00e3o social por meio da inclus\u00e3o digital.<\/p>\n<p>A Vitae Futurekids \u00e9 certificada e habilitada como &#8220;Parceiro T\u00e9cnico Educacional de Cidadania&#8221; e seus educadores j\u00e1 desenvolvem os programas &#8220;Aluno Monitor&#8221; e &#8220;Aprender em Parceria&#8221;, da Microsoft, em ambientes informatizados de escolas p\u00fablicas &#8211; principalmente em munic\u00edpios paulistas. Eles auxiliam os professores a desenvolver projetos que envolvam o uso de tecnologias no ensino e, al\u00e9m disso, transmitem as habilidades adquiridas a alunos e monitores, garantindo assim a multiplica\u00e7\u00e3o do conhecimento nesta nova era digital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e3o abertas at\u00e9 o dia 02 de julho as inscri\u00e7\u00f5es para a quinta edi\u00e7\u00e3o do Pr\u00eamio Microsoft Educadores Inovadores 2010, que valoriza e reconhece os melhores projetos educacionais desenvolvidos por professores brasileiros que utilizem tecnologia em processos de ensino e aprendizagem.\u00a0Para concorrer, basta acessar o site www.educadoresinovadores.com.br e seguir as instru\u00e7\u00f5es. Educadores de todo o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":27779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,370,353],"tags":[],"class_list":{"0":"post-27778","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-inscricao","9":"category-oportunidades","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/microsoft-inscricao-educadores-inovadores-premio-2010.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/27778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=27778"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/27778\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/27779"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=27778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=27778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=27778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}