{"id":27664,"date":"2010-05-10T17:15:07","date_gmt":"2010-05-10T21:15:07","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=27664"},"modified":"2010-05-10T17:15:07","modified_gmt":"2010-05-10T21:15:07","slug":"inscricoes-para-programa-jovens-embaixadores","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/inscricoes-para-programa-jovens-embaixadores\/27664","title":{"rendered":"Inscri\u00e7\u00f5es para programa Jovens Embaixadores"},"content":{"rendered":"<p>Est\u00e3o abertas as <strong><em>inscri\u00e7\u00f5es<\/em><\/strong> para a 9\u00aa edi\u00e7\u00e3o do &#8220;<strong><em>Programa Jovens Embaixadores<\/em><\/strong>&#8220;, promovido pela Embaixada dos Estados Unidos, em parceria com os setores p\u00fablico e privado. Voltado aos alunos de escolas p\u00fablicas de todo o Brasil, o programa levar\u00e1, no in\u00edcio de 2011, 35 estudantes brasileiros aos Estados Unidos por tr\u00eas semanas, com todas as despesas pagas.\u00a0Podem participar do programa jovens entre 15 e 18 anos de idade que estudem na rede p\u00fablica de ensino; tenham excelente desempenho escolar; possuam engajamento em atividades de responsabilidade social e de voluntariado h\u00e1 pelo menos um ano; tenham boa flu\u00eancia oral em ingl\u00eas, iniciativa e sejam comunicativos; demonstrem flexibilidade e facilidade para adaptar-se a realidades e culturas diferentes; mantenham bom relacionamento em casa, na escola e na comunidade; e tenham baixa renda familiar.<\/p>\n<p>Neste ano, devido \u00e0 grande procura pelo programa, a Embaixada Americana incluiu uma nova fase no processo seletivo. Os interessados dever\u00e3o primeiramente entrar no site da Embaixada (<a href=\"http:\/\/www.embaixada-americana.org.br\/\" target=\"_blank\">www.embaixada-americana.org.br<\/a>) e fazer a inscri\u00e7\u00e3o on-line. Ali o candidato responder\u00e1 um question\u00e1rio com perguntas b\u00e1sicas para saber se ele preenche os pr\u00e9-requisitos necess\u00e1rios. Caso seja aprovado nessa etapa, receber\u00e1 uma resposta autom\u00e1tica com os links para o question\u00e1rio preliminar e a lista de institui\u00e7\u00f5es parceiras onde ele dever\u00e1 entregar sua documenta\u00e7\u00e3o completa.<\/p>\n<p>As pr\u00e9-inscri\u00e7\u00f5es devem ser feitas at\u00e9 o dia 5 de agosto no site <a href=\"http:\/\/www.embaixadaamericana.org.br\/ya-index.php\" target=\"_blank\">http:\/\/www.embaixadaamericana.org.br\/ya-index.php<\/a>. O candidato que passar na pr\u00e9-sele\u00e7\u00e3o, dever\u00e1 se dirigir \u00e0 escola em que est\u00e1 matriculado para finalizar o processo de inscri\u00e7\u00e3o. Os estudantes podem obter mais informa\u00e7\u00f5es por meio do site da Cenp (Coordenadoria de Ensino e Normas Pedag\u00f3gicas), da Secretaria de Estado da Educa\u00e7\u00e3o: <a href=\"http:\/\/cenp.edunet.sp.gov.br\/index.htm\" target=\"_blank\">http:\/\/cenp.edunet.sp.gov.br\/index.htm<\/a>.<\/p>\n<p>Outra novidade \u00e9 que a partir deste ano, o Brasil passa a receber tamb\u00e9m Jovens Embaixadores Americanos. Durante tr\u00eas semanas, no per\u00edodo de 2 a 20 de agosto, 12 estudantes americanos visitar\u00e3o o Pa\u00eds em uma programa\u00e7\u00e3o semelhante \u00e0 dos brasileiros nos Estados Unidos.\u00a0 Eles come\u00e7ar\u00e3o pela capital (Bras\u00edlia), depois ser\u00e3o divididos em sub-grupos e cada um ir\u00e1 para um Estado diferente (tr\u00eas para o Amazonas, tr\u00eas para Pernambuco, quatro para o Paran\u00e1 e tr\u00eas para a Bahia). A programa\u00e7\u00e3o ser\u00e1 encerrada no Rio de Janeiro.<\/p>\n<p>Durante o lan\u00e7amento oficial da edi\u00e7\u00e3o 2011 do programa, o embaixador dos Estados Unidos no Brasil, Thomas Shannon, anunciou tamb\u00e9m os jovens embaixadores de edi\u00e7\u00f5es anteriores que ganharam dez bolsas de estudo para cursos de ver\u00e3o na Cushing Academy, Phillips Exeter Academy, Phillips Academy Andover e Universidade da Calif\u00f3rnia &#8211; Riverside e Irvine.<\/p>\n<p>Entre os vencedores est\u00e1 Ellen Deuter Barbosa, 17 anos. Ex-aluna da Escola Estadual Professora Laurentina Lorena Correa da Silva, em Santa Isabel (Grande SP), onde cursou da 5\u00aa a 8\u00aa s\u00e9rie do Ensino Fundamental e todo o Ensino M\u00e9dio, Ellen ganhou um curso de ver\u00e3o na Universidade da California &#8211; Irvine. &#8220;Foi muito emocionante saber que ganhei. Na hora, chorei. Alguns amigos que fizeram o &#8216;Jovens Embaixadores&#8217; comigo tamb\u00e9m ganharam bolsa e dois deles ir\u00e3o para a mesma universidade que eu. Tenho certeza de que novamente, assim como a viagem que fiz pelo programa no ano passado, ser\u00e1 uma experi\u00eancia incr\u00edvel e enriquecedora, especialmente porque haver\u00e1 jovens de diversos pa\u00edses&#8221;, conta.<\/p>\n<p>Hoje estudante do primeiro ano de direito, Ellen afirma que o programa &#8220;Jovens Embaixadores&#8221; foi um marco em sua vida. &#8220;De certa forma, me tornei um exemplo na minha cidade (Santa Isabel) para os demais alunos da rede p\u00fablica. \u00c9 uma forma de demonstrar que quando queremos algo, basta se esfor\u00e7ar e buscar as oportunidades. Aprendi muito com a viagem oferecida pelo programa. Tornei-me muito mais independente e madura. Foi o programa que despertou em mim a vontade de seguir carreira diplom\u00e1tica. \u00c9 por isso que estou estudando direito. N\u00e3o \u00e9 s\u00f3 uma viagem de lazer, \u00e9 uma viagem de cultura e muito aprendizado&#8221;, relata. Ellen embarca para os Estados Unidos em junho e vai fazer um curso de neg\u00f3cios.<\/p>\n<p>O interc\u00e2mbio entre Estados Unidos e Brasil promovido pelo programa &#8220;Jovens Embaixadores&#8221; foi criado em 2002 e hoje j\u00e1 \u00e9 replicado em outros 17 pa\u00edses. Desde que foi lan\u00e7ado, 212 jovens brasileiros j\u00e1 foram beneficiados.<\/p>\n<p>Da Secretaria da Educa\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e3o abertas as inscri\u00e7\u00f5es para a 9\u00aa edi\u00e7\u00e3o do &#8220;Programa Jovens Embaixadores&#8220;, promovido pela Embaixada dos Estados Unidos, em parceria com os setores p\u00fablico e privado. Voltado aos alunos de escolas p\u00fablicas de todo o Brasil, o programa levar\u00e1, no in\u00edcio de 2011, 35 estudantes brasileiros aos Estados Unidos por tr\u00eas semanas, com todas as [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,351,370,353],"tags":[],"class_list":{"0":"post-27664","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-cursos","8":"category-inscricao","9":"category-oportunidades","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/27664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=27664"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/27664\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=27664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=27664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=27664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}