{"id":27044,"date":"2010-04-29T19:29:41","date_gmt":"2010-04-29T23:29:41","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=27044"},"modified":"2010-04-29T19:29:41","modified_gmt":"2010-04-29T23:29:41","slug":"copa-do-mundo-2010-personagens-cartoon-para-os-fas-de-futebol","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/copa-do-mundo-2010-personagens-cartoon-para-os-fas-de-futebol\/27044","title":{"rendered":"Copa do Mundo 2010 &#8211; personagens Cartoon para os f\u00e3s de futebol"},"content":{"rendered":"<p>Em ritmo de <strong><em>Copa do Mundo 2010<\/em><\/strong>, o Cartoon Network come\u00e7a em maio os treinamentos com os jogos da edi\u00e7\u00e3o 2010 do <strong><em>COPA TOON<\/em><\/strong>. No computador ou no celular, os f\u00e3s do canal poder\u00e3o jogar futebol com seus personagens favoritos onde quer que estejam. A partir do dia 3 de maio, os internautas podem acessar o link <a href=\"http:\/\/www.copatoon.com.br\/\" target=\"_blank\">www.copatoon.com.br<\/a> para visitar o site especial desenvolvido para disputar uma atividade multiplayer na qual se pode escolher quatro diferente equipes: Ben 10, As Meninas Superpoderosas, Scooby-Doo e Chowder. Os jogadores devem entrar com o mesmo nome de usu\u00e1rio que usam no site oficial do Cartoon Network (<a href=\"http:\/\/www.cartoonnetwork.com.br\" target=\"_self\">www.cartoonnetwork.com.br<\/a>) para disputar partidas individuais contra outros jogadores de seu pa\u00eds ou mesmo de outros territ\u00f3rios da Am\u00e9rica Latina. E aqueles que n\u00e3o quiserem entrar no ranking oficial podem optar por jogar apenas como convidados.<\/p>\n<p>J\u00e1 o COPA TOON para celular permite que os f\u00e3s de esportes assinem o jogo (modo de compra) e disputem partidas de futebol usando os principais personagens do canal atrav\u00e9s de seus aparelhos. Neste modo, s\u00e3o cinco times dispon\u00edveis: a equipe de Ben 10, seguida pelas equipes de Docinho (As Meninas Superpoderosas), de Chowder, de Billy (As Terr\u00edveis Aventuras de Billy e Mandy) e de Zak S\u00e1bado (S\u00e1bados Secretos), sendo que cada personagem utiliza seus pr\u00f3prios poderes para dominar o advers\u00e1rio em campo. \u00c9 poss\u00edvel selecionar entre cinco est\u00e1dios diferentes, al\u00e9m de poder decidir as forma\u00e7\u00f5es e estrat\u00e9gias de jogo. Desta forma, cada usu\u00e1rio acaba disputando um jogo completamente diferente do outros. A iniciativa mobile COPA TOON foi desenvolvida pela empresas GlobalFun e Kilo e estar\u00e1 dispon\u00edvel em tr\u00eas idiomas: ingl\u00eas, espanhol e portugu\u00eas nos aparelhos equipados com Java.<\/p>\n<p>Al\u00e9m disso, o campeonato invadir\u00e1 as telas. A partir do dia 5 de maio, toda quarta das 18h \u00e0s 20h, o Cartoon Network apresenta a segunda temporada de FUTEBOL NA RUA, uma produ\u00e7\u00e3o em estilo anime criada conjuntamente pela T\u00e9l\u00e9images Kids da Fran\u00e7a e pela RAI da It\u00e1lia. A s\u00e9rie conta a hist\u00f3ria de um grupo de crian\u00e7as que participar\u00e3o da primeira Copa do Mundo de futebol de rua, uma estranha competi\u00e7\u00e3o realizada de forma secreta. Para quem perdeu, mini-maratonas da s\u00e9rie ser\u00e3o exibidas no final do m\u00eas. A primeira delas, sexta-feira, dia 28 de maio, das 17h \u00e0s 20h, e a outra no s\u00e1bado, dia 29 de maio, das 20h \u00e0s 23h.<\/p>\n<p>Para completar, os simp\u00e1ticos avatares do site oficial, conhecidos como Toonix, ser\u00e3o as estrelas de vinhetas tem\u00e1ticas que ser\u00e3o exibidas depois das partidas disputadas pelos pa\u00edses da Am\u00e9rica Latina (Brasil, Argentina, Chile, Honduras, M\u00e9xico, Paraguai e Uruguai) com parab\u00e9ns para os vencedores e mensagens de incentivo para os perdedores.<\/p>\n<p>Cartoon Network, rede de TV por assinatura com transmiss\u00e3o 24 horas da Turner Broadcasting System, Inc., traz os melhores personagens animados e live-action em desenhos, filmes, videoclipes e games, por meio de diversas plataformas incluindo TV, internet, eventos, produtos licenciados e meios digitais. O canal abriga o maior acervo de desenhos animados, com produ\u00e7\u00f5es premiadas como As Meninas Superpoderosas, Ben 10, As Terr\u00edveis Aventuras de Billy e Mandy, A Mans\u00e3o Foster para Amigos Imagin\u00e1rios, Chowder, As Trapalhadas de Flapjack, S\u00e1bados Secretos e Ben 10: For\u00e7a Alien\u00edgena. O canal foi lan\u00e7ado em 30 de abril de 1993 e \u00e9 transmitido na Am\u00e9rica Latina em mais de 30,2 milh\u00f5es de domic\u00edlios em portugu\u00eas, espanhol e ingl\u00eas.<\/p>\n<p>www.CartoonNetwork.com.BR<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em ritmo de Copa do Mundo 2010, o Cartoon Network come\u00e7a em maio os treinamentos com os jogos da edi\u00e7\u00e3o 2010 do COPA TOON. No computador ou no celular, os f\u00e3s do canal poder\u00e3o jogar futebol com seus personagens favoritos onde quer que estejam. A partir do dia 3 de maio, os internautas podem acessar [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22,343],"tags":[],"class_list":{"0":"post-27044","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-televisao","8":"entry","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/27044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=27044"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/27044\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=27044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=27044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=27044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}