{"id":264238,"date":"2026-06-01T22:18:37","date_gmt":"2026-06-02T01:18:37","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2026\/dupla-sena-resultado-do-concurso-2964-sorteado-segunda-feira-01-06-2026\/264238"},"modified":"2026-06-01T22:18:37","modified_gmt":"2026-06-02T01:18:37","slug":"dupla-sena-resultado-do-concurso-2964-sorteado-segunda-feira-01-06-2026","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2026\/dupla-sena-resultado-do-concurso-2964-sorteado-segunda-feira-01-06-2026\/264238","title":{"rendered":"Dupla Sena: Resultado do concurso 2964 sorteado  Segunda-feira 01\/06\/2026"},"content":{"rendered":"<p>Resultado da Dupla Sena, concurso 2964, realizado na  Segunda-feira, dia 01\/06\/2026 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo.  A Dupla Sena 2964 n\u00e3o teve acertador do pr\u00eamio principal e a previs\u00e3o do pr\u00eamio para o pr\u00f3ximo sorteio, Dupla Sena 2965, \u00e9 de R$ 2.300.000,00. Com este resultado a Dupla Sena  esta acumulada ha  11 sorteios<\/p>\n<p>Veja tamb\u00e9m: <\/p>\n<h2>N\u00fameros Sorteados Dupla Sena 2964<\/h2>\n<h4>Primeiro Sorteio:<\/h4>\n<table>\n<tr>\n<td><span class=\"numberCircleDuplaSena\">04<\/span><\/td>\n<td><span class=\"numberCircleDuplaSena\">05<\/span><\/td>\n<td><span class=\"numberCircleDuplaSena\">11<\/span><\/td>\n<td><span class=\"numberCircleDuplaSena\">24<\/span><\/td>\n<td><span class=\"numberCircleDuplaSena\">30<\/span><\/td>\n<td><span class=\"numberCircleDuplaSena\">41<\/span><\/td>\n<\/tr>\n<\/table>\n<h4>Segundo Sorteio<\/h4>\n<table>\n<tr>\n<td><span class=\"numberCircleDuplaSena\">03<\/span><\/td>\n<td><span class=\"numberCircleDuplaSena\">07<\/span><\/td>\n<td><span class=\"numberCircleDuplaSena\">26<\/span><\/td>\n<td><span class=\"numberCircleDuplaSena\">27<\/span><\/td>\n<td><span class=\"numberCircleDuplaSena\">44<\/span><\/td>\n<td><span class=\"numberCircleDuplaSena\">49<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Premia\u00e7\u00e3o Dupla Sena 2964<\/h2>\n<h4>Primeiro Sorteio<\/h4>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhadores<\/th>\n<th>Pr\u00eamio (R$)<\/th>\n<\/tr>\n<tr>\n<td>6<\/td>\n<td>0<\/td>\n<td>0,00<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td>6<\/td>\n<td>9.426,64<\/td>\n<\/tr>\n<tr>\n<td>4<\/td>\n<td>473<\/td>\n<td>136,65<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td>9.970<\/td>\n<td>3,24<\/td>\n<\/tr>\n<\/table>\n<h4>Segundo Sorteio<\/h4>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhadores<\/th>\n<th>Pr\u00eamio (R$)<\/th>\n<\/tr>\n<tr>\n<td>6<\/td>\n<td>0<\/td>\n<td>0,00<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td>15<\/td>\n<td>3.393,59<\/td>\n<\/tr>\n<tr>\n<td>4<\/td>\n<td>658<\/td>\n<td>98,23<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td>11.650<\/td>\n<td>2,77<\/td>\n<\/tr>\n<\/table>\n<h2>Total de Apostas realizadas<\/h2>\n<p>No concurso 2964 da Dupla Sena foi realizado um total de 615.055 apostas.<\/p>\n<h2>Pr\u00f3ximo Sorteio da Dupla Sena <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Quarta-feira 03\/06\/2026, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 2.300.000,00.<\/p>\n<h3>\u00daltimos Resultados da Dupla Sena<\/h3>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2026\/dupla-sena-resultado-do-concurso-2963-sorteado-sexta-feira-29-05-2026\/264193\">Dupla Sena 2963<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2026\/dupla-sena-resultado-do-concurso-2962-sorteado-quarta-feira-27-05-2026\/264153\">Dupla Sena 2962<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2026\/dupla-sena-resultado-do-concurso-2961-sorteado-segunda-feira-25-05-2026\/264118\">Dupla Sena 2961<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2026\/dupla-sena-resultado-do-concurso-2960-sorteado-sexta-feira-22-05-2026\/264082\">Dupla Sena 2960<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Resumo do sorteio da Dupla Sena 2964<\/h2>\n<ul>\n<li>Dos n\u00fameros sorteados neste concurso da Dupla Sena o que mais saiu nos \u00faltimos 12 meses foi o 04, sorteado 22 vezes.<\/li>\n<li>O que menos saiu foi o n\u00famero 41, sorteado apenas 11 vezes.<\/li>\n<li>Das 50 dezenas, a que est\u00e1 h\u00e1 mais tempo sem ser sorteada \u00e9 a 50 que n\u00e3o sai tem 159  dias.<\/li>\n<li>O pr\u00eamio de maior valor pago neste per\u00edodo, sem contar o da Dupla Sena de P\u00e1scoa, foi de R$ 16.564.686,23 correspondente ao concurso 2871, sorteado em 10\/10\/2025.<\/li>\n<li>Nos \u00faltimos 12 meses foram realizados 150 sorteios e premiadas 12 pessoas que acertaram os 6 n\u00fameros da Dupla Sena.<\/li>\n<li>Neste per\u00edodo a Dupla Sena n\u00e3o teve acertadores em 140 oportunidades.<\/li>\n<\/ul>\n<\/ul>\n<h3>Hist\u00f3rico dos n\u00fameros sorteados neste concurso da Dupla Sena<\/h3>\n<p>Nesta tabela voc\u00ea ir\u00e1 encontrar as seguintes informa\u00e7\u00f5es relativas aos sorteios da Dupla Sena dos \u00faltimos 12 meses:<br \/>A quantidade de vezes que o n\u00famero foi sorteado na Dupla Sena,<br \/>A quantidade de sorteios que este n\u00famero saiu e o concurso teve ganhador,<br \/>A data do \u00faltimo sorteio na Dupla Sena desta dezena.<\/p>\n<table>\n<tr>\n<th>Dezena<\/th>\n<th>Total<\/th>\n<th>Premiada<\/th>\n<th>Data<\/th>\n<\/tr>\n<tr>\n<td>04<\/td>\n<td>22<\/td>\n<td>4<\/td>\n<td>20\/03\/2026<\/td>\n<\/tr>\n<tr>\n<td>05<\/td>\n<td>21<\/td>\n<td>1<\/td>\n<td>18\/05\/2026<\/td>\n<\/tr>\n<tr>\n<td>11<\/td>\n<td>22<\/td>\n<td>1<\/td>\n<td>29\/05\/2026<\/td>\n<\/tr>\n<tr>\n<td>24<\/td>\n<td>17<\/td>\n<td>0<\/td>\n<td>27\/05\/2026<\/td>\n<\/tr>\n<tr>\n<td>30<\/td>\n<td>18<\/td>\n<td>1<\/td>\n<td>11\/05\/2026<\/td>\n<\/tr>\n<tr>\n<td>41<\/td>\n<td>11<\/td>\n<td>0<\/td>\n<td>29\/04\/2026<\/td>\n<\/tr>\n<\/table>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dupla Sena 2964 &#8211; Resultado, rateio e ganhadores da Dupla Sena 2964 sorteado em 01\/06\/2026.<\/p>\n","protected":false},"author":5,"featured_media":196328,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[360,335],"tags":[],"class_list":["post-264238","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dupla-sena","category-loteria","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/dupla-sena-resultado.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/264238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=264238"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/264238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196328"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=264238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=264238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=264238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}