{"id":263874,"date":"2026-05-12T22:00:59","date_gmt":"2026-05-13T01:00:59","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2026\/mega-sena-resultado-do-concurso-3007-sorteado-terca-feira-12-05-2026\/263874"},"modified":"2026-05-12T22:00:59","modified_gmt":"2026-05-13T01:00:59","slug":"mega-sena-resultado-do-concurso-3007-sorteado-terca-feira-12-05-2026","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2026\/mega-sena-resultado-do-concurso-3007-sorteado-terca-feira-12-05-2026\/263874","title":{"rendered":"Mega Sena: Resultado do concurso 3007 sorteado  Ter\u00e7a-feira 12\/05\/2026"},"content":{"rendered":"<p>Resultado da Mega Sena, concurso 3007, realizado na  Ter\u00e7a-feira, dia 12\/05\/2026 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo.  A Mega Sena 3007 n\u00e3o teve acertador do pr\u00eamio principal e a previs\u00e3o do pr\u00eamio para o pr\u00f3ximo sorteio, Mega Sena 3008, \u00e9 de R$ 60.000.000,00. Com este resultado a Mega Sena  esta acumulada ha  5 sorteios<\/p>\n<p>Veja tamb\u00e9m: <a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2020\/todos-os-resultados-da-mega-sena\/199303\"> Todos os resultados da Mega Sena<\/a><\/p>\n<h2>N\u00fameros Sorteados Mega Sena 3007<\/h2>\n<table>\n<tr>\n<td><span class=\"numberCircleMega\">17<\/span><\/td>\n<td><span class=\"numberCircleMega\">19<\/span><\/td>\n<td><span class=\"numberCircleMega\">27<\/span><\/td>\n<td><span class=\"numberCircleMega\">32<\/span><\/td>\n<td><span class=\"numberCircleMega\">38<\/span><\/td>\n<td><span class=\"numberCircleMega\">44<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Premia\u00e7\u00e3o Mega Sena 3007<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad.<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td> 6<\/td>\n<td>0<\/td>\n<td>0,00<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td>89<\/td>\n<td>23.778,68<\/td>\n<\/tr>\n<tr>\n<td>4<\/td>\n<td>5.035<\/td>\n<td>692,83<\/td>\n<\/tr>\n<\/table>\n<h2>Total de Apostas realizadas<\/h2>\n<p>No concurso 3007 da Mega Sena foi realizado um total de 8.851.363 apostas.<\/p>\n<h2>Pr\u00f3ximo Sorteio da Mega Sena <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Quinta-feira 14\/05\/2026, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 60.000.000,00.<\/p>\n<h3>\u00daltimos Resultados da Mega Sena<\/h3>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2026\/mega-sena-resultado-do-concurso-3006-sorteado-sabado-09-05-2026\/263830\">Mega Sena 3006<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2026\/mega-sena-resultado-do-concurso-3005-sorteado-quinta-feira-07-05-2026\/263736\">Mega Sena 3005<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2026\/mega-sena-resultado-do-concurso-3004-sorteado-terca-feira-05-05-2026\/263706\">Mega Sena 3004<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2026\/mega-sena-resultado-do-concurso-3003-sorteado-sabado-02-05-2026\/263669\">Mega Sena 3003<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Resumo do sorteio da Mega Sena 3007<\/h2>\n<ul>\n<li>Dos n\u00fameros sorteados neste concurso da Mega Sena o que mais saiu nos \u00faltimos 12 meses foi o 27, sorteado 21 vezes.<\/li>\n<li>O que menos saiu foi o n\u00famero 17, sorteado apenas 16 vezes.<\/li>\n<li>Das 60 dezenas, a que est\u00e1 h\u00e1 mais tempo sem ser sorteada \u00e9 a 34 que n\u00e3o sai tem 110  dias.<\/li>\n<li>O pr\u00eamio de maior valor pago neste per\u00edodo, sem contar o da Mega Sena da Virada, foi de R$ 158.039.482,14 correspondente ao concurso 2979, sorteado em 03\/03\/2026.<\/li>\n<li>Nos \u00faltimos 12 meses foram realizados 146 sorteios e premiadas 29 pessoas que acertaram os 6 n\u00fameros da Mega Sena.<\/li>\n<li>Neste per\u00edodo a Mega Sena n\u00e3o teve acertadores em 124 oportunidades.<\/li>\n<\/ul>\n<\/ul>\n<h3>Hist\u00f3rico dos n\u00fameros sorteados neste concurso da Mega Sena<\/h3>\n<p>Nesta tabela voc\u00ea ir\u00e1 encontrar as seguintes informa\u00e7\u00f5es relativas aos sorteios da Mega Sena dos \u00faltimos 12 meses:<br \/>A quantidade de vezes que o n\u00famero foi sorteado na Mega Sena,<br \/>A quantidade de sorteios que este n\u00famero saiu e o concurso teve ganhador,<br \/>A data do \u00faltimo sorteio na Mega Sena desta dezena.<\/p>\n<table>\n<tr>\n<th>Dezena<\/th>\n<th>Total<\/th>\n<th>Premiada<\/th>\n<th>Data<\/th>\n<\/tr>\n<tr>\n<td>17<\/td>\n<td>16<\/td>\n<td>3<\/td>\n<td>07\/05\/2026<\/td>\n<\/tr>\n<tr>\n<td>19<\/td>\n<td>16<\/td>\n<td>4<\/td>\n<td>31\/03\/2026<\/td>\n<\/tr>\n<tr>\n<td>27<\/td>\n<td>21<\/td>\n<td>6<\/td>\n<td>02\/05\/2026<\/td>\n<\/tr>\n<tr>\n<td>32<\/td>\n<td>20<\/td>\n<td>3<\/td>\n<td>28\/04\/2026<\/td>\n<\/tr>\n<tr>\n<td>38<\/td>\n<td>17<\/td>\n<td>0<\/td>\n<td>23\/04\/2026<\/td>\n<\/tr>\n<tr>\n<td>44<\/td>\n<td>16<\/td>\n<td>1<\/td>\n<td>28\/03\/2026<\/td>\n<\/tr>\n<\/table>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mega Sena 3007 &#8211; Resultado, rateio e ganhadores da Mega Sena 3007 sorteado em 12\/05\/2026.<\/p>\n","protected":false},"author":5,"featured_media":194758,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[335,355],"tags":[],"class_list":{"0":"post-263874","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-mega-sena","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-mega-sena-loterias.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/263874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=263874"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/263874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/194758"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=263874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=263874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=263874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}