{"id":26191,"date":"2010-04-15T16:41:10","date_gmt":"2010-04-15T20:41:10","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=26191"},"modified":"2010-04-15T16:41:10","modified_gmt":"2010-04-15T20:41:10","slug":"ipva-restituicao-em-sp","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/ipva-restituicao-em-sp\/26191","title":{"rendered":"IPVA &#8211; restitui\u00e7\u00e3o em SP"},"content":{"rendered":"<p><strong><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-26192\" title=\"ipva sp restituicao\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/ipva-sp-restituicao.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/ipva-sp-restituicao.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/ipva-sp-restituicao-250x160.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/ipva-sp-restituicao-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>IPVA<\/em><\/strong> <strong><em>restitui\u00e7\u00e3o<\/em><\/strong> &#8211; o governo de S\u00e3o Paulo vai devolver R$ 12,8 milh\u00f5es a contribuintes que tiveram <strong><em>ve\u00edculos roubados<\/em><\/strong> ou furtados em <strong><em>2009<\/em><\/strong> no territ\u00f3rio do Estado de S\u00e3o Paulo. Para consulta acesse o endere\u00e7o <a href=\"http:\/\/www3.fazenda.sp.gov.br\" target=\"_blank\"><strong><em>www3.fazenda.sp.gov.br<\/em><\/strong><\/a>. O reembolso refere-se \u00e0 restitui\u00e7\u00e3o proporcional do IPVA (Imposto sobre a Propriedade de Ve\u00edculos Automotores) e beneficia os motoristas que j\u00e1 haviam pago o tributo quando ocorreu o crime.<\/p>\n<p>Segundo a Secretaria da Fazenda, ser\u00e3o creditadas diferen\u00e7as relativas a 48,7 mil ve\u00edculos, distribu\u00eddas em quatro lotes at\u00e9 o final de abril. O contribuinte nessa situa\u00e7\u00e3o n\u00e3o precisa fazer nenhuma solicita\u00e7\u00e3o. O reembolso \u00e9 autom\u00e1tico, j\u00e1 que os sistemas da Secretaria de Seguran\u00e7a P\u00fablica e do Detran est\u00e3o integrados ao da Fazenda. Os valores ficar\u00e3o \u00e0 disposi\u00e7\u00e3o do propriet\u00e1rio \u00e0 \u00e9poca da ocorr\u00eancia no banco Nossa Caixa e obedecer\u00e3o ao calend\u00e1rio de restitui\u00e7\u00e3o de acordo com a tabela abaixo. Vale lembrar que o contribuinte que estiver inadimplente n\u00e3o poder\u00e1 resgatar o valor enquanto houver a pend\u00eancia.<\/p>\n<p>Ocorr\u00eancia \/ Data da Libera\u00e7\u00e3o &#8211; 1\u00ba trimestre de 2009 &#8211; 15\/03\/2010; 2\u00ba trimestre de 2009 &#8211; 31\/03\/2010; 3\u00ba trimestre de 2009 &#8211; 15\/04\/2010; \u00a04\u00ba trimestre de 2009 &#8211; 30\/04\/2010.<\/p>\n<p>A restitui\u00e7\u00e3o proporcional do IPVA aos donos de ve\u00edculos roubados passou a valer a partir de 2008, conforme regra estabelecida com a Lei 13.032 e aprimorada posteriormente pela Lei 13.296, ambas assinadas pelo governador Jos\u00e9 Serra em 2008. A norma garante ao contribuinte a dispensa proporcional do pagamento do IPVA de 2009, a partir do m\u00eas da ocorr\u00eancia do fato, \u00e0 raz\u00e3o de 1\/12 (um doze avos) por m\u00eas do valor do imposto devido ao Estado. Caso o IPVA j\u00e1 tenha sido pago, o propriet\u00e1rio ter\u00e1 direito a restitui\u00e7\u00e3o. Para tanto, o contribuinte deve registrar o boletim de ocorr\u00eancia para ter direito ao benef\u00edcio.<\/p>\n<p>No caso de recupera\u00e7\u00e3o do ve\u00edculo, volta a ser devido o IPVA no exerc\u00edcio em que ela ocorrer, proporcionalmente aos meses que restarem at\u00e9 o final do respectivo ano, \u00e0 raz\u00e3o de 1\/12 por m\u00eas, devendo computar o m\u00eas da recupera\u00e7\u00e3o. Este \u00e9 o principal motivo pelo qual a restitui\u00e7\u00e3o do imposto pago em 2009 est\u00e1 sendo realizada somente neste ano.<\/p>\n<p>Confira os passos necess\u00e1rios para assegurar o direito ao ressarcimento e efetuar a consulta da devolu\u00e7\u00e3o do IPVA:<\/p>\n<p>Como obter a dispensa e restitui\u00e7\u00e3o<\/p>\n<p>Passo 1<br \/>\nRegistrar o Boletim de Ocorr\u00eancia (BO)<br \/>\na) O Boletim de Ocorr\u00eancia pode ser feito pela Internet, desde que a subtra\u00e7\u00e3o do ve\u00edculo n\u00e3o tenha se dado mediante uso de viol\u00eancia ou grave amea\u00e7a.<br \/>\nb) Se houver viol\u00eancia ou grave amea\u00e7a, o registro do evento ser\u00e1 feito em unidade policial.<\/p>\n<p>Passo 2<br \/>\nO Boletim de Ocorr\u00eancia (BO) bloqueia o ve\u00edculo no Detran.<\/p>\n<p>Passo 3<br \/>\nProcedimentos para restitui\u00e7\u00e3o do IPVA<\/p>\n<p>Situa\u00e7\u00e3o 1: Furto ou roubo ocorrido no m\u00eas de janeiro DEPOIS do pagamento integral do IPVA com desconto:<br \/>\nSe o ve\u00edculo for furtado ou roubado no m\u00eas de janeiro, ap\u00f3s o pagamento integral do IPVA de 2009 com desconto, em princ\u00edpio a restitui\u00e7\u00e3o corresponder\u00e1 ao valor total pago. Todavia, ocorrendo recupera\u00e7\u00e3o do ve\u00edculo, o propriet\u00e1rio estar\u00e1 sujeito ao IPVA do exerc\u00edcio proporcionalmente aos meses que restarem at\u00e9 o final do ano, devendo computar o m\u00eas da recupera\u00e7\u00e3o, \u00e0 raz\u00e3o de 1\/12 (um doze avos) por m\u00eas do valor do imposto devido ao Estado, de modo que haver\u00e1 redu\u00e7\u00e3o do valor a restituir.<\/p>\n<p>Situa\u00e7\u00e3o 2: Furto ou roubo ocorrido AP\u00d3S o pagamento de alguma parcela do IPVA, por exemplo em mar\u00e7o:<br \/>\nSe o contribuinte tiver pago duas parcelas do IPVA (janeiro e fevereiro) e tiver seu carro furtado ou roubado em mar\u00e7o, ele somente deve 2\/12 do IPVA\/2009 e ter\u00e1 direito \u00e0 restitui\u00e7\u00e3o do valor pago a mais que esses 2\/12.<br \/>\n\u00a0<br \/>\nSitua\u00e7\u00e3o 3: Furto ou roubo ocorrido a partir do m\u00eas de abril DEPOIS do pagamento integral do IPVA\/2009:<br \/>\nSe o contribuinte tiver pago o IPVA integralmente, e tiver seu carro furtado ou roubado em agosto, somente deve 7\/12 do IPVA\/2009 e ter\u00e1 direito \u00e0 restitui\u00e7\u00e3o do valor pago a mais, ou seja, ter\u00e1 direito a receber de volta 5\/12 do valor pago do IPVA\/2009.<\/p>\n<p>Como consultar os valores de restitui\u00e7\u00e3o<br \/>\n1. Acesse a \u00e1rea do IPVA no site da Secretaria da Fazenda (www3.fazenda.sp.gov.br).<br \/>\n2. Na barra \u00e0 esquerda, clique no link Restitui\u00e7\u00e3o.<br \/>\n3. Informe o Renavam e o n\u00famero do boletim de ocorr\u00eancia.<\/p>\n<p>IPVA &#8211; restitui\u00e7\u00e3o a propriet\u00e1rios de ve\u00edculos roubados<\/p>\n","protected":false},"excerpt":{"rendered":"<p>IPVA restitui\u00e7\u00e3o &#8211; o governo de S\u00e3o Paulo vai devolver R$ 12,8 milh\u00f5es a contribuintes que tiveram ve\u00edculos roubados ou furtados em 2009 no territ\u00f3rio do Estado de S\u00e3o Paulo. Para consulta acesse o endere\u00e7o www3.fazenda.sp.gov.br. O reembolso refere-se \u00e0 restitui\u00e7\u00e3o proporcional do IPVA (Imposto sobre a Propriedade de Ve\u00edculos Automotores) e beneficia os motoristas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,370,353],"tags":[],"class_list":{"0":"post-26191","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-inscricao","9":"category-oportunidades","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/ipva-sp-restituicao.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/26191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=26191"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/26191\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/26192"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=26191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=26191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=26191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}