{"id":25709,"date":"2010-04-07T16:18:43","date_gmt":"2010-04-07T20:18:43","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=25709"},"modified":"2010-04-07T16:18:43","modified_gmt":"2010-04-07T20:18:43","slug":"trainee-ca-inscricao-ate-15-de-abril","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/trainee-ca-inscricao-ate-15-de-abril\/25709","title":{"rendered":"Trainee C&#038;A &#8211; inscri\u00e7\u00e3o at\u00e9 15 de abril"},"content":{"rendered":"<p><strong><em>Trainee C&amp;A<\/em><\/strong> \u00a0&#8211; a C&amp;A recebe at\u00e9 o dia 15 de abril as inscri\u00e7\u00f5es para a 56\u00aa edi\u00e7\u00e3o do seu Programa de Trainees. Trata-se de um dos mais tradicionais programas do mercado e tem como objetivo selecionar novos talentos para atuar nas \u00e1reas de Neg\u00f3cios do Varejo. Os interessados devem se inscrever pelo site da C&amp;A: <a href=\"http:\/\/www.cea.com.br\" target=\"_blank\"><strong><em>www.cea.com.br<\/em><\/strong><\/a>. Faltam somente oito dias para o encerramento das inscri\u00e7\u00f5es.<\/p>\n<p>Podem se inscrever candidatos graduados no per\u00edodo de julho de 2007 a julho de 2010 nos seguintes cursos: Administra\u00e7\u00e3o de Empresas, Administra\u00e7\u00e3o Mercadol\u00f3gica, Com\u00e9rcio Exterior, Arquitetura, Comunica\u00e7\u00e3o, Economia, Engenharia, Marketing, Rela\u00e7\u00f5es Internacionais e Moda.<\/p>\n<p>Alguns dos requisitos exigidos dos candidatos s\u00e3o: ingl\u00eas avan\u00e7ado ou fluente, vis\u00e3o comercial, perfil desafiador e empreendedor, disponibilidade para viagens e mudan\u00e7as de cidade ou estado, gostar de assumir riscos e habilidade para se relacionar.<\/p>\n<p>A sele\u00e7\u00e3o \u00e9 composta por v\u00e1rias etapas. Durante o processo seletivo, o candidato faz prova de ingl\u00eas e de racioc\u00ednio l\u00f3gico, passa por testes comportamentais, din\u00e2micas de grupo e, por fim, \u00e9 entrevistado por diretores da empresa.<\/p>\n<p>Benef\u00edcios<\/p>\n<p>O Programa de Trainees da C&amp;A \u00e9 um dos mais antigos do g\u00eanero no Brasil, tendo sido lan\u00e7ado na d\u00e9cada de 70, quando a empresa chegou ao Brasil. O \u00edndice de efetiva\u00e7\u00e3o em cargo de ger\u00eancia ao t\u00e9rmino do programa \u00e9 de aproximadamente 80% dos participantes. Atualmente, 55% dos diretores da C&amp;A s\u00e3o oriundos do Programa de Trainees.<\/p>\n<p>Aos trainees s\u00e3o oferecidos v\u00e1rios benef\u00edcios. Al\u00e9m do sal\u00e1rio, compat\u00edvel com o oferecido no mercado, a empresa oferece planos de sa\u00fade e odontol\u00f3gico, refei\u00e7\u00e3o, estacionamento, cart\u00e3o de desconto em compras nas lojas C&amp;A, entre outros. A empresa ainda se responsabiliza pelas despesas dos trainees que permanecer\u00e3o fora dos seus Estados durante o programa, como locomo\u00e7\u00e3o e passagens a\u00e9reas para os participantes viajarem para suas cidades de origem.<\/p>\n<p>O Programa<\/p>\n<p>O treinamento tem dura\u00e7\u00e3o de 15 meses e \u00e9 composto por tr\u00eas m\u00f3dulos: opera\u00e7\u00e3o de loja; compras; e especializa\u00e7\u00e3o em gest\u00e3o de lojas. Depois deste processo, o trainee assume o cargo de gerente e passar\u00e1 a ser respons\u00e1vel por uma unidade de neg\u00f3cio da C&amp;A.<\/p>\n<p>A contrata\u00e7\u00e3o dos aprovados no programa ser\u00e1 realizada em agosto de 2010.<\/p>\n<p>Sobre a C&amp;A<\/p>\n<p>L\u00edder do mercado varejista de moda brasileiro e h\u00e1 34 anos no pa\u00eds, a C&amp;A foi criada em 1841 pelos irm\u00e3os Clemens e August, e a uni\u00e3o de suas iniciais deu origem ao nome da empresa. A primeira loja foi inaugurada na Holanda, em 1861. A rede tornou-se uma das primeiras no mundo a oferecer roupas prontas aos consumidores. Em 1911, com o crescimento do neg\u00f3cio, a empresa instalou-se na Alemanha, e, posteriormente, em outros pa\u00edses da Europa.<\/p>\n<p>A C&amp;A possui, atualmente, mais de 1,5 mil lojas na Europa, Am\u00e9rica Latina e \u00c1sia. No Brasil, a primeira loja foi inaugurada em 1976. Atualmente, a C&amp;A est\u00e1 presente em mais de 60 cidades brasileiras, com mais de 170 lojas.<\/p>\n<p>A empresa sempre orientou sua conduta baseada em princ\u00edpios \u00e9ticos e morais que, desde sua origem, privilegiaram a responsabilidade social e a transpar\u00eancia junto a todos os seus p\u00fablicos: funcion\u00e1rios, fornecedores, clientes e as comunidades com as quais interage.<\/p>\n<p>Para tanto, a empresa fundou, em 1991, uma organiza\u00e7\u00e3o sem fins lucrativos, o Instituto C&amp;A, que tem por objetivo promover e qualificar o processo de educa\u00e7\u00e3o de crian\u00e7as e adolescentes no Brasil.<\/p>\n<p>Sobre o Instituto C&amp;A<\/p>\n<p>O Instituto C&amp;A, criado em 1991, concebe, planeja, gerencia e executa a pol\u00edtica de investimento social da empresa. Sua miss\u00e3o \u00e9 promover a educa\u00e7\u00e3o de crian\u00e7as e adolescentes das comunidades onde a C&amp;A est\u00e1 presente, por meio de apoio t\u00e9cnico e financeiro, de alian\u00e7as e do fortalecimento de organiza\u00e7\u00f5es sociais. Atualmente, o trabalho do Instituto abrange organiza\u00e7\u00f5es sociais que atuam em 84 cidades.<\/p>\n<p>O Instituto C&amp;A organiza suas atividades e programas em torno de tr\u00eas \u00e1reas: Educa\u00e7\u00e3o, Arte e Cultura, Desenvolvimento Institucional e Comunit\u00e1rio; Mobiliza\u00e7\u00e3o Social. Os programas desenvolvidos s\u00e3o: Prazer em Ler, Educa\u00e7\u00e3o Integral, Educa\u00e7\u00e3o Infantil, Redes e Alian\u00e7as, Desenvolvimento Institucional e Voluntariado Empresarial.<\/p>\n<p>Os objetivos estrat\u00e9gicos que servem de base para a cria\u00e7\u00e3o e desenvolvimento de seus programas e a\u00e7\u00f5es s\u00e3o: desenvolver compet\u00eancias organizacionais a fim de manter sua sustentabilidade; aumentar a efici\u00eancia e efic\u00e1cia de seus processos de gest\u00e3o; produzir conhecimento em educa\u00e7\u00e3o e gest\u00e3o institucional; desenvolver as organiza\u00e7\u00f5es sociais e suas lideran\u00e7as; contribuir para a realiza\u00e7\u00e3o das pol\u00edticas p\u00fablicas em educa\u00e7\u00e3o; aumentar a efici\u00eancia e efic\u00e1cia na aplica\u00e7\u00e3o dos recursos; assegurar oportunidades de participa\u00e7\u00e3o social qualificada aos funcion\u00e1rios da C&amp;A; e fortalecer as organiza\u00e7\u00f5es sociais na sua rela\u00e7\u00e3o com a escola e a fam\u00edlia. Desde sua funda\u00e7\u00e3o, o Instituto C&amp;A j\u00e1 investiu mais de US$ 64 milh\u00f5es em 1.420 projetos sociais em todo o Brasil, envolvendo cerca de 1 milh\u00e3o de pessoas, entre crian\u00e7as, adolescentes, educadores e agentes de investimento social.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trainee C&amp;A \u00a0&#8211; a C&amp;A recebe at\u00e9 o dia 15 de abril as inscri\u00e7\u00f5es para a 56\u00aa edi\u00e7\u00e3o do seu Programa de Trainees. Trata-se de um dos mais tradicionais programas do mercado e tem como objetivo selecionar novos talentos para atuar nas \u00e1reas de Neg\u00f3cios do Varejo. Os interessados devem se inscrever pelo site da [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,370,353],"tags":[],"class_list":["post-25709","post","type-post","status-publish","format-standard","category-brasil","category-inscricao","category-oportunidades","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/25709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=25709"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/25709\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=25709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=25709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=25709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}