{"id":25691,"date":"2010-04-07T11:26:06","date_gmt":"2010-04-07T15:26:06","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=25691"},"modified":"2010-04-07T11:29:56","modified_gmt":"2010-04-07T15:29:56","slug":"soletrando-do-caldeirao-do-huck-%e2%80%93-inscricoes-terminam-dia-1704","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/soletrando-do-caldeirao-do-huck-%e2%80%93-inscricoes-terminam-dia-1704\/25691","title":{"rendered":"Soletrando do Caldeir\u00e3o do Huck \u2013 inscri\u00e7\u00f5es terminam dia 17\/04"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-25694\" title=\"soletrando inscricao\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/soletrando-inscricao.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/soletrando-inscricao.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/soletrando-inscricao-250x160.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/soletrando-inscricao-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>A final do <strong><em>Soletrando<\/em><\/strong> 2010 ser\u00e1 s\u00e1bado, dia 10 de abril. Os finalistas s\u00e3o Daniel Coutinho, de Minas Gerais, Dener da Silva, de S\u00e3o Paulo, e Tainara Oliveira, do Piau\u00ed e a Rede <strong><em>Globo<\/em><\/strong> disponibilizou uma enqu\u00eate para saber quem voc\u00ea acha que levar\u00e1 o trof\u00e9u Rachel de Queiroz, al\u00e9m de uma bolsa de estudos no valor de R$100.000? (<a href=\"http:\/\/tvglobo.caldeiraodohuck.globo.com\/soletrando2010-home\/2010\/04\/03\/quem-sera-o-campeao-do-soletrando-2010\/\" target=\"_blank\">Responda<\/a>). Em 2011 a Globo Comunica\u00e7\u00e3o e Participa\u00e7\u00f5es S.A. (\u201cTV Globo\u201d) produzir\u00e1 um quadro intitulado \u201cSoletrando\u201d (\u201cQuadro\u201d), que integrar\u00e1 o programa \u201c<strong><em>Caldeir\u00e3o do Huck<\/em><\/strong>\u201d (\u201cPrograma\u201d). O Quadro \u00e9 uma competi\u00e7\u00e3o de soletra\u00e7\u00e3o entre estudantes do ensino fundamental, sendo que poder\u00e1 participar do Quadro qualquer escola p\u00fablica do Brasil. As inscri\u00e7\u00f5es das escolas dever\u00e3o ser realizadas at\u00e9 o dia 17 de abril de 2010 atrav\u00e9s do site do Programa (<a href=\"http:\/\/www.globo.com\/caldeirao\" target=\"_blank\">www.globo.com\/caldeirao<\/a>), pelo diretor de cada escola interessada em participar do Quadro. A inscri\u00e7\u00e3o da escola no Quadro dever\u00e1 ser confirmada pela pr\u00f3pria atrav\u00e9s de acesso ao site do Programa.<\/p>\n<p>O diretor da escola interessada dever\u00e1 consultar o site do Programa de forma a efetuar e confirmar sua inscri\u00e7\u00e3o, verificar as datas do calend\u00e1rio do Quadro, bem como o manual elaborado pela TV Globo sugerindo forma de organiza\u00e7\u00e3o para a primeira fase do campeonato.<\/p>\n<p>Para a inscri\u00e7\u00e3o no Quadro o estudante dever\u00e1 preencher obrigatoriamente todos os seguintes requisitos:<\/p>\n<p>(i) estar cursando entre a Quinta s\u00e9rie ou Sexto ano e a S\u00e9tima s\u00e9rie ou Oitavo ano do ensino fundamental, sendo que o ano letivo considerado \u00e9 o estabelecido pelo MEC, isto \u00e9, com o t\u00e9rmino em dezembro;<\/p>\n<p>(ii) O aluno indicado pela escola deve obrigatoriamente estar cursando no m\u00e1ximo o \u00faltimo ano do ensino fundamental no ano de 2011;<\/p>\n<p>(iii) ter como idade m\u00ednima 11 (onze) anos completos at\u00e9 o dia 31 de agosto de 2010 e idade m\u00e1xima 16 anos, sendo certo que somente poder\u00e1 completar 17 (dezessete) anos ap\u00f3s o dia 01 de junho de 2011; e<\/p>\n<p>(iv) o estudante dever\u00e1 ter nascido entre 01 de junho de 1994 e 31 de agosto de 1999.<\/p>\n<p>Soletrando do Caldeir\u00e3o do Huck<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A final do Soletrando 2010 ser\u00e1 s\u00e1bado, dia 10 de abril. Os finalistas s\u00e3o Daniel Coutinho, de Minas Gerais, Dener da Silva, de S\u00e3o Paulo, e Tainara Oliveira, do Piau\u00ed e a Rede Globo disponibilizou uma enqu\u00eate para saber quem voc\u00ea acha que levar\u00e1 o trof\u00e9u Rachel de Queiroz, al\u00e9m de uma bolsa de estudos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":25694,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,370,353,375,343],"tags":[],"class_list":["post-25691","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","category-inscricao","category-oportunidades","category-rede-globo","category-televisao","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/soletrando-inscricao.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/25691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=25691"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/25691\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/25694"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=25691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=25691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=25691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}