{"id":25130,"date":"2010-03-27T19:10:42","date_gmt":"2010-03-27T23:10:42","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=25130"},"modified":"2010-03-27T22:17:56","modified_gmt":"2010-03-28T02:17:56","slug":"mega-sena-1165-%e2%80%93-resultado-da-loteria-caixa-deste-sabado-2703","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/mega-sena-1165-%e2%80%93-resultado-da-loteria-caixa-deste-sabado-2703\/25130","title":{"rendered":"Mega Sena 1165 \u2013 resultado da Loteria Caixa deste s\u00e1bado (27\/03)"},"content":{"rendered":"<p><strong><em><span style=\"font-style: normal; font-weight: normal;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-18079\" title=\"resultado da mega sena\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-mega-sena.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-mega-sena.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-mega-sena-250x160.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-mega-sena-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/span>Mega Sena 1165<\/em><\/strong>\u00a0\u2013 o\u00a0<strong><em>resultado<\/em><\/strong>\u00a0do sorteio da <strong><em>Loteria Caixa<\/em><\/strong>\u00a0Mega Sena 1165, neste s\u00e1bado (<strong><em>27\/03<\/em><\/strong>), foi divulgado pelo caminh\u00e3o da sorte em Uni\u00e3o da Vit\u00f3ria\/PR. O pr\u00eamio de hoje estava acumulado e estimado em\u00a025 milh\u00f5es de reais. Mega Sena \u00e9 o jogo que paga milh\u00f5es para o acertador dos 6 n\u00fameros sorteados. Mas quem acerta 4 ou 5 n\u00fameros tamb\u00e9m ganha. Para realizar o sonho de ser o pr\u00f3ximo milion\u00e1rio, voc\u00ea deve marcar de 6 e 15 n\u00fameros, entre os 60 dispon\u00edveis no volante. Voc\u00ea pode deixar que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou concorrer com o mesmo jogo por 2, 4 ou 8 concursos consecutivos (Teimosinha).<\/p>\n<p>Confira o resultado da Loteria Caixa Mega Sena 1165 deste s\u00e1bado (27\/03) \u2013 <strong>20 \u00a040\u00a0 42\u00a0 52 \u00a054 \u00a060<\/strong>. O pr\u00eamio principal acumulou e agora est\u00e1 estimado em 30 milh\u00f5es de reais (fonte UOL Folha).<\/p>\n<p>Os sorteios s\u00e3o realizados duas vezes por semana, \u00e0s quartas e aos s\u00e1bados. A aposta m\u00ednima, de 6 n\u00fameros, custa R$ 2,00. Quanto mais n\u00fameros marcar, maior o pre\u00e7o da aposta e maiores as chances de faturar o pr\u00eamio mais cobi\u00e7ado do pa\u00eds. O pr\u00eamio bruto corresponde a 46% da arrecada\u00e7\u00e3o, j\u00e1 computado o adicional destinado ao Minist\u00e9rio do Esporte. Dessa porcentagem: 35% s\u00e3o distribu\u00eddos entre os acertadores dos 6 n\u00fameros sorteados (Sena); 19% entre os acertadores de 5 n\u00fameros (Quina); 19% entre os acertadores de 4 n\u00fameros (Quadra); 22% ficam acumulados e distribu\u00eddos aos acertadores dos 6 n\u00fameros nos concursos de final 0 ou 5. 5% ficam acumulado para a primeira faixa \u2013 sena \u2013 do \u00faltimo concurso do ano de final zero ou 5 cinco. N\u00e3o havendo acertador em qualquer faixa, o valor acumula para o concurso seguinte, na respectiva faixa de premia\u00e7\u00e3o. N\u00e3o deixe de conferir o seu bilhete de aposta. Os pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mega Sena 1165\u00a0\u2013 o\u00a0resultado\u00a0do sorteio da Loteria Caixa\u00a0Mega Sena 1165, neste s\u00e1bado (27\/03), foi divulgado pelo caminh\u00e3o da sorte em Uni\u00e3o da Vit\u00f3ria\/PR. O pr\u00eamio de hoje estava acumulado e estimado em\u00a025 milh\u00f5es de reais. Mega Sena \u00e9 o jogo que paga milh\u00f5es para o acertador dos 6 n\u00fameros sorteados. Mas quem acerta 4 ou [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18079,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,335,355],"tags":[],"class_list":{"0":"post-25130","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-loteria","9":"category-mega-sena","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-mega-sena.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/25130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=25130"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/25130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/18079"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=25130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=25130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=25130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}