{"id":250435,"date":"2024-12-17T20:14:09","date_gmt":"2024-12-17T23:14:09","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-1002-sorteado-terca-feira-17-12-2024\/250435"},"modified":"2024-12-17T22:29:48","modified_gmt":"2024-12-18T01:29:48","slug":"dia-de-sorte-resultado-do-concurso-1002-sorteado-terca-feira-17-12-2024","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-1002-sorteado-terca-feira-17-12-2024\/250435","title":{"rendered":"Dia de Sorte: Resultado do concurso 1002 sorteado  Ter\u00e7a-feira 17\/12\/2024"},"content":{"rendered":"<p>Resultado do Dia de Sorte, concurso 1002, realizado na  Ter\u00e7a-feira, dia 17\/12\/2024 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo.  O Dia de Sorte 1002 teve 1 acertador dos  n\u00fameros. O ganhador \u00e9 da cidade de Castanhal (PA) e receber\u00e1 um pr\u00eamio de R$ 156.191,93. A previs\u00e3o do pr\u00eamio para o pr\u00f3ximo sorteio, Dia de Sorte 1003,  \u00e9 de R$ 150.000,00.<\/p>\n<p>Veja tamb\u00e9m: <\/p>\n<h2>N\u00fameros Sorteados Dia de Sorte 1002<\/h2>\n<table style=\"margin-bottom: 10px;\">\n<tr>\n<td><span class=\"numberCircleDiaDeSorte\">04<\/span><\/td>\n<td><span class=\"numberCircleDiaDeSorte\">05<\/span><\/td>\n<td><span class=\"numberCircleDiaDeSorte\">10<\/span><\/td>\n<td><span class=\"numberCircleDiaDeSorte\">12<\/span><\/td>\n<td><span class=\"numberCircleDiaDeSorte\">17<\/span><\/td>\n<td><span class=\"numberCircleDiaDeSorte\">24<\/span><\/td>\n<td><span class=\"numberCircleDiaDeSorte\">29<\/span><\/td>\n<\/tr>\n<\/table>\n<div style =\"font-size: 1.3em;margin-bottom:20px;\">M\u00eas da Sorte: Agosto<\/div>\n<h2>Premia\u00e7\u00e3o Dia de Sorte 1002<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad.<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td>  7  <\/td>\n<td>1<\/td>\n<td>156.191,93<\/td>\n<\/tr>\n<tr>\n<td>  6 <\/td>\n<td>103<\/td>\n<td>928,42<\/td>\n<\/tr>\n<tr>\n<td>  5 <\/td>\n<td>2.103<\/td>\n<td>25,00<\/td>\n<\/tr>\n<tr>\n<td>  4 <\/td>\n<td>23.781<\/td>\n<td>5,00<\/td>\n<\/tr>\n<tr>\n<td>  M\u00eas da Sorte <\/td>\n<td>43.779<\/td>\n<td>2,50<\/td>\n<\/tr>\n<\/table>\n<h2>Cidades Ganhadoras da Dia de Sorte 1002<\/h2>\n<p>As apostas vencedoras foram realizadas nas seguintes cidades:<\/p>\n<table>\n<tr>\n<th>Cidade<\/th>\n<th>UF<\/th>\n<th>Ganhadores<\/th>\n<\/tr>\n<tr>\n<td>Castanhal<\/td>\n<td>PA<\/td>\n<td>1<\/td>\n<\/tr>\n<\/table>\n<h2>Total de Apostas realizadas<\/h2>\n<p>No concurso 1002 do Dia de Sorte foi realizado um total de 547.784 apostas.<\/p>\n<h2>Pr\u00f3ximo Sorteio da Dia de Sorte <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Quinta-feira 19\/12\/2024, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 150.000,00.<\/p>\n<h3>\u00daltimos Resultados do Dia de Sorte<\/h3>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-1002-sorteado-terca-feira-17-12-2024\/250435\">Dia de Sorte 1002<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-1001-sorteado-sabado-14-12-2024\/250341\">Dia de Sorte 1001<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-1000-sorteado-quinta-feira-12-12-2024\/250292\">Dia de Sorte 1000<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-999-sorteado-terca-feira-10-12-2024\/250209\">Dia de Sorte 999<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-998-sorteado-sabado-07-12-2024\/250124\">Dia de Sorte 998<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Resumo do sorteio do Dia de Sorte 1002<\/h2>\n<ul>\n<li>Dos n\u00fameros sorteados neste concurso da Dia de Sorte o que mais saiu nos \u00faltimos 12 meses foi o 10, sorteado 45 vezes.<\/li>\n<li>O que menos saiu foi o n\u00famero 12, sorteado apenas 30 vezes.<\/li>\n<li>Das 31 dezenas, a que est\u00e1 h\u00e1 mais tempo sem ser sorteada \u00e9 a 9 que n\u00e3o sai tem 63  dias.<\/li>\n<li>O maior valor pago neste per\u00edodo foi R$ 4.872.571,96 no concurso 853, sorteado em 23\/12\/2023.<\/li>\n<li>Nos \u00faltimos 12 meses foram realizados 152 sorteios e premiadas 49 pessoas que acertaram os 7 n\u00fameros da Dia de Sorte.<\/li>\n<li>Neste per\u00edodo o Dia de Sorte n\u00e3o teve acertadores em 113 oportunidades.<\/li>\n<\/ul>\n<\/ul>\n<h3>Hist\u00f3rico dos n\u00fameros sorteados neste concurso da Dia de Sorte<\/h3>\n<p>Nesta tabela voc\u00ea ir\u00e1 encontrar as seguintes informa\u00e7\u00f5es relativas aos sorteios da Dia de Sorte dos \u00faltimos 12 meses:<br \/>A quantidade de vezes que o n\u00famero foi sorteado na Dia de Sorte,<br \/>A quantidade de sorteios que este n\u00famero saiu e o concurso teve ganhador,<br \/>A data do \u00faltimo sorteio na Dia de Sorte desta dezena.<\/p>\n<table>\n<tr>\n<th>Dezena<\/th>\n<th>Total<\/th>\n<th>Premiada<\/th>\n<th>Data<\/th>\n<\/tr>\n<tr>\n<td>04<\/td>\n<td>38<\/td>\n<td>12<\/td>\n<td>12\/12\/2024<\/td>\n<\/tr>\n<tr>\n<td>05<\/td>\n<td>39<\/td>\n<td>11<\/td>\n<td>03\/12\/2024<\/td>\n<\/tr>\n<tr>\n<td>10<\/td>\n<td>45<\/td>\n<td>11<\/td>\n<td>14\/12\/2024<\/td>\n<\/tr>\n<tr>\n<td>12<\/td>\n<td>30<\/td>\n<td>5<\/td>\n<td>03\/12\/2024<\/td>\n<\/tr>\n<tr>\n<td>17<\/td>\n<td>31<\/td>\n<td>10<\/td>\n<td>05\/12\/2024<\/td>\n<\/tr>\n<tr>\n<td>24<\/td>\n<td>37<\/td>\n<td>6<\/td>\n<td>23\/11\/2024<\/td>\n<\/tr>\n<tr>\n<td>29<\/td>\n<td>33<\/td>\n<td>10<\/td>\n<td>05\/12\/2024<\/td>\n<\/tr>\n<\/table>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dia de Sorte 1002 &#8211; Resultado, rateio e ganhadores do Dia de Sorte 1002 sorteado em 17\/12\/2024.<\/p>\n","protected":false},"author":5,"featured_media":196327,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[478,335],"tags":[],"class_list":{"0":"post-250435","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dia-de-sorte","8":"category-loteria","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/dia-de-sorte-resultado.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/250435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=250435"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/250435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196327"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=250435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=250435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=250435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}