{"id":24952,"date":"2010-03-23T23:56:01","date_gmt":"2010-03-24T03:56:01","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=24952"},"modified":"2018-08-13T10:49:29","modified_gmt":"2018-08-13T13:49:29","slug":"anamara-foi-eliminada-ao-vivo-do-bbb-10-com-57-da-votacao","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/anamara-foi-eliminada-ao-vivo-do-bbb-10-com-57-da-votacao\/24952","title":{"rendered":"Anamara foi eliminada ao vivo do BBB 10 com 57% da vota\u00e7\u00e3o"},"content":{"rendered":"<p><strong><em><span style=\"font-style: normal; font-weight: normal;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-22134\" title=\"BBB 10 Rede Globo\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/BBB-10-Rede-Globo.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/BBB-10-Rede-Globo.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/BBB-10-Rede-Globo-250x161.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/BBB-10-Rede-Globo-150x97.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/span>BBB 10<\/em><\/strong> &#8211; contrariando enquetes de grandes portais como <strong><em>UOL<\/em><\/strong> e IG, Anamara foi eliminada <strong><em>ao vivo<\/em><\/strong> do BBB 10 com 57% de 92.230 milh\u00f5es de voto, segundo informou o apresentador Pedro Bial da Rede <strong><em>Globo<\/em><\/strong>. No portal UOL, em uma amostra de 1.437.730 votos, 59,78% dos internautas que votaram para elimina\u00e7\u00e3o de Lia ou Maroca, em enquete BBB 10, sem valor de amostragem cient\u00edfica e sem interferir no andamento do programa BBB 10 da Globo, demonstraram que gostariam que a Eliane sa\u00edsse, contra 40,22% que preferiam a sa\u00edda de Maroca. No portal IG, tamb\u00e9m em uma amostragem de <strong><span style=\"font-weight: normal;\">376.659 votos, em enquete que n\u00e3o interferiu no programa, 60% preferiam que Lia fosse eliminada.<\/span><\/strong><br \/>\nAp\u00f3s a apresenta\u00e7\u00e3o do resultado da vota\u00e7\u00e3o e a sa\u00edda de Maroca, Fernanda quis abandonar o BBB 10 enquanto o programa ainda estava ao vivo. Fernanda disse para Dicesar que n\u00e3o ganhou nenhum pr\u00eamio e que ser\u00e1 muito dif\u00edcil conviver com Lia, Dourado e Cadu, al\u00e9m de saber que s\u00f3 uma lideran\u00e7a salva ela ou Dicesar do pr\u00f3ximo pared\u00e3o. Dicesar pediu para ela ficar porque o jogo muda a qualquer momento e ela pode ganhar um pr\u00eamio na pr\u00f3xima disputa, alem de que ele precisa muito dela para continuar e ag\u00fcentar a \u00faltima semana do BBB 10.<\/p>\n<p>No final do programa ao vivo, aconteceu uma discuss\u00e3o e troca de insultos entre Dicesar e Dourado, e uma longa conversa entre Dicesar e a dentista. Fernanda concordou em ficar no BBB 10 mas pediu para Dicesar evitar atritos com o lutador. Dicesar disse que vai tentar se controlar, mas deseja enfrentar Dourado no pr\u00f3ximo pared\u00e3o, pois confia na justi\u00e7a e na sua torcida.<\/p>\n<p>Em outro canto da casa, Dourado falou para Lia e Cadu que neste pared\u00e3o ele sentiu o mesmo nervosismo que antecede uma luta, e que est\u00e1 muito feliz por Lia ter ficado. Ele complementou que considerou falta de respeito algumas atitudes de Maroca durante o dia, demonstrando confian\u00e7a antecipada na vit\u00f3ria.<\/p>\n<p>Os participantes do BBB 10 que ainda est\u00e3o na casa n\u00e3o conseguiram dormir cedo pois acham que o Big Fone vai tocar a qualquer momento, e que a prova do l\u00edder poder\u00e1 ser nesta quarta-feira, uma vez que n\u00e3o h\u00e1 clima de festa na casa.<\/p>\n<p>BBB 10 \u2013 12\u00aa elimina\u00e7\u00e3o ao vivo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BBB 10 &#8211; contrariando enquetes de grandes portais como UOL e IG, Anamara foi eliminada ao vivo do BBB 10 com 57% de 92.230 milh\u00f5es de voto, segundo informou o apresentador Pedro Bial da Rede Globo. No portal UOL, em uma amostra de 1.437.730 votos, 59,78% dos internautas que votaram para elimina\u00e7\u00e3o de Lia ou [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":22134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[520,22,379,375,343],"tags":[],"class_list":{"0":"post-24952","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-big-brother-brasil","8":"category-brasil","9":"category-novelas","10":"category-rede-globo","11":"category-televisao","12":"entry","13":"gs-1","14":"gs-odd","15":"gs-even","16":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/BBB-10-Rede-Globo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/24952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=24952"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/24952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/22134"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=24952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=24952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=24952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}