{"id":24919,"date":"2010-03-22T23:54:31","date_gmt":"2010-03-23T03:54:31","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=24919"},"modified":"2010-03-22T23:54:31","modified_gmt":"2010-03-23T03:54:31","slug":"cultura-sp-inscricoes-para-artistas-captarem-recursos","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/cultura-sp-inscricoes-para-artistas-captarem-recursos\/24919","title":{"rendered":"Cultura SP &#8211; inscri\u00e7\u00f5es para artistas captarem recursos"},"content":{"rendered":"<p>A Secretaria da Cultura reabre nesta segunda-feira, 22, as inscri\u00e7\u00f5es para o cadastramento de projetos para a participa\u00e7\u00e3o no <strong><em>Programa de A\u00e7\u00e3o Cultural<\/em><\/strong> &#8211; ProAC-ICMS, que oferece a artistas e produtores culturais a possibilidade de captar recursos junto a empresas que recebem isen\u00e7\u00e3o do imposto.<\/p>\n<p>Em 2010, R$ 60 milh\u00f5es foram liberados pela Secretaria da Fazenda, R$ 10 milh\u00f5es a mais do que nos dois \u00faltimos anos. O dinheiro \u00e9 voltado para apoio a projetos em 21 diferentes segmentos culturais em todo Estado de S\u00e3o Paulo.<\/p>\n<p>Clique <a href=\"http:\/\/www.cultura.sp.gov.br\/portal\/site\/SEC\/menuitem.555627669a24dd2547378d27ca60c1a0\/?vgnextoid=6a33b23eb2a6b110VgnVCM100000ac061c0aRCRD\" target=\"_blank\">aqui<\/a> para mais informa\u00e7\u00f5es.<\/p>\n<p>O ProAC &#8211; Programa de A\u00e7\u00e3o Cultural &#8211; foi institu\u00eddo pela Lei 12.268, de 20 de fevereiro de 2006, e regulamentado pelos Decretos Nros.\u00a0 54.275, de 27 de abril de 2009; e 51.944 de 29 de junho de 2007.<br \/>\nTrata-se de um Programa do Governo do Estado de S\u00e3o Paulo, cujo objetivo \u00e9 disponibilizar recursos financeiros p\u00fablicos para atender demandas da sociedade civil na produ\u00e7\u00e3o art\u00edstico cultural.<\/p>\n<p>Este novo mecanismo de financiamento do segmento cultural busca ampliar e diversificar a produ\u00e7\u00e3o art\u00edstico-cultural em toda sua potencialidade, criar novos espa\u00e7os culturais, preservar o patrim\u00f4nio cultural material e imaterial e fortalecer as formas de circula\u00e7\u00e3o de bens culturais no Estado de S\u00e3o Paulo, de forma participativa.<br \/>\nTrata-se de um aperfei\u00e7oamento na rela\u00e7\u00e3o do Estado com as diversas \u00e1reas de produ\u00e7\u00e3o de bens art\u00edsticos e culturais, no que diz respeito \u00e0 aloca\u00e7\u00e3o dos recurso p\u00fablicos. Neste processo, a Secretaria da Cultura disponibiliza parte de seu or\u00e7amento pr\u00f3prio para implementar projetos que muitas vezes n\u00e3o teriam participa\u00e7\u00e3o no mercado cultural, mas que revelam-se de grande significado para a sociedade.<\/p>\n<p>Da mesma forma, utilizando-se de recursos p\u00fablicos, os empres\u00e1rios escolhem dentre os projetos previamente autorizados, quais aqueles em que desejam aportar recursos provenientes de impostos devidos por suas empresas. \u00c9 um mecanismo pelo qual o Estado delega compet\u00eancia para a sociedade civil escolher onde investir parte do imposto gerado.<\/p>\n<p>Em ambos os mecanismos cria-se no Estado de S\u00e3o Paulo, um novo perfil do universo cultural, que certamente resultar\u00e1 n\u00e3o s\u00f3 no aumento da produ\u00e7\u00e3o, como tamb\u00e9m criar\u00e1 oportunidades inovadoras, permitindo ainda uma melhor distribui\u00e7\u00e3o de bens e servi\u00e7os culturais, assim como a gera\u00e7\u00e3o de renda.<br \/>\nS\u00e3o mecanismos que o Estado disponibiliza para que a sociedade civil, de forma democr\u00e1tica administre n\u00e3o s\u00f3 a universaliza\u00e7\u00e3o do acesso, mas o foco da produ\u00e7\u00e3o.<\/p>\n<p>Da Secretaria da Cultura<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria da Cultura reabre nesta segunda-feira, 22, as inscri\u00e7\u00f5es para o cadastramento de projetos para a participa\u00e7\u00e3o no Programa de A\u00e7\u00e3o Cultural &#8211; ProAC-ICMS, que oferece a artistas e produtores culturais a possibilidade de captar recursos junto a empresas que recebem isen\u00e7\u00e3o do imposto. Em 2010, R$ 60 milh\u00f5es foram liberados pela Secretaria da [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,370,353],"tags":[],"class_list":["post-24919","post","type-post","status-publish","format-standard","category-brasil","category-inscricao","category-oportunidades","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/24919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=24919"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/24919\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=24919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=24919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=24919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}