{"id":248900,"date":"2024-10-28T20:17:13","date_gmt":"2024-10-28T23:17:13","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/lotomania-resultado-do-concurso-2692-sorteado-segunda-feira-28-10-2024\/248900"},"modified":"2024-10-29T15:36:11","modified_gmt":"2024-10-29T18:36:11","slug":"lotomania-resultado-do-concurso-2692-sorteado-segunda-feira-28-10-2024","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/lotomania-resultado-do-concurso-2692-sorteado-segunda-feira-28-10-2024\/248900","title":{"rendered":"Lotomania: Resultado do concurso 2692 sorteado  Segunda-feira 28\/10\/2024"},"content":{"rendered":"<p>Resultado da Lotomania, concurso 2692, realizado na  Segunda-feira, dia 28\/10\/2024 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo.  A Lotomania 2692 n\u00e3o teve acertador do pr\u00eamio principal e a previs\u00e3o do pr\u00eamio para o pr\u00f3ximo sorteio, Lotomania 2693, \u00e9 de R$ 4.700.000,00. Com este resultado a Lotomania  esta acumulada ha  6 sorteios<\/p>\n<p>Veja tamb\u00e9m: <a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2020\/todos-os-resultados-da-lotomania\/199405\"> Todos os resultados da Lotomania<\/a><\/p>\n<h2>N\u00fameros Sorteados Lotomania 2692<\/h2>\n<table>\n<tr>\n<td><span class=\"numberCircleLotoMania\">11<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">12<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">18<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">19<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">21<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleLotoMania\">29<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">32<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">38<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">49<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">52<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleLotoMania\">56<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">58<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">61<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">62<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">65<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleLotoMania\">66<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">67<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">79<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">84<\/span><\/td>\n<td><span class=\"numberCircleLotoMania\">86<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Premia\u00e7\u00e3o Lotomania 2692<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad.<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td>20<\/td>\n<td>0<\/td>\n<td>0,00<\/td>\n<\/tr>\n<tr>\n<td>19<\/td>\n<td>2<\/td>\n<td>112.263,34<\/td>\n<\/tr>\n<tr>\n<td>18<\/td>\n<td>103<\/td>\n<td>1.946,31<\/td>\n<\/tr>\n<tr>\n<td>17<\/td>\n<td>757<\/td>\n<td>185,37<\/td>\n<\/tr>\n<tr>\n<td>16<\/td>\n<td>4.063<\/td>\n<td>34,53<\/td>\n<\/tr>\n<tr>\n<td>15<\/td>\n<td> 16.865<\/td>\n<td>8,32<\/td>\n<\/tr>\n<tr>\n<td>0<\/td>\n<td>0<\/td>\n<td>0,00<\/td>\n<\/tr>\n<\/table>\n<h2>Total de Apostas realizadas<\/h2>\n<p>No concurso 2692 da Lotomania foi realizado um total de 1.541.486 apostas.<\/p>\n<h2>Pr\u00f3ximo Sorteio da Lotomania <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Quarta-feira 30\/10\/2024, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 4.700.000,00.<\/p>\n<h3>\u00daltimos Resultados da Lotomania<\/h3>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/lotomania-resultado-do-concurso-2692-sorteado-segunda-feira-28-10-2024\/248900\">Lotomania 2692<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/lotomania-resultado-do-concurso-2691-sorteado-sexta-feira-25-10-2024\/248821\">Lotomania 2691<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/lotomania-resultado-do-concurso-2690-sorteado-quarta-feira-23-10-2024\/248750\">Lotomania 2690<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/lotomania-resultado-do-concurso-2689-sorteado-segunda-feira-21-10-2024\/248686\">Lotomania 2689<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/lotomania-resultado-do-concurso-2688-sorteado-sexta-feira-18-10-2024\/248591\">Lotomania 2688<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Resumo do sorteio da Lotomania 2692<\/h2>\n<ul>\n<li>Dos n\u00fameros sorteados neste concurso da Lotomania o que mais saiu nos \u00faltimos 12 meses foi o 79, sorteado 47 vezes.<\/li>\n<li>O que menos saiu foi o n\u00famero 18, sorteado apenas 25 vezes.<\/li>\n<li>Das 100 dezenas, a que est\u00e1 h\u00e1 mais tempo sem ser sorteada \u00e9 a 28 que n\u00e3o sai tem 63  dias.<\/li>\n<li>O maior valor pago neste per\u00edodo foi R$ 18.558.357,77 no concurso 2675, sorteado em 18\/09\/2024.<\/li>\n<li>Nos \u00faltimos 12 meses foram realizados 153 sorteios e premiadas 16 pessoas que acertaram os 20 n\u00fameros da Lotomania.<\/li>\n<li>Neste per\u00edodo a Lotomania n\u00e3o teve acertadores em 136 oportunidades.<\/li>\n<\/ul>\n<\/ul>\n<h3>Hist\u00f3rico dos n\u00fameros sorteados neste concurso da Lotomania<\/h3>\n<p>Nesta tabela voc\u00ea ir\u00e1 encontrar as seguintes informa\u00e7\u00f5es relativas aos sorteios da Lotomania dos \u00faltimos 12 meses:<br \/>A quantidade de vezes que o n\u00famero foi sorteado na Lotomania,<br \/>A quantidade de sorteios que este n\u00famero saiu e o concurso teve ganhador,<br \/>A data do \u00faltimo sorteio na Lotomania desta dezena.<\/p>\n<table>\n<tr>\n<th>Dezena<\/th>\n<th>Total<\/th>\n<th>Premiada<\/th>\n<th>Data<\/th>\n<\/tr>\n<tr>\n<td>11<\/td>\n<td>27<\/td>\n<td>4<\/td>\n<td>18\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>12<\/td>\n<td>39<\/td>\n<td>5<\/td>\n<td>23\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>18<\/td>\n<td>25<\/td>\n<td>4<\/td>\n<td>14\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>19<\/td>\n<td>35<\/td>\n<td>4<\/td>\n<td>25\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>21<\/td>\n<td>33<\/td>\n<td>1<\/td>\n<td>21\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>29<\/td>\n<td>31<\/td>\n<td>1<\/td>\n<td>04\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>32<\/td>\n<td>31<\/td>\n<td>2<\/td>\n<td>25\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>38<\/td>\n<td>38<\/td>\n<td>7<\/td>\n<td>23\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>49<\/td>\n<td>31<\/td>\n<td>2<\/td>\n<td>25\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>52<\/td>\n<td>25<\/td>\n<td>1<\/td>\n<td>16\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>56<\/td>\n<td>38<\/td>\n<td>2<\/td>\n<td>23\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>58<\/td>\n<td>25<\/td>\n<td>6<\/td>\n<td>16\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>61<\/td>\n<td>29<\/td>\n<td>2<\/td>\n<td>16\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>62<\/td>\n<td>36<\/td>\n<td>3<\/td>\n<td>25\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>65<\/td>\n<td>26<\/td>\n<td>2<\/td>\n<td>23\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>66<\/td>\n<td>31<\/td>\n<td>2<\/td>\n<td>25\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>67<\/td>\n<td>33<\/td>\n<td>3<\/td>\n<td>21\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>79<\/td>\n<td>47<\/td>\n<td>4<\/td>\n<td>23\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>84<\/td>\n<td>31<\/td>\n<td>1<\/td>\n<td>23\/10\/2024<\/td>\n<\/tr>\n<tr>\n<td>86<\/td>\n<td>30<\/td>\n<td>4<\/td>\n<td>21\/10\/2024<\/td>\n<\/tr>\n<\/table>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lotomania 2692 &#8211; Resultado, rateio e ganhadores da Lotomania 2692 sorteado em 28\/10\/2024.<\/p>\n","protected":false},"author":5,"featured_media":196333,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,359],"tags":[],"class_list":{"0":"post-248900","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-loto-mania","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-lotomania-1-1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/248900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=248900"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/248900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196333"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=248900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=248900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=248900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}