{"id":247470,"date":"2024-09-17T17:50:56","date_gmt":"2024-09-17T20:50:56","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=247470"},"modified":"2024-09-17T17:50:56","modified_gmt":"2024-09-17T20:50:56","slug":"resumo-alma-gemea-18-09-felipe-ve-zulmira-chorando","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/resumo-alma-gemea-18-09-felipe-ve-zulmira-chorando\/247470","title":{"rendered":"Resumo &#8220;Alma G\u00eamea&#8221; 18\/09: Felipe v\u00ea Zulmira chorando"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resumo-alma-gemea-logo-novela.jpg\" alt=\"\" width=\"1280\" height=\"720\" class=\"aligncenter size-full wp-image-244166\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resumo-alma-gemea-logo-novela.jpg 1280w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resumo-alma-gemea-logo-novela-250x140.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resumo-alma-gemea-logo-novela-400x225.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resumo-alma-gemea-logo-novela-768x432.jpg 768w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resumo-alma-gemea-logo-novela-150x85.jpg 150w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p><em><strong>Resumo da novela &#8220;Alma G\u00eamea&#8221;<\/strong><\/em> em 18\/09: no cap\u00edtulo 101(*) da novela, Rafael se recusa a destruir o atelier. D\u00e9bora exige que ele ao menos d\u00ea um filho a Cristina. Todos na pens\u00e3o querem cuidar da pequena Clara. Julian decide pedir a ajuda de Agnes para convencer Dalila a contar a verdade sobre o exame. Cristina decide eliminar a mem\u00f3ria de Luna da casa de Rafael. Raul descobre que Crispim est\u00e1 planejando cobrar de Ol\u00edvia os mantimentos que vendeu ao restaurante e faz o caipira crer que ela n\u00e3o vai pag\u00e1-lo. Sugere que Crispim v\u00e1 cobrar a d\u00edvida quando o restaurante estiver bem cheio. Raul inventa uma desculpa para n\u00e3o ter de sair com Madalena. Depois de jurar fazer Rafael esquecer Luna, Cristina busca uma tesoura. Ela vai at\u00e9 o atelier e destr\u00f3i os vestidos de Luna que estavam guardados. Eduardo promete proteger Alexandra e a beija. Julian explica para H\u00e9lio que o corpo de Serena pode ter trazido seq\u00fcelas da outra vida. D\u00e9bora d\u00e1 uma bronca em Zulmira, que chora. Felipe v\u00ea Zulmira chorando e pergunta o que houve. <\/p>\n<p>Raul descobre que o juiz est\u00e1 no restaurante de Ol\u00edvia e finge ser muito carinhoso com Mirella e Carlito na frente dele. Oliva vem ao sal\u00e3o disposta a saber se Raul vai querer comer de gra\u00e7a. Nessa hora, Crispim aparece exige que Ol\u00edvia lhe pague o que deve diante de todos os clientes. Cristina mostra a Rafael os trapos em que transformou os vestidos de Luna. Rafael perde a paci\u00eancia com Cristina. Cristina se descontrola e Rafael tenta segur\u00e1-la. Eurico vai contar a Felipe que D\u00e9bora maltrata Zulmira, mas \u00e9 interrompido pelos gritos de Cristina e Rafael. D\u00e9bora e Felipe separam Cristina e Rafael. Rafael chora por causa dos vestidos de Luna. Felipe aconselha Rafael a se libertar da lembran\u00e7a de Luna, dizendo que foi ela quem o impediu de valorizar Serena. Ol\u00edvia pede que Crispim volte em outra hora, mas ele acha que ela est\u00e1 tentando engan\u00e1-lo e se recusa. Raul aparece fingindo que quer ajudar. Disposta a se vingar de Rafael, Cristina se aproxima de Ivan e o beija.<\/p>\n<p> Ivan insiste em passar a noite com Cristina, mas ela acha perigoso. Cristina pede que ele a ajude na sua vingan\u00e7a contra Rafael. Rafael comenta com Felipe ter ouvido barulho vindo do quarto de Cristina. Ele diz que n\u00e3o deve larg\u00e1-la at\u00e9 que se recupere pela perda do beb\u00ea. Serena garante a Ter\u00ea que n\u00e3o est\u00e1 doente, pois n\u00e3o vai morrer antes de cumprir sua miss\u00e3o. H\u00e9lio pede Sabina em namoro e ela aceita. Eduardo diz a Alexandra que ela precisa se tratar antes que possam voltar a viver como marido e mulher. Alexandra fica arrasada e sente o esp\u00edrito mau dominando-a. Agnes garante a Julian que convencer\u00e1 Dalila a contar a verdade a Rafael. Raul salda a d\u00edvida de Ol\u00edvia com Crispim para impressionar o juiz. Ol\u00edvia n\u00e3o entende nada. Rodriguez diz a K\u00e1tia que a quer de volta e ela promete pensar. Ol\u00edvia tenta consertar as coisas com o juiz, mas parece piorar tudo. Raul finge estar preocupado com as crian\u00e7as e as leva para casa. Dalila confessa ter tido medo que Roberval n\u00e3o voltasse. Cristina jura que n\u00e3o perder\u00e1 Rafael antes de cumprir sua vingan\u00e7a. <\/p>\n<p>Divina e Roberval disputam quem vai dar a mamadeira para Clara. Roberval sai vencedor. H\u00e9lio anuncia para sua fam\u00edlia que est\u00e1 namorando Sabina. Divina desmaia. Jos\u00e9 Aristides diz que estava com saudades e d\u00e1 uma flor para Serena. D\u00e9bora tortura Rafael dizendo que \u00e9 dele a culpa pelo desequil\u00edbrio de Cristina. Agnes promete desmascarar Cristina. Raul comemora o vexame de Ol\u00edvia no restaurante. Ol\u00edvia n\u00e3o tem a menor id\u00e9ia do que far\u00e1 para saldar suas d\u00edvidas. Cristina fala para Raul que quer deixar Rafael na mis\u00e9ria. Cristina garante a Raul que vai convencer Rafael a vender o campo de rosas se descobrir que h\u00e1 mesmo uma jazida de ferro. Jos\u00e9 Aristides deixa claro a Serena que ainda gosta dela. Cristina afirma para Raul que quer ver o roseiral destru\u00eddo. <\/p>\n<p>Ter\u00ea traz uma pedra diferente e Bernardo afirma que \u00e9 ferro, sem valor algum. Cristina acaba a reuni\u00e3o com Raul e afirma para quem quiser ouvir que anda farta de rosas. Mirella pede que Raul empreste dinheiro a Ol\u00edvia para que ela pague suas d\u00edvidas. Raul fala para Mirella que quer tomar posse do restaurante. D\u00e9bora diz para Zulmira e Eurico que ir\u00e1 prejudic\u00e1-los se eles se queixarem com Felipe ou Rafael. Cristina afirma para D\u00e9bora que vai destruir tudo que Rafael mais ama, a come\u00e7ar por Serena. Crispim conta com orgulho que K\u00e1tia o defendeu. Cristina procura Rafael para pedir desculpas. Ela promete ser mais gentil e pede um prazo para que ele aprenda a am\u00e1-la, caso contr\u00e1rio ela lhe dar\u00e1 o div\u00f3rcio.<\/p>\n<p>(*) edi\u00e7\u00e3o das novelas da Globo, &#8220;Alma G\u00eamea&#8221;, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Sinopse &#8220;Alma G\u00eamea&#8221;: Rafael e Luna casam-se e t\u00eam um filho, mas a felicidade \u00e9 invejada por Cristina. Em um passeio, Rafael reage a um assalto e um dos ladr\u00f5es, que \u00e9 conhecido de Cristina, atira. Luna morre. Enquanto Rafael se desespera com a perda de Luna, em um lugar bem distante dali, nasce a menina Serena, filha de uma \u00edndia com um garimpeiro. Ela cresce em uma aldeia ind\u00edgena e tem vis\u00f5es. <\/p>\n<p>Vinte anos se passam da morte de Luna. Serena consegue trabalho como empregada na mans\u00e3o de Rafael. Serena tem em seu corpo uma marca de nascen\u00e7a, no mesmo lugar em que Luna levou o tiro. A trama segue envolta em mist\u00e9rios e marcada por fatos inexplic\u00e1veis. Rafael passa a acreditar que Serena \u00e9 de fato a reencarna\u00e7\u00e3o de Luna, se apaixona por ela e a pede em casamento. Cristina e sua m\u00e3e D\u00e9bora percebem que Serena representa uma amea\u00e7a, e a novela segue com as duas tramando de tudo para separar os dois.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo da novela &#8220;Alma G\u00eamea&#8221; em 18\/09: no cap\u00edtulo 101(*) da novela, Rafael se recusa a destruir o atelier. D\u00e9bora exige que ele ao menos d\u00ea um filho a Cristina. Todos na pens\u00e3o querem cuidar da pequena Clara. Julian decide pedir a ajuda de Agnes para convencer Dalila a contar a verdade sobre o exame. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":244165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2328,379,375,2025,343],"tags":[441],"class_list":{"0":"post-247470","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-alma-gemea","8":"category-novelas","9":"category-rede-globo","10":"category-resumo","11":"category-televisao","12":"tag-resumo-do-dia","13":"entry","14":"gs-1","15":"gs-odd","16":"gs-even","17":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela-alma-gemea-logo-resumo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/247470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=247470"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/247470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/244165"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=247470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=247470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=247470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}