{"id":245987,"date":"2024-07-16T12:12:58","date_gmt":"2024-07-16T15:12:58","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=245987"},"modified":"2024-07-16T12:12:58","modified_gmt":"2024-07-16T15:12:58","slug":"resumo-alma-gemea-17-07-cristina-diz-que-serena-ficara-sem-ter-onde-morar","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/resumo-alma-gemea-17-07-cristina-diz-que-serena-ficara-sem-ter-onde-morar\/245987","title":{"rendered":"Resumo &#8220;Alma G\u00eamea&#8221; 17\/07: Cristina diz que Serena ficar\u00e1 sem ter onde morar"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resumo-alma-gemea-logo-novela.jpg\" alt=\"\" width=\"1280\" height=\"720\" class=\"aligncenter size-full wp-image-244166\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resumo-alma-gemea-logo-novela.jpg 1280w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resumo-alma-gemea-logo-novela-250x140.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resumo-alma-gemea-logo-novela-400x225.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resumo-alma-gemea-logo-novela-768x432.jpg 768w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resumo-alma-gemea-logo-novela-150x85.jpg 150w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p><em><strong>Resumo da novela &#8220;Alma G\u00eamea&#8221;<\/strong><\/em> em 17\/07: no cap\u00edtulo 058(*) da novela, Crispim pede a Santo Expedito que lhe traga K\u00e1tia de volta. Rodriguez se recusa a se casar com K\u00e1tia. Dalila acredita que Raul esteja planejando comprar a casa da pens\u00e3o para dar um teto para ela e seu filho. Ciro conta a Rafael que encontrou uma carta de Cristina no quarto de Guto, mas confessa n\u00e3o ter tido tempo de l\u00ea-la. Gumercindo se aproxima de K\u00e1tia quando a v\u00ea chorando. No in\u00edcio ela corresponde, mas depois o afasta. Ol\u00edvia diz a Vit\u00f3rio que eles precisam namorar escondido para que Raul n\u00e3o tire a guarda de Mirella e Carlito. Dois meses se passam. Adelaide fala para Serena que o m\u00e9dico que vai ajud\u00e1-la a se lembrar de sua vida passada est\u00e1 chegando. Ciro recebe o dossi\u00ea de Guto e conta a Rafael que Cristina lhe enviou dinheiro v\u00e1rias vezes. Rafael pergunta a Cristina o que h\u00e1 entre ela e Guto. Julian, o m\u00e9dico que vai ajudar Serena, chega a Roseiral acompanhado de Sabina, sua assistente.<\/p>\n<p> Adelaide avisa Agnes que vai hospedar Julian e Sabina em sua casa. Agnes garante que vai trat\u00e1-los bem, mas acredita que Julian seja um charlat\u00e3o. Julian e Sabina chegam \u00e0 casa de Adelaide. Sabina diz a Agnes que \u00e9 uma pessoa muito triste. Agnes fica perturbada, mas responde que n\u00e3o acredita em vidas passadas. Cristina diz a Rafael que enviou dinheiro a Guto porque tinha pena dele. Rafael continua ressabiado. Cristina finge estar magoada com a desconfian\u00e7a dele. D\u00e9bora avisa Cristina que Rafael vai romper o noivado se continuar desconfiando dela. Ol\u00edvia quer gastar os lucros do restaurante em vestidos, mas Vit\u00f3rio avisa que eles precisam pagar as d\u00edvidas antes. K\u00e1tia d\u00e1 um par de sapatos de presente a Gumercindo. Ele acha que o presente \u00e9 uma declara\u00e7\u00e3o de amor, mas a secret\u00e1ria avisa que s\u00f3 gosta dele como amigo. Raul manda que seu advogado despeje os moradores da pens\u00e3o. <\/p>\n<p>Cristina diz a D\u00e9bora que Serena logo ser\u00e1 despejada junto com todos os seus amigos e ficar\u00e1 sem ter onde morar. Elias apresenta Julian e Sabina a Serena. Julian pergunta a Serena se ela quer mesmo descobrir tudo sobre sua vida passada. Rafael diz a Ciro que precisa saber a verdade sobre Cristina antes do casamento e pede que ele apresse as investiga\u00e7\u00f5es. Carlito pega Ol\u00edvia e Vit\u00f3rio juntos e fica indignado. Ol\u00edvia explica que jamais namoraria o cozinheiro. Vit\u00f3rio se ofende e os dois brigam. Crispim pergunta a K\u00e1tia por que ela n\u00e3o gosta dele. K\u00e1tia explica que \u00e9 porque ele n\u00e3o tem dinheiro. Carlito diz a Ol\u00edvia que, se a vir com Vit\u00f3rio de novo, vai contar tudo para Raul. O advogado de Raul fala para Divina e Osvaldo que eles e todos os h\u00f3spedes ter\u00e3o que deixar a casa. Serena fica euf\u00f3rica quando Julian diz que, em breve, eles ir\u00e3o come\u00e7ar uma viagem por suas vidas passadas.<\/p>\n<p>Divina e Osvaldo dizem que n\u00e3o saem da casa de jeito algum. H\u00e9lio diz ao advogado que ter\u00e1 que apresentar documentos que provem que eles precisam sair. O advogado garante que voltar\u00e1 com os documentos, deixando todos assustados. Dalila chora decepcionada e conta para o marido que Raul a enganou. Cristina experimenta seu vestido de noiva e sonha com o dia de seu casamento com Rafael. Eduardo sugere que Rafael adie seu casamento at\u00e9 Ciro terminar as investiga\u00e7\u00f5es sobre Cristina. D\u00e9bora aconselha Cristina a procurar Guto para saber se foi ele quem revelou a Rafael que ela lhe mandou dinheiro. Raul d\u00e1 o contrato de compra e venda da casa ao advogado para que ele o mostre aos pensionistas. <\/p>\n<p>Cristina pede que o advogado os despeje o mais r\u00e1pido poss\u00edvel. Vera conta a Julian que acha que a perturba\u00e7\u00e3o de Alexandra pode ter causas sobrenaturais. Julian explica que s\u00f3 poder\u00e1 investigar o caso com a permiss\u00e3o de Eduardo. Mas o m\u00e9dico se a nega. Alexandra manda que Vera a deixe em paz. Divina chora ao pensar na possibilidade de sair da casa onde mora. Guto garante a Cristina que n\u00e3o falou a Rafael que ela lhe mandava dinheiro. Cristina pede que Guto descubra quem o est\u00e1 investigando. Rafael diz a Felipe que vai desmarcar seu casamento com Cristina. Eurico ouve e conta a Zulmira. Ivan escuta. Julian comenta com Cristina que, com as sess\u00f5es de hipnose, \u00e9 poss\u00edvel que Serena se lembre do momento de sua morte na vida passada. Cristina fica nervosa. Ivan conta para Cristina que Rafael est\u00e1 pensando em desmarcar o casamento. Dalila acusa Raul de t\u00ea-la enganado e jura que vai fazer um esc\u00e2ndalo. Cristina conta a Rafael que est\u00e1 gr\u00e1vida. Serena diz a Julian que j\u00e1 est\u00e1 pronta para come\u00e7ar.<\/p>\n<p>(*) edi\u00e7\u00e3o das novelas da Globo, &#8220;Alma G\u00eamea&#8221;, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Sinopse &#8220;Alma G\u00eamea&#8221;: Rafael e Luna casam-se e t\u00eam um filho, mas a felicidade \u00e9 invejada por Cristina. Em um passeio, Rafael reage a um assalto e um dos ladr\u00f5es, que \u00e9 conhecido de Cristina, atira. Luna morre. Enquanto Rafael se desespera com a perda de Luna, em um lugar bem distante dali, nasce a menina Serena, filha de uma \u00edndia com um garimpeiro. Ela cresce em uma aldeia ind\u00edgena e tem vis\u00f5es. <\/p>\n<p>Vinte anos se passam da morte de Luna. Serena consegue trabalho como empregada na mans\u00e3o de Rafael. Serena tem em seu corpo uma marca de nascen\u00e7a, no mesmo lugar em que Luna levou o tiro. A trama segue envolta em mist\u00e9rios e marcada por fatos inexplic\u00e1veis. Rafael passa a acreditar que Serena \u00e9 de fato a reencarna\u00e7\u00e3o de Luna, se apaixona por ela e a pede em casamento. Cristina e sua m\u00e3e D\u00e9bora percebem que Serena representa uma amea\u00e7a, e a novela segue com as duas tramando de tudo para separar os dois.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo da novela &#8220;Alma G\u00eamea&#8221; em 17\/07: no cap\u00edtulo 058(*) da novela, Crispim pede a Santo Expedito que lhe traga K\u00e1tia de volta. Rodriguez se recusa a se casar com K\u00e1tia. Dalila acredita que Raul esteja planejando comprar a casa da pens\u00e3o para dar um teto para ela e seu filho. Ciro conta a Rafael [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":244165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2328,379,375,2025,343],"tags":[441],"class_list":{"0":"post-245987","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-alma-gemea","8":"category-novelas","9":"category-rede-globo","10":"category-resumo","11":"category-televisao","12":"tag-resumo-do-dia","13":"entry","14":"gs-1","15":"gs-odd","16":"gs-even","17":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela-alma-gemea-logo-resumo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/245987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=245987"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/245987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/244165"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=245987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=245987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=245987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}