{"id":24554,"date":"2010-03-15T13:14:53","date_gmt":"2010-03-15T17:14:53","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=24554"},"modified":"2012-04-02T15:42:49","modified_gmt":"2012-04-02T18:42:49","slug":"malhacao-bernardo-surpreende-cristiana-15-a-1903","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/malhacao-bernardo-surpreende-cristiana-15-a-1903\/24554","title":{"rendered":"Malha\u00e7\u00e3o &#8211; Bernardo surpreende Cristiana (15 a 19\/03)"},"content":{"rendered":"<p><strong><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-22587\" title=\"novela globo malhacao\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela-globo-malhacao1.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela-globo-malhacao1.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela-globo-malhacao1-250x161.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela-globo-malhacao1-150x97.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Malha\u00e7\u00e3o<\/em><\/strong>, novela da Rede Globo &#8211; o <strong><em>resumo de novela<\/em><\/strong> publicado pela Rede <strong><em>Globo<\/em><\/strong> divulgou que em Malha\u00e7\u00e3o, Bernardo vai surpreender Cristiana com uma declara\u00e7\u00e3o de amor p\u00fablica antes da apresenta\u00e7\u00e3o da banda. Em Malha\u00e7\u00e3o, <strong><em>cap\u00edtulo<\/em><\/strong> 3769 \u2013 Segunda-feira, dia 15 de mar\u00e7o &#8211;\u00a0Nanda afirma para Bernardo e Cristiana que o namoro deles n\u00e3o vai durar. Ant\u00f4nio conversa com Nanda sobre sua rea\u00e7\u00e3o ao namoro da irm\u00e3 e fica sem paci\u00eancia ao ouvir os argumentos da filha. Os Vikings n\u00e3o aceitam Bernardo de volta no time. Rodrigo fica irritado com Jotapeg por ter engolido seu piv\u00f4. Bruno pensa insistentemente sobre como se aproximar de Samira. Cristiana repreende Bernardo por querer apressar as coisas entre eles. Valter conversa com Al\u00ea sobre sua vida. Nanda chega ao col\u00e9gio e chama Bia e Tati para conversar no Escondidinho. Cristiana conta para Valentina e Maria Cl\u00e1udia como ganhou o colar de Bernardo. Nanda explica para as c\u00famplices o que aconteceu para que sua irm\u00e3 assumisse o namoro com Bernardo e planeja separ\u00e1-los. Bernardo fica chateado por n\u00e3o ter sido aceito de volta no time. Bruno vai procurar Samira e se entristece ao perceber que ela n\u00e3o foi ao col\u00e9gio. Samira tenta argumentar com Jamal, mas ele n\u00e3o a escuta. Livramento e Julinho avaliam os trabalhos sobre samba dos alunos. Os Florestanos v\u00e3o at\u00e9 o Rocket para propor um desafio aos Vikings. Julinho fala para Livramento observar Rodrigo e se espanta ao v\u00ea-lo sambar mal. Beto aceita o desafio dos Florestanos, mas fica receoso ao lembrar que Bernardo n\u00e3o est\u00e1 mais no time. A turma do Himalaia combina de comprar um novo piv\u00f4 para Rodrigo. Samira se sente mal e L\u00edvia fica preocupada. Bernardo tenta se aproximar de Cristiana, mas ela n\u00e3o deixa e fica irritada com ele. Bernardo e Cristiana recebem outra foto deles se beijando e ficam intrigados.<\/p>\n<p>Em Malha\u00e7\u00e3o cap\u00edtulo 3770 \u2013 Ter\u00e7a-feira, dia 16 de mar\u00e7o &#8211;\u00a0Bernardo e Cristiana reagem surpresos ao receberem fotos deles juntos e comentam com Clarinha, Paulo Roberto e Cissa. L\u00edvia chama um m\u00e9dico para Samira e Jamal fica ao lado da filha. Beto e Al\u00ea comunicam aos Vikings sobre o desafio contra os Florestanos e eles aceitam que Bernardo volte para o time. Samira continua sem comer nada e Jamal e L\u00edvia ficam preocupados com a filha. Cissa sonda Bernardo sobre suas inten\u00e7\u00f5es com Cristiana. Nanda aproveita para usar o colar que Bernardo deu para Cristiana quando ela o tira para tomar banho. Valter se encontra com Al\u00ea. Maria Cl\u00e1udia se apresenta para ser a baixista da banda das meninas. Cristiana e Bernardo chegam ao Rocket para ver o show de Beto e Reco, e Bia fica enfurecida. Cissa n\u00e3o gosta de ver que Bernardo trocou a foto dela por uma foto de Cristiana. Maria Cl\u00e1udia toca muito mal o baixo e as meninas ficam sem saber o que dizer. Tati tamb\u00e9m se candidata para ser baixista da banda de meninas e todas ficam surpresas. Cissa vai reclamar do namoro de Bernardo e Cristiana com Paulo Roberto. Beto chama Bernardo para voltar para os Vikings. Valentina, Rita e Juju ficam impressionadas ao ouvirem Tati tocar o baixo. Al\u00ea conta para Ciro sobre a conversa que teve com Valter. Cristiana e Bernardo chegam em casa e ele sugere que os dois tomem um banho de piscina. Juju, Rita e Valentina ficam na d\u00favida sobre quem chamar para baixista da banda. Bernardo deixa Cristiana sozinha na piscina e vai at\u00e9 a mans\u00e3o pegar mais suco para eles. Bruno se preocupa ao saber sobre o estado de sa\u00fade de Samira. Jamal e L\u00edvia ficam na d\u00favida se deixam Bruno falar com a filha. Cissa repreende Cristiana e a manda sair de sua piscina.<\/p>\n<p>Em Malha\u00e7\u00e3o cap\u00edtulo\u00a03771 \u2013 Quarta-feira, dia 17 de mar\u00e7o &#8211;\u00a0Cissa n\u00e3o deixa Cristiana se explicar e a menina sai da piscina arrasada. Ela entra em casa chorando e Nanda fica curiosa para descobrir o que aconteceu. L\u00edvia convence Jamal a deixar Bruno falar com Samira. Bernardo vai at\u00e9 a casa de Cristina e os dois saem, deixando Nanda ainda mais curiosa. Bruno consegue fazer Samira comer, deixando L\u00edvia e Jamal aliviados. Cristiana conta para Bernardo o que Cissa fez com ela e o rapaz se irrita com a m\u00e3e. Bruno pede para Samira n\u00e3o deixar mais de comer. Bernardo tira satisfa\u00e7\u00f5es com Cissa, que fica indignada com a atitude do filho. Maria Cl\u00e1udia leva mai\u00f4s para o figurino da banda de garotas. Rafael, Jotapeg e Juju conversam sobre o Festival de M\u00fasica no Rocket. Bernardo conta para Beto sobre as atitudes de Cissa com Cristiana. Tati mostra seu blog para Juju, Valentina e Rita, e diz que seus f\u00e3s poder\u00e3o ajud\u00e1-las a ganhar o festival fazendo uma grande torcida. L\u00edvia conversa com Jamal sobre Bruno e o pai de Samira decide falar com o ele. Cristiana n\u00e3o aceita almo\u00e7ar na casa de Bernardo e ele fica chateado. Maria Cl\u00e1udia e Tati agradam Juju, Valentina e Rita para ficarem com a vaga de baixista da banda. Bernardo discute com Cissa e vai almo\u00e7ar na casa de Cristiana. Al\u00ea conversa com Valter sobre suas d\u00favidas. Bernardo entra na casa de Cristiana e Nanda os deixa a s\u00f3s. Juju, Valentina e Rita n\u00e3o sabem quem ir\u00e3o escolher para baixista da banda. Jamal avisa Samira e Bruno que quer conversar sobre o relacionamento deles. Cissa reclama com Paulo Roberto do namoro de Bernardo e Nanda fica feliz ao ouvir a conversa deles.<\/p>\n<p>Em Malha\u00e7\u00e3o cap\u00edtulo\u00a03772 \u2013 Quinta-feira, dia 18 de mar\u00e7o &#8211;\u00a0Nanda pensa em se aproximar de Cissa para acabar com o namoro de Bernardo e Cristiana. Cissa fica contrariada quando Paulo Roberto pede para ela esquecer o namoro de Bernardo. Nanda esconde de Bia a descoberta que fez sobre a m\u00e3e de Bernardo. Al\u00ea diz que vai pensar na proposta de Valter. Jamal diz a Bruno que Samira n\u00e3o vai sair do Primeira Op\u00e7\u00e3o, mas pro\u00edbe o casal de namorar. Juju, Valentina e Rita decidem escolher Tati como baixista da banda e Maria Cl\u00e1udia fica arrasada. Cissa diz que vai com Bernardo assistir ao jogo dos Vikings e fica chateada ao saber que o filho vai levar Cristiana com ele. Samira diz a Bruno que n\u00e3o vai seguir as regras de Jamal. Cristiana conta para Valentina o que Cissa fez com ela. Bernardo anima os Vikings antes do come\u00e7o do jogo. Nanda fala mal da irm\u00e3 para Cissa e diz que pode ajud\u00e1-la a separar Cristiana e seu filho. Bernardo marca o gol decisivo no jogo contra os Florestanos. Valentina, Juju, Rita e Tati se re\u00fanem para pensar em um nome para a banda e em uma m\u00fasica para elas tocarem. Cissa se decepciona ao descobrir que a m\u00fasica que Bernardo est\u00e1 compondo n\u00e3o \u00e9 para ela. Zuleide pede para Beto e Reco apresentarem o festival de m\u00fasica e os dois pensam em novas piadas. Maria Cl\u00e1udia reclama de n\u00e3o ter sido escolhida por Valentina, Juju e Rita para ser a baixista da banda. As meninas da banda ficam aflitas por n\u00e3o conseguirem compor nenhuma m\u00fasica. Nanda conta para Cissa que Bernardo vendeu seu bal\u00e3o para ajudar Cristiana. Al\u00ea conversa com Ciro. Cissa fica indignada com a not\u00edcia que Nanda lhe d\u00e1 e avisa que vai falar com o marido sobre o caso. Paulo Roberto e Cissa perguntam se Bernardo vendeu mesmo seu bal\u00e3o para pagar a fisioterapia de Cristiana.<\/p>\n<p>Em Malha\u00e7\u00e3o cap\u00edtulo\u00a03773 \u2013 Sexta-feira, dia 19 de mar\u00e7o &#8211;\u00a0Bernardo afirma que emprestou uma parte do dinheiro para Cristiana e que ela j\u00e1 pagou a d\u00edvida com o pr\u00eamio que ganharam no campeonato de patina\u00e7\u00e3o. Paulo Roberto compreende a explica\u00e7\u00e3o do filho, mas Cissa fica indignada. Tati n\u00e3o concorda com a letra da m\u00fasica escrita por Valentina, Juju e Rita. Bernardo termina de compor a m\u00fasica que fez para Cristiana e mostra para Beto. Samira volta para o col\u00e9gio, mas n\u00e3o deixa Bruno beij\u00e1-la na frente de todos. T\u00e2nia faz um an\u00fancio na r\u00e1dio com g\u00edrias antigas e os alunos n\u00e3o entendem o que ela quis dizer. Bernardo e Cristiana tentam descobrir como os pais dele souberam que ele vendeu o bal\u00e3o. Paulo Roberto pede para Cissa desistir de impedir o namoro de Bernardo, mas ela n\u00e3o o ouve e garante que vai separar os dois. Cristiana fica curiosa para saber como \u00e9 a m\u00fasica que Bernardo fez para ela. Reco, Jotapeg e Rodrigo ironizam o jeito de T\u00e2nia falar e a deixam intrigada com suas g\u00edrias. T\u00e2nia diz a Livramento que vai se atualizar para entender os adolescentes. Cristiana conta para Maria Cl\u00e1udia e Samira que Bernardo fez uma m\u00fasica para ela. Reco e Beto iniciam a apresenta\u00e7\u00e3o do festival de m\u00fasica. A plateia reage desanimada \u00e0 m\u00fasica de Rafael e dan\u00e7a com o som eletr\u00f4nico de Jotapeg. Bruno pergunta para Samira se ela est\u00e1 mesmo disposta a mudar suas atitudes para que eles fiquem juntos. Rodrigo comenta com Bimba que j\u00e1 ouviu a m\u00fasica que Jotapeg tocou. A banda de garotas come\u00e7a sua apresenta\u00e7\u00e3o. Nanda conta para Cissa que Bernardo usou o dinheiro que Cristiana lhe deu para comprar uma j\u00f3ia para a namorada. Antes de sua apresenta\u00e7\u00e3o, Bernardo faz uma declara\u00e7\u00e3o de amor para Cristiana.\u00a0<\/p>\n<p>Malha\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Malha\u00e7\u00e3o, novela da Rede Globo &#8211; o resumo de novela publicado pela Rede Globo divulgou que em Malha\u00e7\u00e3o, Bernardo vai surpreender Cristiana com uma declara\u00e7\u00e3o de amor p\u00fablica antes da apresenta\u00e7\u00e3o da banda. Em Malha\u00e7\u00e3o, cap\u00edtulo 3769 \u2013 Segunda-feira, dia 15 de mar\u00e7o &#8211;\u00a0Nanda afirma para Bernardo e Cristiana que o namoro deles n\u00e3o vai [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":22587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22,379,375,343],"tags":[],"class_list":{"0":"post-24554","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-novelas","9":"category-rede-globo","10":"category-televisao","11":"entry","12":"gs-1","13":"gs-odd","14":"gs-even","15":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela-globo-malhacao1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/24554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=24554"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/24554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/22587"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=24554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=24554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=24554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}