{"id":244514,"date":"2024-05-09T20:10:17","date_gmt":"2024-05-09T23:10:17","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-911-sorteado-quinta-feira-09-05-2024\/244514"},"modified":"2024-05-10T09:52:58","modified_gmt":"2024-05-10T12:52:58","slug":"dia-de-sorte-resultado-do-concurso-911-sorteado-quinta-feira-09-05-2024","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-911-sorteado-quinta-feira-09-05-2024\/244514","title":{"rendered":"Dia de Sorte: Resultado do concurso 911 sorteado  Quinta-feira 09\/05\/2024"},"content":{"rendered":"<p>Resultado do Dia de Sorte, concurso 911, realizado na  Quinta-feira, dia 09\/05\/2024 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo.  O Dia de Sorte 911 n\u00e3o teve acertador do pr\u00eamio principal e a previs\u00e3o do pr\u00eamio para o pr\u00f3ximo sorteio, Dia de Sorte 912, \u00e9 de R$ 300.000,00. Com este resultado a Dia de Sorte  esta acumulado ha  1 sorteio<\/p>\n<p>Veja tamb\u00e9m: <\/p>\n<h2>N\u00fameros Sorteados Dia de Sorte 911<\/h2>\n<table style=\"margin-bottom: 10px;\">\n<tr>\n<td><span class=\"numberCircleDiaDeSorte\">01<\/span><\/td>\n<td><span class=\"numberCircleDiaDeSorte\">02<\/span><\/td>\n<td><span class=\"numberCircleDiaDeSorte\">10<\/span><\/td>\n<td><span class=\"numberCircleDiaDeSorte\">13<\/span><\/td>\n<td><span class=\"numberCircleDiaDeSorte\">25<\/span><\/td>\n<td><span class=\"numberCircleDiaDeSorte\">29<\/span><\/td>\n<td><span class=\"numberCircleDiaDeSorte\">30<\/span><\/td>\n<\/tr>\n<\/table>\n<div style =\"font-size: 1.3em;margin-bottom:20px;\">M\u00eas da Sorte: Dezembro<\/div>\n<h2>Premia\u00e7\u00e3o Dia de Sorte 911<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad.<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td>  7  <\/td>\n<td>0<\/td>\n<td>0,00<\/td>\n<\/tr>\n<tr>\n<td>  6 <\/td>\n<td>37<\/td>\n<td>2.060,23<\/td>\n<\/tr>\n<tr>\n<td>  5 <\/td>\n<td>1.280<\/td>\n<td>25,00<\/td>\n<\/tr>\n<tr>\n<td>  4 <\/td>\n<td>15.039<\/td>\n<td>5,00<\/td>\n<\/tr>\n<tr>\n<td>  M\u00eas da Sorte <\/td>\n<td>37.400<\/td>\n<td>2,50<\/td>\n<\/tr>\n<\/table>\n<h2>Total de Apostas realizadas<\/h2>\n<p>No concurso 911 do Dia de Sorte foi realizado um total de 520.127 apostas.<\/p>\n<h2>Pr\u00f3ximo Sorteio da Dia de Sorte <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado S\u00e1bado 11\/05\/2024, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 300.000,00.<\/p>\n<h3>\u00daltimos Resultados do Dia de Sorte<\/h3>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-911-sorteado-quinta-feira-09-05-2024\/244514\">Dia de Sorte 911<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-910-sorteado-terca-feira-07-05-2024\/244460\">Dia de Sorte 910<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-909-sorteado-sabado-04-05-2024\/244389\">Dia de Sorte 909<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-908-sorteado-quinta-feira-02-05-2024\/244348\">Dia de Sorte 908<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/dia-de-sorte-resultado-do-concurso-907-sorteado-terca-feira-30-04-2024\/244306\">Dia de Sorte 907<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Resumo do sorteio do Dia de Sorte 911<\/h2>\n<ul>\n<li>Dos n\u00fameros sorteados neste concurso da Dia de Sorte o que mais saiu nos \u00faltimos 12 meses foi o 25, sorteado 42 vezes.<\/li>\n<li>O que menos saiu foi o n\u00famero 30, sorteado apenas 31 vezes.<\/li>\n<li>Das 31 dezenas, a que est\u00e1 h\u00e1 mais tempo sem ser sorteada \u00e9 a 19 que n\u00e3o sai tem 33  dias.<\/li>\n<li>O maior valor pago neste per\u00edodo foi R$ 6.900.229,20 no concurso 815, sorteado em 26\/09\/2023.<\/li>\n<li>Nos \u00faltimos 12 meses foram realizados 156 sorteios e premiadas 36 pessoas que acertaram os 7 n\u00fameros da Dia de Sorte.<\/li>\n<li>Neste per\u00edodo o Dia de Sorte n\u00e3o teve acertadores em 126 oportunidades.<\/li>\n<\/ul>\n<\/ul>\n<h3>Hist\u00f3rico dos n\u00fameros sorteados neste concurso da Dia de Sorte<\/h3>\n<p>Nesta tabela voc\u00ea ir\u00e1 encontrar as seguintes informa\u00e7\u00f5es relativas aos sorteios da Dia de Sorte dos \u00faltimos 12 meses:<br \/>A quantidade de vezes que o n\u00famero foi sorteado na Dia de Sorte,<br \/>A quantidade de sorteios que este n\u00famero saiu e o concurso teve ganhador,<br \/>A data do \u00faltimo sorteio na Dia de Sorte desta dezena.<\/p>\n<table>\n<tr>\n<th>Dezena<\/th>\n<th>Total<\/th>\n<th>Premiada<\/th>\n<th>Data<\/th>\n<\/tr>\n<tr>\n<td>01<\/td>\n<td>32<\/td>\n<td>5<\/td>\n<td>07\/05\/2024<\/td>\n<\/tr>\n<tr>\n<td>02<\/td>\n<td>39<\/td>\n<td>7<\/td>\n<td>30\/04\/2024<\/td>\n<\/tr>\n<tr>\n<td>10<\/td>\n<td>36<\/td>\n<td>6<\/td>\n<td>02\/05\/2024<\/td>\n<\/tr>\n<tr>\n<td>13<\/td>\n<td>35<\/td>\n<td>5<\/td>\n<td>02\/05\/2024<\/td>\n<\/tr>\n<tr>\n<td>25<\/td>\n<td>42<\/td>\n<td>11<\/td>\n<td>04\/05\/2024<\/td>\n<\/tr>\n<tr>\n<td>29<\/td>\n<td>37<\/td>\n<td>5<\/td>\n<td>27\/04\/2024<\/td>\n<\/tr>\n<tr>\n<td>30<\/td>\n<td>31<\/td>\n<td>3<\/td>\n<td>04\/05\/2024<\/td>\n<\/tr>\n<\/table>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dia de Sorte 911 &#8211; Resultado, rateio e ganhadores do Dia de Sorte 911 sorteado em 09\/05\/2024.<\/p>\n","protected":false},"author":5,"featured_media":196327,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[478,335],"tags":[],"class_list":{"0":"post-244514","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dia-de-sorte","8":"category-loteria","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/dia-de-sorte-resultado.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/244514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=244514"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/244514\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196327"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=244514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=244514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=244514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}