{"id":243180,"date":"2024-03-20T20:08:14","date_gmt":"2024-03-20T23:08:14","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6395-sorteado-quarta-feira-20-03-2024\/243180"},"modified":"2024-03-21T07:00:32","modified_gmt":"2024-03-21T10:00:32","slug":"quina-resultado-do-concurso-6395-sorteado-quarta-feira-20-03-2024","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6395-sorteado-quarta-feira-20-03-2024\/243180","title":{"rendered":"Quina: Resultado do concurso 6395 sorteado  Quarta-feira 20\/03\/2024"},"content":{"rendered":"<p>Resultado da Quina, concurso 6395, realizado na  Quarta-feira, dia 20\/03\/2024 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo.  A Quina 6395 teve 1 acertador dos  n\u00fameros. O ganhador \u00e9 da cidade de Embu-Gua\u00e7u (SP) e receber\u00e1 um pr\u00eamio de R$ 9.013.491,13. A previs\u00e3o do pr\u00eamio para o pr\u00f3ximo sorteio, Quina 6396,  \u00e9 de R$ 700.000,00.<\/p>\n<p>Veja tamb\u00e9m: <a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2020\/todos-os-resultados-da-quina\/199388\"> Todos os resultados da Quina<\/a><\/p>\n<h2>N\u00fameros Sorteados Quina 6395<\/h2>\n<table>\n<tr>\n<td><span class=\"numberCircleQuina\">14<\/span><\/td>\n<td><span class=\"numberCircleQuina\">27<\/span><\/td>\n<td><span class=\"numberCircleQuina\">35<\/span><\/td>\n<td><span class=\"numberCircleQuina\">51<\/span><\/td>\n<td><span class=\"numberCircleQuina\">78<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Premia\u00e7\u00e3o Quina 6395<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad.<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td> 1<\/td>\n<td>9.013.491,13<\/td>\n<\/tr>\n<tr>\n<td>  4 <\/td>\n<td>61<\/td>\n<td>7.149,02<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td>4.061<\/td>\n<td>102,27<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td>103.639<\/td>\n<td>4,00<\/td>\n<\/tr>\n<\/table>\n<h2>Cidades Ganhadoras da Quina 6395<\/h2>\n<p>As apostas vencedoras foram realizadas nas seguintes cidades:<\/p>\n<table>\n<tr>\n<th>Cidade<\/th>\n<th>UF<\/th>\n<th>Ganhadores<\/th>\n<\/tr>\n<tr>\n<td>Embu-Gua\u00e7u<\/td>\n<td>SP<\/td>\n<td>1<\/td>\n<\/tr>\n<\/table>\n<h2>Total de Apostas realizadas<\/h2>\n<p>No concurso 6395 da Quina foi realizado um total de 3.832.285 apostas.<\/p>\n<h2>Pr\u00f3ximo Sorteio da Quina <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Quinta-feira 21\/03\/2024, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 700.000,00.<\/p>\n<h3>\u00daltimos Resultados da Quina<\/h3>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6395-sorteado-quarta-feira-20-03-2024\/243180\">Quina 6395<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6394-sorteado-terca-feira-19-03-2024\/243136\">Quina 6394<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6393-sorteado-segunda-feira-18-03-2024\/243104\">Quina 6393<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6392-sorteado-sabado-16-03-2024\/243066\">Quina 6392<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6391-sorteado-sexta-feira-15-03-2024\/243022\">Quina 6391<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Resumo do sorteio da Quina 6395<\/h2>\n<ul>\n<li>Dos n\u00fameros sorteados neste concurso da Quina o que mais saiu nos \u00faltimos 12 meses foi o 14, sorteado 23 vezes.<\/li>\n<li>O que menos saiu foi o n\u00famero 35, sorteado apenas 19 vezes.<\/li>\n<li>Das 80 dezenas, a que est\u00e1 h\u00e1 mais tempo sem ser sorteada \u00e9 a 68 que n\u00e3o sai tem 82  dias.<\/li>\n<li>O pr\u00eamio de maior valor pago neste per\u00edodo, sem contar o da Quina de S\u00e3o Jo\u00e3o, foi de R$ 36.290.017,10 correspondente ao concurso 6196, sorteado em 22\/07\/2023.<\/li>\n<li>Nos \u00faltimos 12 meses foram realizados 290 sorteios e premiadas 75 pessoas que acertaram os 5 n\u00fameros da Quina.<\/li>\n<li>Neste per\u00edodo a Quina n\u00e3o teve acertadores em 239 oportunidades.<\/li>\n<\/ul>\n<\/ul>\n<h3>Hist\u00f3rico dos n\u00fameros sorteados neste concurso da Quina<\/h3>\n<p>Nesta tabela voc\u00ea ir\u00e1 encontrar as seguintes informa\u00e7\u00f5es relativas aos sorteios da Quina dos \u00faltimos 12 meses:<br \/>A quantidade de vezes que o n\u00famero foi sorteado na Quina,<br \/>A quantidade de sorteios que este n\u00famero saiu e o concurso teve ganhador,<br \/>A data do \u00faltimo sorteio na Quina desta dezena.<\/p>\n<table>\n<tr>\n<th>Dezena<\/th>\n<th>Total<\/th>\n<th>Premiada<\/th>\n<th>Data<\/th>\n<\/tr>\n<tr>\n<td>14<\/td>\n<td>23<\/td>\n<td>7<\/td>\n<td>28\/12\/2023<\/td>\n<\/tr>\n<tr>\n<td>27<\/td>\n<td>21<\/td>\n<td>5<\/td>\n<td>07\/03\/2024<\/td>\n<\/tr>\n<tr>\n<td>35<\/td>\n<td>19<\/td>\n<td>1<\/td>\n<td>17\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>51<\/td>\n<td>20<\/td>\n<td>4<\/td>\n<td>06\/03\/2024<\/td>\n<\/tr>\n<tr>\n<td>78<\/td>\n<td>19<\/td>\n<td>4<\/td>\n<td>05\/03\/2024<\/td>\n<\/tr>\n<\/table>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quina 6395 &#8211; Resultado, rateio e ganhadores da Quina 6395 sorteado em 20\/03\/2024.<\/p>\n","protected":false},"author":5,"featured_media":196332,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,358],"tags":[],"class_list":["post-243180","post","type-post","status-publish","format-standard","has-post-thumbnail","category-loteria","category-quina","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-quina-1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/243180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=243180"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/243180\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196332"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=243180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=243180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=243180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}