{"id":242995,"date":"2024-03-14T20:07:15","date_gmt":"2024-03-14T23:07:15","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6390-sorteado-quinta-feira-14-03-2024\/242995"},"modified":"2024-03-15T00:10:30","modified_gmt":"2024-03-15T03:10:30","slug":"quina-resultado-do-concurso-6390-sorteado-quinta-feira-14-03-2024","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6390-sorteado-quinta-feira-14-03-2024\/242995","title":{"rendered":"Quina: Resultado do concurso 6390 sorteado  Quinta-feira 14\/03\/2024"},"content":{"rendered":"<p>Resultado da Quina, concurso 6390, realizado na  Quinta-feira, dia 14\/03\/2024 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo.  A Quina 6390 n\u00e3o teve acertador do pr\u00eamio principal e a previs\u00e3o do pr\u00eamio para o pr\u00f3ximo sorteio, Quina 6391, \u00e9 de R$ 1.300.000,00. Com este resultado a Quina  esta acumulada ha  1 sorteio<\/p>\n<p>Veja tamb\u00e9m: <a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2020\/todos-os-resultados-da-quina\/199388\"> Todos os resultados da Quina<\/a><\/p>\n<h2>N\u00fameros Sorteados Quina 6390<\/h2>\n<table>\n<tr>\n<td><span class=\"numberCircleQuina\">21<\/span><\/td>\n<td><span class=\"numberCircleQuina\">38<\/span><\/td>\n<td><span class=\"numberCircleQuina\">52<\/span><\/td>\n<td><span class=\"numberCircleQuina\">61<\/span><\/td>\n<td><span class=\"numberCircleQuina\">67<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Premia\u00e7\u00e3o Quina 6390<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad.<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td> 0<\/td>\n<td>0,00<\/td>\n<\/tr>\n<tr>\n<td>  4 <\/td>\n<td>14<\/td>\n<td>18.117,68<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td>1.520<\/td>\n<td>158,92<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td>44.019<\/td>\n<td>5,48<\/td>\n<\/tr>\n<\/table>\n<h2>Total de Apostas realizadas<\/h2>\n<p>No concurso 6390 da Quina foi realizado um total de 2.229.011 apostas.<\/p>\n<h2>Pr\u00f3ximo Sorteio da Quina <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Sexta-feira 15\/03\/2024, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 1.300.000,00.<\/p>\n<h3>\u00daltimos Resultados da Quina<\/h3>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6390-sorteado-quinta-feira-14-03-2024\/242995\">Quina 6390<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6389-sorteado-quarta-feira-13-03-2024\/242956\">Quina 6389<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6388-sorteado-terca-feira-12-03-2024\/242911\">Quina 6388<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6387-sorteado-segunda-feira-11-03-2024\/242859\">Quina 6387<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6386-sorteado-sabado-09-03-2024\/242830\">Quina 6386<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Resumo do sorteio da Quina 6390<\/h2>\n<ul>\n<li>Dos n\u00fameros sorteados neste concurso da Quina o que mais saiu nos \u00faltimos 12 meses foi o 52, sorteado 25 vezes.<\/li>\n<li>O que menos saiu foi o n\u00famero 38, sorteado apenas 13 vezes.<\/li>\n<li>Das 80 dezenas, a que est\u00e1 h\u00e1 mais tempo sem ser sorteada \u00e9 a 14 que n\u00e3o sai tem 77  dias.<\/li>\n<li>O pr\u00eamio de maior valor pago neste per\u00edodo, sem contar o da Quina de S\u00e3o Jo\u00e3o, foi de R$ 36.290.017,10 correspondente ao concurso 6196, sorteado em 22\/07\/2023.<\/li>\n<li>Nos \u00faltimos 12 meses foram realizados 290 sorteios e premiadas 74 pessoas que acertaram os 5 n\u00fameros da Quina.<\/li>\n<li>Neste per\u00edodo a Quina n\u00e3o teve acertadores em 240 oportunidades.<\/li>\n<\/ul>\n<\/ul>\n<h3>Hist\u00f3rico dos n\u00fameros sorteados neste concurso da Quina<\/h3>\n<p>Nesta tabela voc\u00ea ir\u00e1 encontrar as seguintes informa\u00e7\u00f5es relativas aos sorteios da Quina dos \u00faltimos 12 meses:<br \/>A quantidade de vezes que o n\u00famero foi sorteado na Quina,<br \/>A quantidade de sorteios que este n\u00famero saiu e o concurso teve ganhador,<br \/>A data do \u00faltimo sorteio na Quina desta dezena.<\/p>\n<table>\n<tr>\n<th>Dezena<\/th>\n<th>Total<\/th>\n<th>Premiada<\/th>\n<th>Data<\/th>\n<\/tr>\n<tr>\n<td>21<\/td>\n<td>22<\/td>\n<td>3<\/td>\n<td>06\/03\/2024<\/td>\n<\/tr>\n<tr>\n<td>38<\/td>\n<td>13<\/td>\n<td>2<\/td>\n<td>24\/01\/2024<\/td>\n<\/tr>\n<tr>\n<td>52<\/td>\n<td>25<\/td>\n<td>4<\/td>\n<td>07\/03\/2024<\/td>\n<\/tr>\n<tr>\n<td>61<\/td>\n<td>25<\/td>\n<td>1<\/td>\n<td>12\/03\/2024<\/td>\n<\/tr>\n<tr>\n<td>67<\/td>\n<td>13<\/td>\n<td>1<\/td>\n<td>19\/02\/2024<\/td>\n<\/tr>\n<\/table>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quina 6390 &#8211; Resultado, rateio e ganhadores da Quina 6390 sorteado em 14\/03\/2024.<\/p>\n","protected":false},"author":5,"featured_media":196332,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,358],"tags":[],"class_list":["post-242995","post","type-post","status-publish","format-standard","has-post-thumbnail","category-loteria","category-quina","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-quina-1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/242995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=242995"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/242995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196332"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=242995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=242995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=242995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}