{"id":241985,"date":"2024-02-06T20:18:35","date_gmt":"2024-02-06T23:18:35","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/lotofacil-resultado-do-concurso-3023-sorteado-terca-feira-06-02-2024\/241985"},"modified":"2024-02-06T20:18:35","modified_gmt":"2024-02-06T23:18:35","slug":"lotofacil-resultado-do-concurso-3023-sorteado-terca-feira-06-02-2024","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/lotofacil-resultado-do-concurso-3023-sorteado-terca-feira-06-02-2024\/241985","title":{"rendered":"Lotofacil: Resultado do concurso 3023 sorteado  Ter\u00e7a-feira 06\/02\/2024"},"content":{"rendered":"<p>Resultado da Lotofacil, concurso 3023, realizado na  Ter\u00e7a-feira, dia 06\/02\/2024 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo.  O sorteio da Lotofacil 3023 foi realizado h\u00e1 pouco, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo, e a Caixa ainda n\u00e3o divulgou a premia\u00e7\u00e3o. O pr\u00eamio previsto para o acertador do pr\u00eamio principal deste sorteio \u00e9 de R$ 4.700.000,00.<\/p>\n<p>Veja tamb\u00e9m: <a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2020\/todos-os-resultados-da-lotofacil\/199385\"> Todos os resultados da Lotofacil<\/a><\/p>\n<h2>N\u00fameros Sorteados Lotofacil 3023<\/h2>\n<table>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">02<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">03<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">06<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">07<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">10<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">12<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">13<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">15<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">16<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">18<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">20<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">21<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">22<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">23<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">25<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Pr\u00f3ximo Sorteio da Lotofacil <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Quarta-feira 07\/02\/2024, . <\/p>\n<h3>\u00daltimos Resultados da Lotofacil<\/h3>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/lotofacil-resultado-do-concurso-3022-sorteado-segunda-feira-05-02-2024\/241950\">Lotofacil 3022<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/lotofacil-resultado-do-concurso-3021-sorteado-sabado-03-02-2024\/241920\">Lotofacil 3021<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/lotofacil-resultado-do-concurso-3020-sorteado-sexta-feira-02-02-2024\/241895\">Lotofacil 3020<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/lotofacil-resultado-do-concurso-3019-sorteado-quinta-feira-01-02-2024\/241868\">Lotofacil 3019<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Resumo do sorteio da Lotofacil 3023<\/h2>\n<ul>\n<li>Dos n\u00fameros sorteados neste concurso da Lotofacil o que mais saiu nos \u00faltimos 12 meses foi o 20, sorteado 200 vezes.<\/li>\n<li>O que menos saiu foi o n\u00famero 16, sorteado apenas 153 vezes.<\/li>\n<li>Das 25 dezenas, a que est\u00e1 h\u00e1 mais tempo sem ser sorteada \u00e9 a 1 que n\u00e3o sai tem 5  dias.<\/li>\n<li>O pr\u00eamio de maior valor pago neste per\u00edodo, sem contar o da Lotofacil da Independ\u00eancia, foi de R$ 12.607.118,10 correspondente ao concurso 2971, sorteado em 05\/12\/2023.<\/li>\n<li>Nos \u00faltimos 12 meses foram realizados 290 sorteios e premiadas 718 pessoas que acertaram os 15 n\u00fameros da Lotofacil.<\/li>\n<li>Neste per\u00edodo a Lotofacil n\u00e3o teve acertadores em 54 oportunidades.<\/li>\n<\/ul>\n<\/ul>\n<h3>Hist\u00f3rico dos n\u00fameros sorteados neste concurso da Lotofacil<\/h3>\n<p>Nesta tabela voc\u00ea ir\u00e1 encontrar as seguintes informa\u00e7\u00f5es relativas aos sorteios da Lotofacil dos \u00faltimos 12 meses:<br \/>A quantidade de vezes que o n\u00famero foi sorteado na Lotofacil,<br \/>A quantidade de sorteios que este n\u00famero saiu e o concurso teve ganhador,<br \/>A data do \u00faltimo sorteio na Lotofacil desta dezena.<\/p>\n<table>\n<tr>\n<th>Dezena<\/th>\n<th>Total<\/th>\n<th>Premiada<\/th>\n<th>Data<\/th>\n<\/tr>\n<tr>\n<td>02<\/td>\n<td>179<\/td>\n<td>149<\/td>\n<td>03\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>03<\/td>\n<td>168<\/td>\n<td>138<\/td>\n<td>02\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>06<\/td>\n<td>178<\/td>\n<td>141<\/td>\n<td>05\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>07<\/td>\n<td>185<\/td>\n<td>152<\/td>\n<td>05\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>10<\/td>\n<td>181<\/td>\n<td>148<\/td>\n<td>05\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>12<\/td>\n<td>181<\/td>\n<td>144<\/td>\n<td>05\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>13<\/td>\n<td>170<\/td>\n<td>141<\/td>\n<td>05\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>15<\/td>\n<td>164<\/td>\n<td>134<\/td>\n<td>05\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>16<\/td>\n<td>153<\/td>\n<td>122<\/td>\n<td>05\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>18<\/td>\n<td>183<\/td>\n<td>150<\/td>\n<td>02\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>20<\/td>\n<td>200<\/td>\n<td>163<\/td>\n<td>05\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>21<\/td>\n<td>171<\/td>\n<td>132<\/td>\n<td>05\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>22<\/td>\n<td>165<\/td>\n<td>135<\/td>\n<td>02\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>23<\/td>\n<td>168<\/td>\n<td>138<\/td>\n<td>05\/02\/2024<\/td>\n<\/tr>\n<tr>\n<td>25<\/td>\n<td>182<\/td>\n<td>149<\/td>\n<td>05\/02\/2024<\/td>\n<\/tr>\n<\/table>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lotofacil 3023 &#8211; Resultado, rateio e ganhadores da Lotofacil 3023 sorteado em 06\/02\/2024.<\/p>\n","protected":false},"author":5,"featured_media":196331,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,357],"tags":[],"class_list":{"0":"post-241985","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-loto-facil","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/lotofacil-resultado.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/241985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=241985"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/241985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196331"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=241985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=241985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=241985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}