{"id":241540,"date":"2024-01-21T08:27:21","date_gmt":"2024-01-21T11:27:21","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/milionaria-resultado-do-concurso-114-sorteado-sabado-20-01-2024\/241540"},"modified":"2024-01-21T08:27:21","modified_gmt":"2024-01-21T11:27:21","slug":"milionaria-resultado-do-concurso-114-sorteado-sabado-20-01-2024","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/milionaria-resultado-do-concurso-114-sorteado-sabado-20-01-2024\/241540","title":{"rendered":"+Milionaria: Resultado do concurso 114 sorteado  S\u00e1bado 20\/01\/2024"},"content":{"rendered":"<p>Resultado da +Milionaria, concurso 114, realizado no  S\u00e1bado, dia 20\/01\/2024 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo.  A +Milionaria 114 n\u00e3o teve acertador do pr\u00eamio principal e a previs\u00e3o do pr\u00eamio para o pr\u00f3ximo sorteio, +Milionaria 115, \u00e9 de R$ 128.000.000,00. Com este resultado a +Milionaria  esta acumulada ha  114 sorteios<\/p>\n<p>Veja tamb\u00e9m: <\/p>\n<h2>N\u00fameros Sorteados +Milionaria 114<\/h2>\n<table style=\"margin-bottom: 10px;\">\n<tr>\n<td><span class=\"numberCircleMilionaria\">03<\/span><\/td>\n<td><span class=\"numberCircleMilionaria\">11<\/span><\/td>\n<td><span class=\"numberCircleMilionaria\">20<\/span><\/td>\n<td><span class=\"numberCircleMilionaria\">36<\/span><\/td>\n<td><span class=\"numberCircleMilionaria\">47<\/span><\/td>\n<td><span class=\"numberCircleMilionaria\">50<\/span><\/td>\n<\/tr>\n<\/table >\n<h4> Trevos<\/h4>\n<table style=\"width: 200px; margin-bottom: 10px;\">\n<tr>\n<td><span class=\"numberCircleMilionaria\">3<\/span><\/td>\n<td><span class=\"numberCircleMilionaria\">6<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Premia\u00e7\u00e3o +Milionaria 114<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td>6 + (2)<\/td>\n<td>0<\/td>\n<td>0,00<\/td>\n<\/tr>\n<tr>\n<td>6 + (1 ou 0)<\/td>\n<td>0<\/td>\n<td>0,00<\/td>\n<\/tr>\n<tr>\n<td>5 + (2)<\/td>\n<td>2<\/td>\n<td>273.678,40<\/td>\n<\/tr>\n<tr>\n<td>5 + (1 ou 0)<\/td>\n<td>37<\/td>\n<td>6.574,86<\/td>\n<\/tr>\n<tr>\n<td>4 + (2)<\/td>\n<td>172<\/td>\n<td>1.515,38<\/td>\n<\/tr>\n<tr>\n<td>4 + (1)<\/td>\n<td>2.382<\/td>\n<td>109,42<\/td>\n<\/tr>\n<tr>\n<td>3 + (2) <\/td>\n<td>2.923<\/td>\n<td>50,00<\/td>\n<\/tr>\n<tr>\n<td>3 + (1)<\/td>\n<td>22.346<\/td>\n<td>24,00<\/td>\n<\/tr>\n<tr>\n<td>2 + (2)<\/td>\n<td>23.525<\/td>\n<td>12,00<\/td>\n<\/tr>\n<tr>\n<td>2 + (1)<\/td>\n<td>174.543<\/td>\n<td>6,00<\/td>\n<\/tr>\n<p>><\/table>\n<h2>Total de Apostas realizadas<\/h2>\n<p>No concurso 114 da +Milionaria foi realizado um total de 2.572.336 apostas.<\/p>\n<h2>Pr\u00f3ximo Sorteio da +Milionaria <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Quarta-feira 24\/01\/2024, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 128.000.000,00.<\/p>\n<h3>\u00daltimos Resultados da +Milionaria<\/h3>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/milionaria-resultado-do-concurso-113-sorteado-quarta-feira-17-01-2024\/241441\">+Milionaria 113<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/milionaria-resultado-do-concurso-112-sorteado-sabado-13-01-2024\/241315\">+Milionaria 112<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/milionaria-resultado-do-concurso-111-sorteado-quarta-feira-10-01-2024\/241242\">+Milionaria 111<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/milionaria-resultado-do-concurso-110-sorteado-sabado-06-01-2024\/241093\">+Milionaria 110<\/a><\/li>\n<p><\/lu><\/p>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>+Milionaria 114 &#8211; Resultado, rateio e ganhadores da +Milionaria 114 sorteado em 20\/01\/2024.<\/p>\n","protected":false},"author":5,"featured_media":224747,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2283,335],"tags":[],"class_list":{"0":"post-241540","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-milionaria","8":"category-loteria","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/milionaria_cef.png","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/241540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=241540"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/241540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/224747"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=241540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=241540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=241540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}