{"id":241287,"date":"2024-01-12T04:01:14","date_gmt":"2024-01-12T07:01:14","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6338-sorteado-quinta-feira-11-01-2024\/241287"},"modified":"2024-01-12T04:01:14","modified_gmt":"2024-01-12T07:01:14","slug":"quina-resultado-do-concurso-6338-sorteado-quinta-feira-11-01-2024","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6338-sorteado-quinta-feira-11-01-2024\/241287","title":{"rendered":"Quina: Resultado do concurso 6338 sorteado  Quinta-feira 11\/01\/2024"},"content":{"rendered":"<p>Resultado da Quina, concurso 6338, realizado na  Quinta-feira, dia 11\/01\/2024 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo.  A Quina 6338 n\u00e3o teve acertador do pr\u00eamio principal e a previs\u00e3o do pr\u00eamio para o pr\u00f3ximo sorteio, Quina 6339, \u00e9 de R$ 17.500.000,00. Com este resultado a Quina  esta acumulada ha  6 sorteios<\/p>\n<p>Veja tamb\u00e9m: <a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2020\/todos-os-resultados-da-quina\/199388\"> Todos os resultados da Quina<\/a><\/p>\n<h2>N\u00fameros Sorteados Quina 6338<\/h2>\n<table>\n<tr>\n<td><span class=\"numberCircleQuina\">07<\/span><\/td>\n<td><span class=\"numberCircleQuina\">10<\/span><\/td>\n<td><span class=\"numberCircleQuina\">21<\/span><\/td>\n<td><span class=\"numberCircleQuina\">49<\/span><\/td>\n<td><span class=\"numberCircleQuina\">75<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Premia\u00e7\u00e3o Quina 6338<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad.<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td> 0<\/td>\n<td>0,00<\/td>\n<\/tr>\n<tr>\n<td>  4 <\/td>\n<td>122<\/td>\n<td>6.572,63<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td>10.026<\/td>\n<td>76,16<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td>226.487<\/td>\n<td>3,37<\/td>\n<\/tr>\n<\/table>\n<h2>Total de Apostas realizadas<\/h2>\n<p>No concurso 6338 da Quina foi realizado um total de 7.046.613 apostas.<\/p>\n<h2>Pr\u00f3ximo Sorteio da Quina <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Sexta-feira 12\/01\/2024, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 17.500.000,00.<\/p>\n<h3>\u00daltimos Resultados da Quina<\/h3>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6337-sorteado-quarta-feira-10-01-2024\/241250\">Quina 6337<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6336-sorteado-terca-feira-09-01-2024\/241201\">Quina 6336<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6335-sorteado-segunda-feira-08-01-2024\/241172\">Quina 6335<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2024\/quina-resultado-do-concurso-6334-sorteado-sabado-06-01-2024\/241097\">Quina 6334<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Resumo do sorteio da Quina 6338<\/h2>\n<ul>\n<li>Dos n\u00fameros sorteados neste concurso da Quina o que mais saiu nos \u00faltimos 12 meses foi o 49, sorteado 21 vezes.<\/li>\n<li>O que menos saiu foi o n\u00famero 07, sorteado apenas 14 vezes.<\/li>\n<li>Das 80 dezenas, a que est\u00e1 h\u00e1 mais tempo sem ser sorteada \u00e9 a 20 que n\u00e3o sai tem 55  dias.<\/li>\n<li>O pr\u00eamio de maior valor pago neste per\u00edodo, sem contar o da Quina de S\u00e3o Jo\u00e3o, foi de R$ 36.290.017,10 correspondente ao concurso 6196, sorteado em 22\/07\/2023.<\/li>\n<li>Nos \u00faltimos 12 meses foram realizados 289 sorteios e premiadas 67 pessoas que acertaram os 5 n\u00fameros da Quina.<\/li>\n<li>Neste per\u00edodo a Quina n\u00e3o teve acertadores em 239 oportunidades.<\/li>\n<\/ul>\n<\/ul>\n<h3>Hist\u00f3rico dos n\u00fameros sorteados neste concurso da Quina<\/h3>\n<p>Nesta tabela voc\u00ea ir\u00e1 encontrar as seguintes informa\u00e7\u00f5es relativas aos sorteios da Quina dos \u00faltimos 12 meses:<br \/>A quantidade de vezes que o n\u00famero foi sorteado na Quina,<br \/>A quantidade de sorteios que este n\u00famero saiu e o concurso teve ganhador,<br \/>A data do \u00faltimo sorteio na Quina desta dezena.<\/p>\n<table>\n<tr>\n<th>Dezena<\/th>\n<th>Total<\/th>\n<th>Premiada<\/th>\n<th>Data<\/th>\n<\/tr>\n<tr>\n<td>07<\/td>\n<td>14<\/td>\n<td>5<\/td>\n<td>07\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>10<\/td>\n<td>16<\/td>\n<td>2<\/td>\n<td>22\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>21<\/td>\n<td>20<\/td>\n<td>5<\/td>\n<td>21\/12\/2023<\/td>\n<\/tr>\n<tr>\n<td>49<\/td>\n<td>21<\/td>\n<td>2<\/td>\n<td>09\/01\/2024<\/td>\n<\/tr>\n<tr>\n<td>75<\/td>\n<td>14<\/td>\n<td>2<\/td>\n<td>15\/12\/2023<\/td>\n<\/tr>\n<\/table>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quina 6338 &#8211; Resultado, rateio e ganhadores da Quina 6338 sorteado em 11\/01\/2024.<\/p>\n","protected":false},"author":5,"featured_media":196332,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,358],"tags":[],"class_list":["post-241287","post","type-post","status-publish","format-standard","has-post-thumbnail","category-loteria","category-quina","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-quina-1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/241287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=241287"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/241287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196332"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=241287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=241287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=241287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}