{"id":239809,"date":"2023-11-25T20:14:10","date_gmt":"2023-11-25T23:14:10","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2023\/quina-resultado-do-concurso-6300-sorteado-sabado-25-11-2023\/239809"},"modified":"2023-11-26T04:44:38","modified_gmt":"2023-11-26T07:44:38","slug":"quina-resultado-do-concurso-6300-sorteado-sabado-25-11-2023","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2023\/quina-resultado-do-concurso-6300-sorteado-sabado-25-11-2023\/239809","title":{"rendered":"Quina: Resultado do concurso 6300 sorteado  S\u00e1bado 25\/11\/2023"},"content":{"rendered":"<p>Resultado da Quina, concurso 6300, realizado no  S\u00e1bado, dia 25\/11\/2023 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo.  A Quina 6300 teve 1 acertador dos  n\u00fameros. O ganhador \u00e9 da cidade de Mat\u00e3o (SP) e receber\u00e1 um pr\u00eamio de R$ 1.372.477,83. A previs\u00e3o do pr\u00eamio para o pr\u00f3ximo sorteio, Quina 6301,  \u00e9 de R$ 700.000,00.<\/p>\n<p>Veja tamb\u00e9m: <a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2020\/todos-os-resultados-da-quina\/199388\"> Todos os resultados da Quina<\/a><\/p>\n<h2>N\u00fameros Sorteados Quina 6300<\/h2>\n<table>\n<tr>\n<td><span class=\"numberCircleQuina\">03<\/span><\/td>\n<td><span class=\"numberCircleQuina\">06<\/span><\/td>\n<td><span class=\"numberCircleQuina\">09<\/span><\/td>\n<td><span class=\"numberCircleQuina\">29<\/span><\/td>\n<td><span class=\"numberCircleQuina\">76<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Premia\u00e7\u00e3o Quina 6300<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad.<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td> 1<\/td>\n<td>1.372.477,83<\/td>\n<\/tr>\n<tr>\n<td>  4 <\/td>\n<td>125<\/td>\n<td>2.600,12<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td>6.122<\/td>\n<td>50,56<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td>101.931<\/td>\n<td>3,03<\/td>\n<\/tr>\n<\/table>\n<h2>Cidades Ganhadoras da Quina 6300<\/h2>\n<p>As apostas vencedoras foram realizadas nas seguintes cidades:<\/p>\n<table>\n<tr>\n<th>Cidade<\/th>\n<th>UF<\/th>\n<th>Ganhadores<\/th>\n<\/tr>\n<tr>\n<td>Mat\u00e3o<\/td>\n<td>SP<\/td>\n<td>1<\/td>\n<\/tr>\n<\/table>\n<h2>Total de Apostas realizadas<\/h2>\n<p>No concurso 6300 da Quina foi realizado um total de 2.856.172 apostas.<\/p>\n<h2>Pr\u00f3ximo Sorteio da Quina <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Segunda-feira 27\/11\/2023, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 700.000,00.<\/p>\n<h3>\u00daltimos Resultados da Quina<\/h3>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2023\/quina-resultado-do-concurso-6300-sorteado-sabado-25-11-2023\/239809\">Quina 6300<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2023\/quina-resultado-do-concurso-6299-sorteado-sexta-feira-24-11-2023\/239776\">Quina 6299<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2023\/quina-resultado-do-concurso-6298-sorteado-quinta-feira-23-11-2023\/239740\">Quina 6298<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2023\/quina-resultado-do-concurso-6297-sorteado-quarta-feira-22-11-2023\/239699\">Quina 6297<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2023\/quina-resultado-do-concurso-6296-sorteado-terca-feira-21-11-2023\/239654\">Quina 6296<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Resumo do sorteio da Quina 6300<\/h2>\n<ul>\n<li>Dos n\u00fameros sorteados neste concurso da Quina o que mais saiu nos \u00faltimos 12 meses foi o 29, sorteado 25 vezes.<\/li>\n<li>O que menos saiu foi o n\u00famero 03, sorteado apenas 16 vezes.<\/li>\n<li>Das 80 dezenas, a que est\u00e1 h\u00e1 mais tempo sem ser sorteada \u00e9 a 65 que n\u00e3o sai tem 169  dias.<\/li>\n<li>O pr\u00eamio de maior valor pago neste per\u00edodo, sem contar o da Quina de S\u00e3o Jo\u00e3o, foi de R$ 36.290.017,10 correspondente ao concurso 6196, sorteado em 22\/07\/2023.<\/li>\n<li>Nos \u00faltimos 12 meses foram realizados 291 sorteios e premiadas 71 pessoas que acertaram os 5 n\u00fameros da Quina.<\/li>\n<li>Neste per\u00edodo a Quina n\u00e3o teve acertadores em 236 oportunidades.<\/li>\n<\/ul>\n<\/ul>\n<h3>Hist\u00f3rico dos n\u00fameros sorteados neste concurso da Quina<\/h3>\n<p>Nesta tabela voc\u00ea ir\u00e1 encontrar as seguintes informa\u00e7\u00f5es relativas aos sorteios da Quina dos \u00faltimos 12 meses:<br \/>A quantidade de vezes que o n\u00famero foi sorteado na Quina,<br \/>A quantidade de sorteios que este n\u00famero saiu e o concurso teve ganhador,<br \/>A data do \u00faltimo sorteio na Quina desta dezena.<\/p>\n<table>\n<tr>\n<th>Dezena<\/th>\n<th>Total<\/th>\n<th>Premiada<\/th>\n<th>Data<\/th>\n<\/tr>\n<tr>\n<td>03<\/td>\n<td>16<\/td>\n<td>3<\/td>\n<td>21\/10\/2023<\/td>\n<\/tr>\n<tr>\n<td>06<\/td>\n<td>19<\/td>\n<td>7<\/td>\n<td>14\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>09<\/td>\n<td>18<\/td>\n<td>3<\/td>\n<td>21\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>29<\/td>\n<td>25<\/td>\n<td>5<\/td>\n<td>17\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>76<\/td>\n<td>19<\/td>\n<td>2<\/td>\n<td>03\/11\/2023<\/td>\n<\/tr>\n<\/table>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quina 6300 &#8211; Resultado, rateio e ganhadores da Quina 6300 sorteado em 25\/11\/2023.<\/p>\n","protected":false},"author":5,"featured_media":196332,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,358],"tags":[],"class_list":["post-239809","post","type-post","status-publish","format-standard","has-post-thumbnail","category-loteria","category-quina","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-quina-1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/239809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=239809"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/239809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196332"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=239809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=239809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=239809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}