{"id":239210,"date":"2023-11-08T20:28:02","date_gmt":"2023-11-08T23:28:02","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2023\/lotofacil-resultado-do-concurso-2949-sorteado-quarta-feira-08-11-2023\/239210"},"modified":"2023-11-09T08:16:20","modified_gmt":"2023-11-09T11:16:20","slug":"lotofacil-resultado-do-concurso-2949-sorteado-quarta-feira-08-11-2023","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2023\/lotofacil-resultado-do-concurso-2949-sorteado-quarta-feira-08-11-2023\/239210","title":{"rendered":"Lotofacil: Resultado do concurso 2949 sorteado  Quarta-feira 08\/11\/2023"},"content":{"rendered":"<p>Resultado da Lotofacil, concurso 2949, realizado na  Quarta-feira, dia 08\/11\/2023 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo.  A Lotofacil 2949 teve 2 acertadores dos  n\u00fameros. Os ganhadores receber\u00e3o, cada um, o pr\u00eamio de R$ 908.982,18. A previs\u00e3o do pr\u00eamio para o pr\u00f3ximo sorteio, Lotofacil 2950, \u00e9 de R$ 5.000.000,00.<\/p>\n<p>Veja tamb\u00e9m: <a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2020\/todos-os-resultados-da-lotofacil\/199385\"> Todos os resultados da Lotofacil<\/a><\/p>\n<h2>N\u00fameros Sorteados Lotofacil 2949<\/h2>\n<table>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">06<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">07<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">09<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">12<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">13<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">14<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">15<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">16<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">17<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">18<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">20<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">21<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">22<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">23<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">24<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Premia\u00e7\u00e3o Lotofacil 2949<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad.<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td>15<\/td>\n<td>2<\/td>\n<td align=right>908.982,18<\/td>\n<\/tr>\n<tr>\n<td>14 <\/td>\n<td>211<\/td>\n<td align=right> 1.806,57<\/td>\n<\/tr>\n<tr>\n<td> 13 <\/td>\n<td>7.508<\/td>\n<td align=right> 30,00<\/td>\n<\/tr>\n<tr>\n<td> 12 <\/td>\n<td>102.837<\/td>\n<td align=right> 12,00<\/td>\n<\/tr>\n<tr>\n<td> 11 <\/td>\n<td>537.895<\/td>\n<td align=right> 6,00<\/td>\n<\/tr>\n<\/table>\n<h2>Cidades Ganhadoras da Lotofacil 2949<\/h2>\n<p>As apostas vencedoras foram realizadas nas seguintes cidades:<\/p>\n<table>\n<tr>\n<th>Cidade<\/th>\n<th>UF<\/th>\n<th>Ganhadores<\/th>\n<\/tr>\n<tr>\n<td>Manaus<\/td>\n<td>AM<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>Taio<\/td>\n<td>SC<\/td>\n<td>1<\/td>\n<\/tr>\n<\/table>\n<h2>Total de Apostas realizadas<\/h2>\n<p>No concurso 2949 da Lotofacil foi realizado um total de 6.824.692 apostas.<\/p>\n<h2>Pr\u00f3ximo Sorteio da Lotofacil <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Quinta-feira 09\/11\/2023, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 5.000.000,00.<\/p>\n<h3>\u00daltimos Resultados da Lotofacil<\/h3>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2023\/lotofacil-resultado-do-concurso-2949-sorteado-quarta-feira-08-11-2023\/239210\">Lotofacil 2949<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2023\/lotofacil-resultado-do-concurso-2948-sorteado-terca-feira-07-11-2023\/239161\">Lotofacil 2948<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2023\/lotofacil-resultado-do-concurso-2947-sorteado-segunda-feira-06-11-2023\/239117\">Lotofacil 2947<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2023\/lotofacil-resultado-do-concurso-2946-sorteado-sabado-04-11-2023\/239073\">Lotofacil 2946<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2023\/lotofacil-resultado-do-concurso-2945-sorteado-sexta-feira-03-11-2023\/239025\">Lotofacil 2945<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Resumo do sorteio da Lotofacil 2949<\/h2>\n<ul>\n<li>Dos n\u00fameros sorteados neste concurso da Lotofacil o que mais saiu nos \u00faltimos 12 meses foi o 20, sorteado 194 vezes.<\/li>\n<li>O que menos saiu foi o n\u00famero 16, sorteado apenas 158 vezes.<\/li>\n<li>Das 25 dezenas, a que est\u00e1 h\u00e1 mais tempo sem ser sorteada \u00e9 a 19 que n\u00e3o sai tem 4  dias.<\/li>\n<li>O pr\u00eamio de maior valor pago neste per\u00edodo, sem contar o da Lotofacil da Independ\u00eancia, foi de R$ 11.480.010,08 correspondente ao concurso 2830, sorteado em 05\/06\/2023.<\/li>\n<li>Nos \u00faltimos 12 meses foram realizados 290 sorteios e premiadas 746 pessoas que acertaram os 15 n\u00fameros da Lotofacil.<\/li>\n<li>Neste per\u00edodo a Lotofacil n\u00e3o teve acertadores em 47 oportunidades.<\/li>\n<\/ul>\n<\/ul>\n<h3>Hist\u00f3rico dos n\u00fameros sorteados neste concurso da Lotofacil<\/h3>\n<p>Nesta tabela voc\u00ea ir\u00e1 encontrar as seguintes informa\u00e7\u00f5es relativas aos sorteios da Lotofacil dos \u00faltimos 12 meses:<br \/>A quantidade de vezes que o n\u00famero foi sorteado na Lotofacil,<br \/>A quantidade de sorteios que este n\u00famero saiu e o concurso teve ganhador,<br \/>A data do \u00faltimo sorteio na Lotofacil desta dezena.<\/p>\n<table>\n<tr>\n<th>Dezena<\/th>\n<th>Total<\/th>\n<th>Premiada<\/th>\n<th>Data<\/th>\n<\/tr>\n<tr>\n<td>06<\/td>\n<td>177<\/td>\n<td>147<\/td>\n<td>06\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>07<\/td>\n<td>183<\/td>\n<td>152<\/td>\n<td>07\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>09<\/td>\n<td>182<\/td>\n<td>152<\/td>\n<td>07\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>12<\/td>\n<td>174<\/td>\n<td>141<\/td>\n<td>07\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>13<\/td>\n<td>172<\/td>\n<td>151<\/td>\n<td>06\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>14<\/td>\n<td>168<\/td>\n<td>136<\/td>\n<td>04\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>15<\/td>\n<td>167<\/td>\n<td>140<\/td>\n<td>06\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>16<\/td>\n<td>158<\/td>\n<td>130<\/td>\n<td>07\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>17<\/td>\n<td>162<\/td>\n<td>132<\/td>\n<td>03\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>18<\/td>\n<td>172<\/td>\n<td>147<\/td>\n<td>07\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>20<\/td>\n<td>194<\/td>\n<td>163<\/td>\n<td>06\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>21<\/td>\n<td>178<\/td>\n<td>147<\/td>\n<td>07\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>22<\/td>\n<td>177<\/td>\n<td>150<\/td>\n<td>06\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>23<\/td>\n<td>165<\/td>\n<td>139<\/td>\n<td>07\/11\/2023<\/td>\n<\/tr>\n<tr>\n<td>24<\/td>\n<td>177<\/td>\n<td>150<\/td>\n<td>07\/11\/2023<\/td>\n<\/tr>\n<\/table>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lotofacil 2949 &#8211; Resultado, rateio e ganhadores da Lotofacil 2949 sorteado em 08\/11\/2023.<\/p>\n","protected":false},"author":5,"featured_media":196331,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[335,357],"tags":[],"class_list":{"0":"post-239210","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-loto-facil","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/lotofacil-resultado.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/239210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=239210"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/239210\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196331"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=239210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=239210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=239210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}