{"id":237098,"date":"2023-09-14T13:58:23","date_gmt":"2023-09-14T16:58:23","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=237098"},"modified":"2023-09-14T13:58:23","modified_gmt":"2023-09-14T16:58:23","slug":"resumo-os-dez-mandamentos-15-09-lemuel-conta-a-leila-que-baraquias-e-seu-filho","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2023\/resumo-os-dez-mandamentos-15-09-lemuel-conta-a-leila-que-baraquias-e-seu-filho\/237098","title":{"rendered":"Resumo \u201cOs Dez Mandamentos\u201d 15\/09: Lemuel conta a Leila que Baraquias \u00e9 seu filho"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-230999\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_resumo_novela.jpeg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_resumo_novela.jpeg 1280w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_resumo_novela-250x140.jpeg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_resumo_novela-400x225.jpeg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_resumo_novela-768x432.jpeg 768w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_resumo_novela-150x84.jpeg 150w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p><strong><em>Resumo da novela \u201cOs Dez Mandamentos\u201d<\/em><\/strong> em 15\/09: no cap\u00edtulo 240(*) da novela, Mois\u00e9s fica emocionado ao orar a Deus de forma fervorosa. Cor\u00e1 diz que Mois\u00e9s cansou o povo e que, por precisarem de um novo l\u00edder, ele \u00e9 o mais apto, ao se gabar para Assir e Elcana. Ada fica furiosa quando discute com Z\u00edpora por ela n\u00e3o aprovar o que o marido de Ada tem feito, indo contra Mois\u00e9s. Mois\u00e9s admite j\u00e1 ter entregue nas m\u00e3os de Deus pois a batalha n\u00e3o \u00e9 mais dele, em conversa com Z\u00edpora. Para mostrar quem s\u00e3o os Seus escolhidos, Deus ganha ora\u00e7\u00e3o de Mois\u00e9s depois dele discursar. Se achando vitoriosos, Cor\u00e1 e Abir\u00e3o sorriem confiantes que Deus est\u00e1 do lado deles. O povo deve se afastar da tenda de Cor\u00e1 por ordem de Deus a Mois\u00e9s. Dat\u00e3 ouve para desistir da oposi\u00e7\u00e3o em s\u00faplica de Safira. O povo se divide na frente de Ar\u00e3o e Mois\u00e9s.    <\/p>\n<p>Mois\u00e9s diz que todos v\u00e3o saber que o Senhor \u00e9 desprezado se a terra se abrir e engolir Cor\u00e1, Dat\u00e3 e Abir\u00e3o e tudo que eles possuem. Apavoradas, correm as pessoas quando objetos caem e o ch\u00e3o come\u00e7a a tremer. Aos p\u00e9s de Cor\u00e1, Dat\u00e3 e Abir\u00e3o chega uma fenda enorme como se tivesse sendo rasgada. Agarrado a Bina, cai, gritando desesperado, Cor\u00e1 ap\u00f3s todos congelarem de medo. Em meio a gritos de p\u00e2nico, os demais s\u00e3o engolidos pela terra. Come\u00e7a a se agitar e crescer a nuvem de fogo que pairava sobre o tabern\u00e1culo. Os revoltosos tentam correr inutilmente e acabam mortos. Bet\u00e2nia reencontra a filha ao chegar desesperada. Mois\u00e9s consola Z\u00edpora pela perda de sua irm\u00e3. <\/p>\n<p>Oren beija com paix\u00e3o Adira quando ela revela sentir mais que apenas gratid\u00e3o. Deus diz que ir\u00e1 cessar as murmura\u00e7\u00f5es dos filhos de Israel ao chamar por Mois\u00e9s e pedir para ele falar com os l\u00edderes das doze tribos. Ar\u00e3o fica emocionado quando Mois\u00e9s lhe mostra o milagre de Deus. Ilan \u00e9 cuidado de forma orgulhosa por Safira. Ela \u00e9 pedida, sem voltas, em casamento por Eldade, que chega tenso. Se declaram Josu\u00e9 e Ana. Mortos est\u00e3o Miri\u00e3 e Hur. As crian\u00e7as se tornam adultos e formam as pr\u00f3prias fam\u00edlias, ap\u00f3s 38 anos. J\u00e1 com filhos, os filhos de Simut e Jerusa s\u00e3o olhados felizes pelos pais. Eli e Rebecca est\u00e3o com as filhas de Abigail e Zelofeade e com seus pais, Deborah e Bezalel. <\/p>\n<p>Natan encontra Z\u00edpora e Mois\u00e9s depois de muitos anos. Em Hesbom, em uma barraca pr\u00f3spera est\u00e3o Eva e os pais, Jair e Talita. Ap\u00f3s passar mal, desmaia Lemuel. Cosby tem seu retorno ao pal\u00e1cio negado por Balaque ap\u00f3s pedido de Bet\u00e2nia. Jaque, Jerusa e Damarina se espantam quando Sara conta que Adira est\u00e1 em Hesbom. \u00c0 beira da morte, Lemuel conta a Leila que Baraquias \u00e9 seu filho. Ana \u00e9 lembrada por seus momentos ao lado de Josu\u00e9 por ele. Os ossos de Jetro ser\u00e3o enterrados em Midi\u00e3, avisa Mois\u00e9s. Adira diz que n\u00e3o vai desistir de procurar por Haya e Abner em conversa com Oren. Todos os filhos de Balaque ca\u00edram doentes fica sabendo Elda. As palavras de Bala\u00e3o est\u00e3o se cumprindo afirma o rei depois de saber o que Elda lhe contou. Para tomarem conta do acampamento, ficam Ar\u00e3o e Josu\u00e9.<\/p>\n<p>(*) edi\u00e7\u00e3o das novelas da Record, \u201cOs Dez Mandamentos\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Sinopse \u201cOs Dez Mandamentos\u201d: Mois\u00e9s um dia est\u00e1 a pastorear um rebanho quando recebe um chamado de Deus e o manda voltar ao Egito para que junto com seu irm\u00e3o Ar\u00e3o liberte todo o povo hebreu da escravid\u00e3o. Ao voltar para o Egito, Mois\u00e9s tem que enfrentar aquele que um dia considerou como um irm\u00e3o e agora se tornar\u00e1 seu pior inimigo. Somente ap\u00f3s as dez pragas do Egito Rams\u00e9s liberta o povo.<\/p>\n<p>Mas acaba voltando atr\u00e1s e decide persegui-los atrav\u00e9s do deserto. \u00c9 ent\u00e3o que Deus, em uma das cenas mais grandiosas da novela, abre o Mar Vermelho, deixando o povo hebreu passar, e depois o fecha matando o ex\u00e9rcito eg\u00edpcio que os persegue. No deserto Deus revela a Mois\u00e9s os Dez Mandamentos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo da novela \u201cOs Dez Mandamentos\u201d em 15\/09: no cap\u00edtulo 240(*) da novela, Mois\u00e9s fica emocionado ao orar a Deus de forma fervorosa. Cor\u00e1 diz que Mois\u00e9s cansou o povo e que, por precisarem de um novo l\u00edder, ele \u00e9 o mais apto, ao se gabar para Assir e Elcana. Ada fica furiosa quando discute [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":230998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,424,371,2025,343],"tags":[441],"class_list":{"0":"post-237098","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-os-dez-mandamentos","9":"category-rede-record","10":"category-resumo","11":"category-televisao","12":"tag-resumo-do-dia","13":"entry","14":"gs-1","15":"gs-odd","16":"gs-even","17":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos.jpeg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/237098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=237098"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/237098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/230998"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=237098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=237098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=237098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}