{"id":236624,"date":"2023-08-31T16:45:06","date_gmt":"2023-08-31T19:45:06","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=236624"},"modified":"2023-08-31T16:45:06","modified_gmt":"2023-08-31T19:45:06","slug":"resumo-os-dez-mandamentos-01-09-rishon-compra-leila-e-apresenta-a-dorcas","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2023\/resumo-os-dez-mandamentos-01-09-rishon-compra-leila-e-apresenta-a-dorcas\/236624","title":{"rendered":"Resumo \u201cOs Dez Mandamentos\u201d 01\/09: Rishon compra Leila e apresenta a Dorcas"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-230999\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_resumo_novela.jpeg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_resumo_novela.jpeg 1280w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_resumo_novela-250x140.jpeg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_resumo_novela-400x225.jpeg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_resumo_novela-768x432.jpeg 768w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_resumo_novela-150x84.jpeg 150w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p><strong><em>Resumo da novela \u201cOs Dez Mandamentos\u201d<\/em><\/strong> em 01\/09: no cap\u00edtulo 230(*) da novela, Cor\u00e1 conversa com Mois\u00e9s sobre a decis\u00e3o de deixar Z\u00edpora acompanhar Miri\u00e3. Uma semana depois, Cor\u00e1 avalia Bala\u00e3o e comprova que ele n\u00e3o tinha lepra. Bala\u00e3o pede a Cor\u00e1 para ir junto ver o estado de Miri\u00e3. Caravana dos mercadores chega a Hesbom. Leila, capturada, est\u00e1 no cavalo do l\u00edder. Ao perguntar o que era o local, o l\u00edder pede sil\u00eancio e a trata como escrava. Miri\u00e3 est\u00e1 fraca, com olhos vermelhos e pele danificada. Cor\u00e1 diz que ela n\u00e3o poder\u00e1 retornar a viver entre eles. Z\u00edpora e Miri\u00e3 rebatem. Uma luz vem do c\u00e9u, envolve Miri\u00e3, que fica completamente curada. Miri\u00e3 agradece e abra\u00e7a Z\u00edpora, emocionada.<\/p>\n<p>Z\u00edpora pergunta a Cor\u00e1 se ela e a irm\u00e3 podem voltar. Ar\u00e3o diz que precisa confirmar a cura primeiro. Bala\u00e3o diz a Cor\u00e1 que est\u00e1 surpreso com o milagre ocorrido. Na rua do com\u00e9rcio, Rishon e Jair conversam sobre a chegada de novas escravas e Jair demonstra interesse. Seon e Oren falam do interesse de Oren em Adira e da chegada dos hebreus. Miri\u00e3 e Z\u00edpora se encontram com Cor\u00e1 e Ar\u00e3o e eles avisam que elas podem retornar ao acampamento depois de terminar o procedimento de purifica\u00e7\u00e3o. Z\u00edpora e Miri\u00e3 entram no rio para se banhar e saem. O leil\u00e3o pelas escravas come\u00e7a, Rishon demonstra interesse em Leila. Z\u00edpora e Miri\u00e3 chegam ao acampamento, Ar\u00e3o realiza o processo de purifica\u00e7\u00e3o e Miri\u00e3 \u00e9 abra\u00e7ada por todos. Balaque, Elda e Zur falam sobre a chegada dos hebreus e o plano de Cor\u00e1 roubar a lideran\u00e7a de Mois\u00e9s. Cor\u00e1 sai com Assir e Elcana. Mois\u00e9s convida Miri\u00e3 e Hur para morarem junto com ele e eles aceitam. <\/p>\n<p>O mercador mostra que Leila est\u00e1 gr\u00e1vida e inicia a sua venda. Rishon oferece dinheiro e encontra um concorrente para a compra. Cor\u00e1 diz a Dat\u00e3 e Abir\u00e3o que Bala\u00e3o estava presente quando Miri\u00e3 foi curada e ressalta que ser\u00e1 l\u00edder dos hebreus em pouco tempo. Bina e Libna conversam sobre a rela\u00e7\u00e3o de Abir\u00e3o e Tales e Bina diz que h\u00e1 necessidade de arrumar um pretendente a Dum\u00e1. Tales conversa com Yarin e diz que estava com ci\u00fames e nunca pretendeu se matar de verdade. Z\u00edpora conta a Gerson, Eliezer e Mois\u00e9s sobre a ovelha que estava na caverna e Mois\u00e9s fala da import\u00e2ncia de estar atento aos sinais de Deus. Miri\u00e3 e Hur chegam \u00e0 tenda de Mois\u00e9s, se desculpam e se abra\u00e7am. Abigail, Bezalel, Zelofeade e Deborah falam sobre o tempo que Miri\u00e3 ficou afastada. Abigail e Bezalel demonstram-se preocupados com Leila. Simut conversa com Aoliabe e Eldade e diz que est\u00e1 preocupado com Gahiji no deserto. <\/p>\n<p>Rishon chega com Leila e apresenta a Dorcas. Leila pede ajuda a Dorcas, que diz que n\u00e3o deixar\u00e1 ningu\u00e9m encostar nela enquanto estiver gr\u00e1vida. Zur presenteia Bet\u00e2nia com uma pulseira, que resiste no in\u00edcio, mas aceita a joia. Balaque conversa com Elda e pede para que ela avise Bet\u00e2nia para comparecer a seus aposentos assim que chegar. Gerson, Eliezer e Fineas brincam na tenda e depois se retiram para dormir. Miri\u00e3 e Ar\u00e3o relembram quando Mois\u00e9s estava afastando quando era crian\u00e7a. Dorcas diz a Rishon para respeitar Leila, Rishon responde e diz que ela deve trabalhar no dia seguinte. Leila conversa com Talita e descobre que Adira era a antiga escrava e que agora estava morando com Oren. <\/p>\n<p>Oren conversa com Adira, diz que a ama e os dois se beijam. Calebe diz a Noemi que est\u00e1 ansioso com o casamento deles. Quenaz diz a Yarin que est\u00e1 feliz com o afastamento de Tales, os dois fantasiam sobre o casamento. Adira diz a Oren que n\u00e3o pode gostar dele e que deseja voltar \u00e0 sua fam\u00edlia. Leila pede que Talita a leve para ver Adira. Balaque e Bet\u00e2nia est\u00e3o nos aposentos do Rei. Bet\u00e2nia serve diversas ta\u00e7as de vinho a Balaque, que cai em sono. Zur levanta sem camisa da cama, pede desculpas a Tanya por ter falhado. Tanya sai irritada dos aposentos. Abner conversa com Haya, que diz que sente falta da m\u00e3e. Assir e Elcana entram tensos na tenda para falar com Mois\u00e9s. Cor\u00e1 discursa na frente dos hebreus e n\u00e3o percebe a presen\u00e7a de Mois\u00e9s e Josu\u00e9. Os hebreus comentam intensamente o que foi dito por Cor\u00e1, que v\u00ea Mois\u00e9s e Josu\u00e9 e fica assustado.<\/p>\n<p>(*) edi\u00e7\u00e3o das novelas da Record, \u201cOs Dez Mandamentos\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n<p>Sinopse \u201cOs Dez Mandamentos\u201d: Mois\u00e9s um dia est\u00e1 a pastorear um rebanho quando recebe um chamado de Deus e o manda voltar ao Egito para que junto com seu irm\u00e3o Ar\u00e3o liberte todo o povo hebreu da escravid\u00e3o. Ao voltar para o Egito, Mois\u00e9s tem que enfrentar aquele que um dia considerou como um irm\u00e3o e agora se tornar\u00e1 seu pior inimigo. Somente ap\u00f3s as dez pragas do Egito Rams\u00e9s liberta o povo.<\/p>\n<p>Mas acaba voltando atr\u00e1s e decide persegui-los atrav\u00e9s do deserto. \u00c9 ent\u00e3o que Deus, em uma das cenas mais grandiosas da novela, abre o Mar Vermelho, deixando o povo hebreu passar, e depois o fecha matando o ex\u00e9rcito eg\u00edpcio que os persegue. No deserto Deus revela a Mois\u00e9s os Dez Mandamentos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo da novela \u201cOs Dez Mandamentos\u201d em 01\/09: no cap\u00edtulo 230(*) da novela, Cor\u00e1 conversa com Mois\u00e9s sobre a decis\u00e3o de deixar Z\u00edpora acompanhar Miri\u00e3. Uma semana depois, Cor\u00e1 avalia Bala\u00e3o e comprova que ele n\u00e3o tinha lepra. Bala\u00e3o pede a Cor\u00e1 para ir junto ver o estado de Miri\u00e3. Caravana dos mercadores chega a [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":230998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[379,424,371,2025,343],"tags":[441],"class_list":{"0":"post-236624","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-os-dez-mandamentos","9":"category-rede-record","10":"category-resumo","11":"category-televisao","12":"tag-resumo-do-dia","13":"entry","14":"gs-1","15":"gs-odd","16":"gs-even","17":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos.jpeg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/236624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=236624"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/236624\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/230998"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=236624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=236624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=236624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}