{"id":23039,"date":"2010-02-05T13:14:47","date_gmt":"2010-02-05T17:14:47","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=23039"},"modified":"2010-02-05T13:14:47","modified_gmt":"2010-02-05T17:14:47","slug":"emprega-sp-oferece-203-mil-vagas-em-todo-o-estado","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/emprega-sp-oferece-203-mil-vagas-em-todo-o-estado\/23039","title":{"rendered":"Emprega SP oferece 20,3 mil vagas em todo o Estado"},"content":{"rendered":"<p>O Emprega SP, sistema online e gratuito de intermedia\u00e7\u00e3o de m\u00e3o-de-obra da Secretaria de Emprego e Rela\u00e7\u00f5es do Trabalho, disponibiliza nesta ter\u00e7a-feira, 2, mais de 20,3 mil vagas, distribu\u00eddas entre diversos setores. Ao todo, s\u00e3o 8,7 mil vagas na Regi\u00e3o Metropolitana de S\u00e3o Paulo (RMSP) e 4,5 mil na Capital.<\/p>\n<p>Com a constru\u00e7\u00e3o civil aquecida, o mercado de trabalho paulista precisa de m\u00e3o de obra para construir e para vender os novos empreendimentos imobili\u00e1rios. Por conta disso, entre as vagas mais ofertadas na RMSP est\u00e3o corretor de im\u00f3veis (253 vagas) e ocupa\u00e7\u00f5es ligadas \u00e0 constru\u00e7\u00e3o civil, como pedreiro (128) e carpinteiro (99).<\/p>\n<p>Outras ocupa\u00e7\u00f5es de grande oferta na RMSP s\u00e3o operador de telemarketing (547 vagas), faxineiro (163), porteiro (160), mec\u00e2nico (138) e empregada dom\u00e9stica (136).<\/p>\n<p>Os interessados nas vagas devem fazer um cadastro gratuito no site do Emprega S\u00e3o Paulo (<a href=\"www.empregasaopaulo.sp.gov.br\" target=\"_blank\">www.empregasaopaulo.sp.gov.br<\/a>) ou comparecer a um dos 205 Postos de Atendimento ao Trabalhador (PATs), com RG, CPF e carteira de trabalho. Os endere\u00e7os dos postos est\u00e3o no site da SERT (www.emprego.sp.gov.br). Em caso de d\u00favidas o cidad\u00e3o pode telefonar para a Central de Atendimento do Emprega S\u00e3o Paulo: 0800-770-7378.<\/p>\n<p>\u00a0Da Secretaria de Emprego e Rela\u00e7\u00f5es do Trabalho<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Emprega SP, sistema online e gratuito de intermedia\u00e7\u00e3o de m\u00e3o-de-obra da Secretaria de Emprego e Rela\u00e7\u00f5es do Trabalho, disponibiliza nesta ter\u00e7a-feira, 2, mais de 20,3 mil vagas, distribu\u00eddas entre diversos setores. Ao todo, s\u00e3o 8,7 mil vagas na Regi\u00e3o Metropolitana de S\u00e3o Paulo (RMSP) e 4,5 mil na Capital. Com a constru\u00e7\u00e3o civil aquecida, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,370,353],"tags":[],"class_list":["post-23039","post","type-post","status-publish","format-standard","category-brasil","category-inscricao","category-oportunidades","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/23039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=23039"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/23039\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=23039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=23039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=23039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}