{"id":22463,"date":"2010-01-26T18:13:55","date_gmt":"2010-01-26T22:13:55","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=22463"},"modified":"2010-01-26T18:13:55","modified_gmt":"2010-01-26T22:13:55","slug":"hopi-hari-tem-120-oportunidades-de-trabalho","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/hopi-hari-tem-120-oportunidades-de-trabalho\/22463","title":{"rendered":"Hopi Hari tem 120 oportunidades de trabalho"},"content":{"rendered":"<p><strong><em>Hopi Hari<\/em><\/strong> abre <strong><em>processo seletivo<\/em><\/strong> para a contrata\u00e7\u00e3o de 120 novos colaboradores para as mais diversas \u00e1reas. Seguindo a filosofia da empresa o processo seletivo tem por objetivo garantir inclus\u00e3o social n\u00e3o fazendo discrimina\u00e7\u00e3o de idade, cor, religi\u00e3o, sexo, e limita\u00e7\u00f5es f\u00edsicas, prevalecendo os crit\u00e9rios de seguran\u00e7a e qualidade relacionados ao perfil da vaga. H\u00e1 oportunidades para pessoas com defici\u00eancia, integrantes da terceira idade e jovens &#8211; primeiro emprego. Os candidatos devem residir nas cidades de Campinas, Jundia\u00ed, Vinhedo, Valinhos, Indaiatuba, Louveira e Itupeva, pois Hopi Hari oferece \u00f4nibus fretado para essas regi\u00f5es. As vagas s\u00e3o efetivas.<\/p>\n<p>Os candidatos devem ter 18 anos completos, disponibilidade total de hor\u00e1rio (finais de semana e feriados &#8211; escala rotativa) e bom-humor, solicitude, proatividade e gostar de servir pessoas.<\/p>\n<p>ATENDENTE DE OPERA\u00c7\u00d5ES II<br \/>\nRequisitos Obrigat\u00f3rios<br \/>\n2\u00ba grau completo comprovado com certificado de conclus\u00e3o<br \/>\n\u00c1reas de atua\u00e7\u00e3o:<\/p>\n<p>Alimentos e Bebidas (30 vagas)<br \/>\nAtuar\u00e1 em fast foods e\/ou restaurantes<br \/>\nDesej\u00e1vel: Boas pr\u00e1ticas de Manipula\u00e7\u00e3o de Alimentos, atendimento de gar\u00e7om e balc\u00e3o e opera\u00e7\u00e3o de caixa<\/p>\n<p>Mercadorias (10 vagas)<br \/>\nAtuar\u00e1 em lojas de sortimento variado (vidraria, t\u00eaxtil, papelaria etc.)<br \/>\nDesej\u00e1vel: Atendimento, venda e opera\u00e7\u00e3o de caixa<\/p>\n<p>Jogos (10 vagas)<br \/>\nAtuar\u00e1 na venda e atendimento em jogos de habilidades.<br \/>\nDesej\u00e1vel: experi\u00eancia em atendimento e venda e ser extrovertido<\/p>\n<p>Rides (brinquedos) (30 vagas)<br \/>\nAtuar\u00e1 realizando atendimento nos brinquedos<br \/>\nDesej\u00e1vel: Experi\u00eancia em opera\u00e7\u00e3o de m\u00e1quinas e atendimento<\/p>\n<p>Admiss\u00f5es (Bilheteria e Catraca) (5 vagas)<br \/>\nAtuar\u00e1 realizando atendimento e venda nas bilheterias e catracas<br \/>\nDesej\u00e1vel: experi\u00eancia em opera\u00e7\u00e3o de caixa<\/p>\n<p>Estacionamento (5 vagas)<br \/>\nAtuar\u00e1 realizando atendimento e venda nos estacionamentos e no monitoramento dos ve\u00edculos<br \/>\nDesej\u00e1vel: experi\u00eancia em opera\u00e7\u00e3o de caixa e monitoramento de estacionamentos<\/p>\n<p>Monitores de Seguran\u00e7a (10 vagas)<br \/>\nAtuar\u00e1 no atendimento aos clientes, orientando e informando sobre procedimentos e regras de utiliza\u00e7\u00e3o.<br \/>\nDesej\u00e1vel: Curso de Forma\u00e7\u00e3o de Vigilantes, experi\u00eancia em portaria e seguran\u00e7a patrimonial<\/p>\n<p>Caracterizador (3 vagas)<\/p>\n<p>Profissional com experi\u00eancia em teatro e ou a\u00e7\u00f5es c\u00eanicas.<\/p>\n<p>Atuar\u00e1 em atra\u00e7\u00e3o com intera\u00e7\u00e3o dram\u00e1tica, necess\u00e1rio DRT de caracterizador.<\/p>\n<p>Vendedor Interno (6 vagas)<\/p>\n<p>Atuar\u00e1 no atendimento e venda de atra\u00e7\u00f5es e servi\u00e7os.<\/p>\n<p>ATENDENTE DE OPERA\u00c7\u00d5ES I &#8211; Conserva\u00e7\u00e3o e Limpeza (10 vagas )<br \/>\nRequisitos Obrigat\u00f3rios<br \/>\n1\u00ba grau completo comprovado com certificado original de conclus\u00e3o<\/p>\n<p>\u00c1rea de atua\u00e7\u00e3o:<br \/>\nConserva\u00e7\u00e3o e limpeza<br \/>\nAtuar\u00e1 em \u00e1reas internas e externas alternadamente<br \/>\nDesej\u00e1vel: experi\u00eancia anterior em empresas de limpeza industrial<\/p>\n<p>ATENDENTE DE OPERA\u00c7\u00d5ES III &#8211; Conserva\u00e7\u00e3o e Limpeza (1 vaga)<br \/>\nRequisitos Obrigat\u00f3rios<br \/>\n2\u00ba grau completo comprovado com certificado original de conclus\u00e3o<\/p>\n<p>Opera\u00e7\u00e3o de Trator para atividades de conserva\u00e7\u00e3o e limpeza externa<\/p>\n<p>\u00c1rea de atua\u00e7\u00e3o:<br \/>\nConserva\u00e7\u00e3o e limpeza<br \/>\nAtuar\u00e1 em \u00e1reas internas e externas alternadamente<br \/>\nDesej\u00e1vel: experi\u00eancia anterior em empresas de limpeza industrial<\/p>\n<p>Al\u00e9m das op\u00e7\u00f5es acima, o parque oferece vagas para especialistas:<\/p>\n<p>T\u00e9cnicos El\u00e9trico e Mec\u00e2nicos, Carpinteiros e Pedreiros.<\/p>\n<p>Encaminhar curr\u00edculo para:<\/p>\n<p>Correio<br \/>\nRodovia dos Bandeirantes, km 72 &#8211; Vinhedo\/SP &#8211; CEP: 13.280-000<br \/>\nInformando o T\u00edtulo da vaga no envelope<\/p>\n<p>e-mail : recrutamento@hopihari.com.br<br \/>\ncom o t\u00edtulo da vaga no campo &#8220;assunto&#8221;.<\/p>\n<p>\u00a0Os curr\u00edculos identificados com o cargo no campo assunto ter\u00e3o prefer\u00eancia na triagem.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hopi Hari abre processo seletivo para a contrata\u00e7\u00e3o de 120 novos colaboradores para as mais diversas \u00e1reas. Seguindo a filosofia da empresa o processo seletivo tem por objetivo garantir inclus\u00e3o social n\u00e3o fazendo discrimina\u00e7\u00e3o de idade, cor, religi\u00e3o, sexo, e limita\u00e7\u00f5es f\u00edsicas, prevalecendo os crit\u00e9rios de seguran\u00e7a e qualidade relacionados ao perfil da vaga. H\u00e1 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,370,353],"tags":[],"class_list":{"0":"post-22463","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-inscricao","8":"category-oportunidades","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/22463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=22463"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/22463\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=22463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=22463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=22463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}