{"id":221647,"date":"2022-07-06T20:26:44","date_gmt":"2022-07-06T23:26:44","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2022\/lotofacil-resultado-do-concurso-2565-sorteado-quarta-feira-06-07-2022\/221647"},"modified":"2022-07-06T22:27:19","modified_gmt":"2022-07-07T01:27:19","slug":"lotofacil-resultado-do-concurso-2565-sorteado-quarta-feira-06-07-2022","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2022\/lotofacil-resultado-do-concurso-2565-sorteado-quarta-feira-06-07-2022\/221647","title":{"rendered":"Lotofacil: Resultado do concurso 2565 sorteado  Quarta-feira 06\/07\/2022"},"content":{"rendered":"<p>Resultado da Lotofacil 2565 realizado na  Quarta-feira dia 06\/07\/2022 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo: <\/p>\n<h2>Total de Apostas realizadas<\/h2>\n<p>No concurso 2565 da Lotofacil foi realizado um total de 7.846.357 apostas.<\/p>\n<h2>N\u00fameros Sorteados Lotofacil 2565<\/h2>\n<table>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">01<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">02<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">05<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">07<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">09<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">10<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">11<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">12<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">14<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">15<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">16<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">18<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">20<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">22<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">25<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Premia\u00e7\u00e3o Lotofacil 2565<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad.<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td>15<\/td>\n<td>8<\/td>\n<td align=right>142.620,78<\/td>\n<\/tr>\n<tr>\n<td>14 <\/td>\n<td>734<\/td>\n<td align=right> 465,61<\/td>\n<\/tr>\n<tr>\n<td> 13 <\/td>\n<td>19.232<\/td>\n<td align=right> 25,00<\/td>\n<\/tr>\n<tr>\n<td> 12 <\/td>\n<td>164.926<\/td>\n<td align=right> 10,00<\/td>\n<\/tr>\n<tr>\n<td> 11 <\/td>\n<td>748.895<\/td>\n<td align=right> 5,00<\/td>\n<\/tr>\n<\/table>\n<h2>Cidades Ganhadoras da Lotofacil 2565<\/h2>\n<p>As apostas vencedoras foram realizadas nas seguintes cidades:<\/p>\n<table>\n<tr>\n<th>Cidade<\/th>\n<th>UF<\/th>\n<th>Ganhadores<\/th>\n<\/tr>\n<tr>\n<td>Manaus<\/td>\n<td>AM<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>Belo Horizonte<\/td>\n<td>MG<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>Cianorte<\/td>\n<td>PR<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>Londrina<\/td>\n<td>PR<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>Cacique Doble<\/td>\n<td>RS<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>Farroupilha<\/td>\n<td>RS<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>Indaiatuba<\/td>\n<td>SP<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>Piracicaba<\/td>\n<td>SP<\/td>\n<td>1<\/td>\n<\/tr>\n<\/table>\n<h2>Pr\u00f3ximo Sorteio da Lotofacil <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Quinta-feira 07\/07\/2022, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 1.500.000,00.<\/p>\n<h2>\u00daltimos Resultados da Lotofacil<\/h2>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2022\/lotofacil-resultado-do-concurso-2564-sorteado-terca-feira-05-07-2022\/221635\">Lotofacil 2564<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2022\/lotofacil-resultado-do-concurso-2563-sorteado-segunda-feira-04-07-2022\/221584\">Lotofacil 2563<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2022\/lotofacil-resultado-do-concurso-2562-sorteado-sabado-02-07-2022\/221513\">Lotofacil 2562<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2022\/lotofacil-resultado-do-concurso-2561-sorteado-sexta-feira-01-07-2022\/221499\">Lotofacil 2561<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2022\/lotofacil-resultado-do-concurso-2560-sorteado-quinta-feira-30-06-2022\/221473\">Lotofacil 2560<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Como jogar na Lotofacil<\/h2>\n<p>Em um volante com 25 n\u00fameros voc\u00ea pode marcar entre 15 e 20 e ganha pr\u00eamio se acertar 11, 12, 13, 14 ou 15 n\u00fameros.<br \/>\nPode ainda deixar que o sistema escolha os n\u00fameros, na modalidade Surpresinha ou concorrer com a mesma aposta por 3, 6, 12, 18 ou 24 concursos consecutivos atrav\u00e9s da Teimosinha.<br \/>\nValor da Aposta<br \/>\nA aposta m\u00ednima, de 15 n\u00fameros, custa R$ 2,50.<\/p>\n<h3>Sorteios<\/h3>\n<p>Os sorteios s\u00e3o realizados \u00e0s segundas, ter\u00e7as, quartas, quintas, sextas-feiras e s\u00e1bados, sempre a partir das 20h.<\/p>\n<h3>Premia\u00e7\u00e3o<\/h3>\n<p>O pr\u00eamio para os acertadores de 15 e 14 n\u00fameros s\u00e3o vari\u00e1veis, de acordo com a arrecada\u00e7\u00e3o. Os acertadores de 13 n\u00fameros ganham 25 reais, os acertadores de 12 n\u00fameros ganham 10 reais e os de 11 n\u00fameros ganham 5 reais.<br \/>\n10% dos recursos de cada concurso da Lotofacil s\u00e3o acumulados para compor o pr\u00eamio dos concursos com final 0 (zero). Esse valor acumulado \u00e9 rateado entre os acertadores de 15 e 14 n\u00fameros.<br \/>\nOs pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao Tesouro Nacional para aplica\u00e7\u00e3o no FIES &#8211; Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lotofacil 2565 &#8211; Resultado, rateio e ganhadores da Lotofacil 2565 sorteado em 06\/07\/2022.<\/p>\n","protected":false},"author":3,"featured_media":196331,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,357],"tags":[],"class_list":{"0":"post-221647","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-loto-facil","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/lotofacil-resultado.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/221647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=221647"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/221647\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196331"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=221647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=221647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=221647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}