{"id":220224,"date":"2022-05-21T20:25:12","date_gmt":"2022-05-21T23:25:12","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2022\/timemania-resultado-do-concurso-1786-sorteado-sabado-21-05-2022\/220224"},"modified":"2022-05-22T01:01:05","modified_gmt":"2022-05-22T04:01:05","slug":"timemania-resultado-do-concurso-1786-sorteado-sabado-21-05-2022","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2022\/timemania-resultado-do-concurso-1786-sorteado-sabado-21-05-2022\/220224","title":{"rendered":"Timemania: Resultado do concurso 1786 sorteado  S\u00e1bado 21\/05\/2022"},"content":{"rendered":"<p>Resultado da Timemania 1786 realizado  S\u00e1bado dia 21\/05\/2022 no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo: <\/p>\n<h2>Total de Apostas realizadas<\/h2>\n<p>No concurso 1786 da Timemania foi realizado um total de 2.102.325 apostas.<\/p>\n<h2>N\u00fameros Sorteados Timemania 1786<\/h2>\n<table style=\"margin-bottom: 10px;\">\n<tr>\n<td><span class=\"numberCircleTimeMania\">12<\/span><\/td>\n<td><span class=\"numberCircleTimeMania\">25<\/span><\/td>\n<td><span class=\"numberCircleTimeMania\">28<\/span><\/td>\n<td><span class=\"numberCircleTimeMania\">56<\/span><\/td>\n<td><span class=\"numberCircleTimeMania\">64<\/span><\/td>\n<td><span class=\"numberCircleTimeMania\">65<\/span><\/td>\n<td><span class=\"numberCircleTimeMania\">71<\/span><\/td>\n<\/tr>\n<\/table >\n<div style =\"font-size: 1.3em;margin-bottom:20px;\">Time do Cora\u00e7\u00e3o: N\u00e1utico (PE)<\/div>\n<h2>Premia\u00e7\u00e3o Timemania 1786<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad.<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td>  7  <\/td>\n<td>0<\/td>\n<td>0,00<\/td>\n<\/tr>\n<tr>\n<td>  6 <\/td>\n<td>7<\/td>\n<td>48.735,93<\/td>\n<\/tr>\n<tr>\n<td>  5 <\/td>\n<td>423<\/td>\n<td>1.152,14<\/td>\n<\/tr>\n<tr>\n<td>  4 <\/td>\n<td>7.891<\/td>\n<td>9,00<\/td>\n<\/tr>\n<tr>\n<td>  3 <\/td>\n<td>73.816<\/td>\n<td>3,00<\/td>\n<\/tr>\n<tr>\n<td>  Time do cora\u00e7\u00e3o <\/td>\n<td>22.926<\/td>\n<td>7,50<\/td>\n<\/tr>\n<\/table>\n<h2>Pr\u00f3ximo Sorteio da Timemania <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Ter\u00e7a-feira 24\/05\/2022, no Espa\u00e7o da Sorte, na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 22.500.000,00.<\/p>\n<h2>\u00daltimos Resultados da Timemania<\/h2>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2022\/timemania-resultado-do-concurso-1785-sorteado-quinta-feira-19-05-2022\/220159\">Timemania 1785<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2022\/timemania-resultado-do-concurso-1784-sorteado-terca-feira-17-05-2022\/220068\">Timemania 1784<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2022\/timemania-resultado-do-concurso-1783-sorteado-sabado-14-05-2022\/219936\">Timemania 1783<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2022\/timemania-resultado-do-concurso-1782-sorteado-quinta-feira-12-05-2022\/219891\">Timemania 1782<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2022\/timemania-resultado-do-concurso-1781-sorteado-terca-feira-10-05-2022\/219795\">Timemania 1781<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Como jogar na Timemania <\/h2>\n<p>Voc\u00ea escolhe dez n\u00fameros entre os oitenta dispon\u00edveis e um Time do Cora\u00e7\u00e3o. S\u00e3o sorteados sete n\u00fameros e um Time do Cora\u00e7\u00e3o. Voc\u00ea ganha se acertar 7, 6, 5, 4 ou 3 n\u00fameros. Tamb\u00e9m ganha se acertar o Time do Cora\u00e7\u00e3o.<br \/>\nVoc\u00ea pode deixar, ainda, que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) ou repetir o mesmo jogo por 2 ou 4 concursos consecutivos (Teimosinha).<\/p>\n<h3>Aposta<\/h3>\n<p>O valor da aposta \u00e9 de R$ 3,00.<\/p>\n<h3>Sorteios<\/h3>\n<p>Os sorteios da Timemania s\u00e3o realizados nas ter\u00e7as, quintas e s\u00e1bados, a partir das 20h.<\/p>\n<h3>Premia\u00e7\u00e3o<\/h3>\n<p>O pr\u00eamio para os acertadores de 7 ou 6 n\u00fameros s\u00e3o vari\u00e1veis, a depender da arrecada\u00e7\u00e3o. Ganha R$ 7,50 quem acertar o Time do Cora\u00e7\u00e3o sorteado; R$ 3,00 para as apostas com 3 n\u00fameros sorteados; e R$ 9,00 para as apostas com 4 n\u00fameros sorteados.<br \/>\nOs pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao Tesouro Nacional para aplica\u00e7\u00e3o no FIES &#8211; Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n<h3>Acumula\u00e7\u00e3o de pr\u00eamios<\/h3>\n<p>N\u00e3o existindo aposta premiada na 1\u00aa, 2\u00aa ou 3\u00aa faixas de premia\u00e7\u00e3o, inclusive nos concursos de 0 ou 5, o(s) pr\u00eamio(s) acumula(m) para o concurso subsequente, na 1\u00aa faixa de premia\u00e7\u00e3o &#8211; apostas com 7 n\u00fameros certos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Timemania 1786 &#8211; Resultado, rateio e ganhadores da Timemania 1786 sorteado em 21\/05\/2022.<\/p>\n","protected":false},"author":3,"featured_media":196329,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,361],"tags":[],"class_list":{"0":"post-220224","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-time-mania","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/timemania-resultado.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/220224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=220224"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/220224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196329"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=220224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=220224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=220224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}