{"id":217398,"date":"2022-03-18T10:34:24","date_gmt":"2022-03-18T13:34:24","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=217398"},"modified":"2022-03-18T10:34:24","modified_gmt":"2022-03-18T13:34:24","slug":"dupla-sena-2355-dupla-de-pascoa-premio-de-r-30-milhoes-dia-16-de-abril-de-2022","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2022\/dupla-sena-2355-dupla-de-pascoa-premio-de-r-30-milhoes-dia-16-de-abril-de-2022\/217398","title":{"rendered":"Dupla Sena 2355 \u201cDupla de P\u00e1scoa\u201d: pr\u00eamio de R$ 30 milh\u00f5es dia 16 de abril de 2022"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-194777\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/dupla-sena-resultado-sorteio-loteria.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/dupla-sena-resultado-sorteio-loteria.jpg 1280w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/dupla-sena-resultado-sorteio-loteria-250x140.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/dupla-sena-resultado-sorteio-loteria-400x225.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/dupla-sena-resultado-sorteio-loteria-768x432.jpg 768w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/dupla-sena-resultado-sorteio-loteria-150x85.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/dupla-sena-resultado-sorteio-loteria-696x392.jpg 696w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/dupla-sena-resultado-sorteio-loteria-1068x601.jpg 1068w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>A <em><strong>Dupla Sena 2355, \u201cDupla de P\u00e1scoa\u201d de 2022<\/strong><\/em>, ser\u00e1 sorteada no dia 16 de abril, a partir das 20h (hor\u00e1rio de Bras\u00edlia), e oferece o pr\u00eamio estimado em R$ 30 milh\u00f5es. As vendas paralelas para o concurso especial come\u00e7aram nesta segunda-feira (14\/03).<\/p>\n<p>Pode interessar<br \/>\n<a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2022\/dupla-de-pascoa-2355-6a-edicao-do-concurso-especial\/217389\">\u201cDupla de P\u00e1scoa\u201d 2355: 6\u00aa edi\u00e7\u00e3o do concurso especial<\/a><\/p>\n<p>Caso apenas um apostador leve o pr\u00eamio de R$ 30 milh\u00f5es e aplique na Poupan\u00e7a da CAIXA, receber\u00e1 um rendimento de R$ 150 mil no primeiro m\u00eas. O valor tamb\u00e9m seria suficiente para comprar uma frota popular de 400 carros de R$ 75 mil cada. <\/p>\n<p>Bol\u00e3o da Dupla de P\u00e1scoa<\/p>\n<p>Para aumentar as chances de ganhar, os apostadores tamb\u00e9m podem participar de bol\u00f5es. Basta formar um grupo, escolher os n\u00fameros da aposta, marcar a quantidade de cotas e registrar em qualquer uma das lot\u00e9ricas do pa\u00eds. <\/p>\n<p>O apostador tamb\u00e9m pode adquirir cotas de bol\u00f5es organizados pelas lot\u00e9ricas. Basta solicitar ao atendente a quantidade de cotas que deseja e guardar o recibo para conferir a aposta no dia do sorteio. Nesse caso, poder\u00e1 ser cobrado uma tarifa de servi\u00e7o adicional de at\u00e9 35% do valor da cota, a crit\u00e9rio da lot\u00e9rica.<\/p>\n<p>Na Dupla Sena, os bol\u00f5es t\u00eam pre\u00e7o m\u00ednimo de R$ 10,00. Cada cota n\u00e3o pode ser inferior a R$ 2,50. \u00c9 poss\u00edvel realizar um bol\u00e3o de no m\u00ednimo duas e no m\u00e1ximo 50 cotas. \u00c9 permitida a realiza\u00e7\u00e3o de no m\u00e1ximo dez apostas por bol\u00e3o. Em caso de bol\u00e3o com mais de uma aposta, todas elas dever\u00e3o conter a mesma quantidade de n\u00fameros de progn\u00f3sticos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Dupla Sena 2355, \u201cDupla de P\u00e1scoa\u201d de 2022, ser\u00e1 sorteada no dia 16 de abril, a partir das 20h (hor\u00e1rio de Bras\u00edlia), e oferece o pr\u00eamio estimado em R$ 30 milh\u00f5es. As vendas paralelas para o concurso especial come\u00e7aram nesta segunda-feira (14\/03). Pode interessar \u201cDupla de P\u00e1scoa\u201d 2355: 6\u00aa edi\u00e7\u00e3o do concurso especial Caso [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":194755,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,360,335],"tags":[524,476,531],"class_list":["post-217398","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","category-dupla-sena","category-loteria","tag-dupla-sena","tag-loteria","tag-numeros-sorteados","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-dupla-sena-sorteio-premio-loteria.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/217398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=217398"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/217398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/194755"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=217398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=217398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=217398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}