{"id":216889,"date":"2022-03-03T23:03:24","date_gmt":"2022-03-04T02:03:24","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2022\/a-quina-5794-nesta-sexta-feira-preve-pagar-r-1-400-00000\/216889"},"modified":"2022-03-03T23:03:24","modified_gmt":"2022-03-04T02:03:24","slug":"a-quina-5794-nesta-sexta-feira-preve-pagar-r-1-400-00000","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2022\/a-quina-5794-nesta-sexta-feira-preve-pagar-r-1-400-00000\/216889","title":{"rendered":"A Quina 5794, nesta  Sexta-feira, preve pagar R$ 1.400.000,00"},"content":{"rendered":"<p>A Quina de Quinta-feira, concurso 5793 n\u00e3o teve acertador das 5 dezenas sorteadas. <\/p>\n<p>Os n\u00fameros sorteados foram:<br \/><b>22, 13, 51, 72, 66.<\/b><\/p>\n<p>O pr\u00f3ximo sorteio, <b>Quina 5794<\/b>, tem um pr\u00eamio previsto de R$ 1.400.000,00 e ser\u00e1 realizado nesta  Sexta-feira, dia 04\/03\/2022, a partir das 20 horas.<\/p>\n<p>Para jogar na \u201cQuina\u201d, o apostador escolhe de cinco a 15 n\u00fameros, entre os 80 dispon\u00edveis. Ganha quem acertar de dois a cinco n\u00fameros.<\/p>\n<p>O Concurso Especial da \u201cQuina\u201d \u00e9 realizado sempre pr\u00f3ximo ao dia 24 de junho de cada ano civil. N\u00e3o existindo aposta premiada na 1\u00aa faixa (quina), este valor ser\u00e1 somado ao valor da 2\u00aa faixa e rateado entre as apostas que contiverem 4 progn\u00f3sticos certos (quadra)<\/p>\n<p>As apostas nas loterias consistem na indica\u00e7\u00e3o de um conjunto de progn\u00f3sticos sobre n\u00fameros inteiros, mediante pagamento de quantia prefixada por aposta efetuada. As apostas podem ser realizadas at\u00e9 uma hora antes dos sorteios. Os sorteios acontecem seis vezes por semana, de segunda-feira a s\u00e1bado. Caso n\u00e3o haja acertador em qualquer faixa de premia\u00e7\u00e3o, o valor acumula para o concurso seguinte na respectiva faixa.<\/p>\n<p>O pr\u00eamio bruto \u00e9 assim distribu\u00eddo: 35% entre os acertadores dos cinco n\u00fameros, 20% de tr\u00eas n\u00fameros, 19% de quatro, 11% de dois e 15% acumulam para o concurso especial \u201cQuina\u201d de S\u00e3o Jo\u00e3o. Realizado no m\u00eas de junho, o concurso sorteia uma pequena fortuna e, como os outros especial, tamb\u00e9m n\u00e3o acumula.<\/p>\n<p>Confira o bilhete impresso em uma casa lot\u00e9rica. Ele \u00e9 o \u00fanico comprovante da sua aposta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Quina de Quinta-feira, concurso 5793 n\u00e3o teve acertador das 5 dezenas sorteadas. Os n\u00fameros sorteados foram:22, 13, 51, 72, 66. O pr\u00f3ximo sorteio, Quina 5794, tem um pr\u00eamio previsto de R$ 1.400.000,00 e ser\u00e1 realizado nesta Sexta-feira, dia 04\/03\/2022, a partir das 20 horas. Para jogar na \u201cQuina\u201d, o apostador escolhe de cinco a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":196332,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,2258,358],"tags":[],"class_list":{"0":"post-216889","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-premio","9":"category-quina","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-quina-1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/216889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=216889"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/216889\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196332"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=216889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=216889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=216889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}