{"id":211695,"date":"2021-10-20T20:26:14","date_gmt":"2021-10-20T23:26:14","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-do-super-sete-159-de-20-10-2021\/211695"},"modified":"2021-10-20T20:26:14","modified_gmt":"2021-10-20T23:26:14","slug":"resultado-do-super-sete-159-de-20-10-2021","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-do-super-sete-159-de-20-10-2021\/211695","title":{"rendered":"Resultado do Super Sete 159 de 20\/10\/2021"},"content":{"rendered":"<p>Resultado do Super Sete 159 realizado na  Quarta-feira dia 20\/10\/2021 no Espa\u00e7o CAIXA Loterias na cidade de S\u00e3o Paulo: <\/p>\n<h2>N\u00fameros Sorteados Super Sete 159<\/h2>\n<table style=\"margin-bottom: 10px;\">\n<tr>\n<td>1<\/td>\n<td>2<\/td>\n<td>3<\/td>\n<td>4<\/td>\n<td>5<\/td>\n<td>6<\/td>\n<td>7<\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleSuperSete\">8<\/span><\/td>\n<td><span class=\"numberCircleSuperSete\">3<\/span><\/td>\n<td><span class=\"numberCircleSuperSete\">0<\/span><\/td>\n<td><span class=\"numberCircleSuperSete\">4<\/span><\/td>\n<td><span class=\"numberCircleSuperSete\">6<\/span><\/td>\n<td><span class=\"numberCircleSuperSete\">0<\/span><\/td>\n<td><span class=\"numberCircleSuperSete\">4<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Pr\u00f3ximo Sorteio da Super Sete <\/h2>\n<p>O pr\u00f3ximo sorteio ser\u00e1 realizado Sexta-feira 22\/10\/2021, . <\/p>\n<h2>\u00daltimos Resultados do Super Sete<\/h2>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-do-super-sete-158-de-18-10-2021\/211602\">Super Sete 158<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-do-super-sete-157-de-15-10-2021\/211507\">Super Sete 157<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-do-super-sete-156-de-13-10-2021\/211411\">Super Sete 156<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-do-super-sete-155-de-11-10-2021\/211325\">Super Sete 155<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-do-super-sete-154-de-08-10-2021\/211272\">Super Sete 154<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Como jogar no Super Sete<\/h2>\n<p>Para jogar voc\u00ea deve escolher um n\u00famero (de 0 a 9) de cada uma das sete colunas. Ganha quem acertar os 7, 6, 5, 4 ou 3 n\u00fameros. Voc\u00ea pode deixar, ainda, que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou continuar com o seu jogo por 3, 6,  9 ou 12 concursos consecutivos (Teimosinha).<br \/>\nApostas<br \/>\nO valor da aposta \u00e9 de R$ 2,50.<\/p>\n<h3>Sorteios<\/h3>\n<p>S\u00e3o 3 sorteios semanais: \u00e0s segundas, quartas e sextas-feiras, a partir das 20h.<\/p>\n<h3>Premia\u00e7\u00e3o<\/h3>\n<p>Os valores dos pr\u00eamios para os acertadores dos 7 n\u00fameros e de 6, 5, e 4 n\u00fameros \u00e9 vari\u00e1vel e depende da arrecada\u00e7\u00e3o. O pr\u00eamio para quem acertar 3 n\u00fameros \u00e9 de R$ 5,00.<br \/>\nVoc\u00ea pode receber seu pr\u00eamio em qualquer casa lot\u00e9rica credenciada ou nas ag\u00eancias da CAIXA. Caso o pr\u00eamio bruto seja superior a R$ 1.903,98, o pagamento pode ser realizado somente nas ag\u00eancias da CAIXA, <\/p>\n<h3>Acumula\u00e7\u00e3o<\/h3>\n<p>N\u00e3o existindo aposta premiada em qualquer faixa de premia\u00e7\u00e3o, os valores acumulam para o concurso seguinte, na primeira faixa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Super Sete 159 &#8211; Resultado, rateio e ganhadores do Super Sete 159 sorteado em 20\/10\/2021.<\/p>\n","protected":false},"author":3,"featured_media":198345,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,2074],"tags":[],"class_list":{"0":"post-211695","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-super-sete","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/super-sete-resultado-loteria-premio.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/211695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=211695"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/211695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/198345"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=211695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=211695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=211695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}