{"id":209076,"date":"2021-08-04T21:42:13","date_gmt":"2021-08-05T00:42:13","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2299-de-04-08-2021\/209076"},"modified":"2021-08-04T21:42:13","modified_gmt":"2021-08-05T00:42:13","slug":"resultado-da-lotofacil-2299-de-04-08-2021","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2299-de-04-08-2021\/209076","title":{"rendered":"Resultado da Lotofacil 2299 de 04\/08\/2021"},"content":{"rendered":"<p>Resultado da Lotofacil 2299 realizado na  Quarta-feira dia 04\/08\/2021 no Espa\u00e7o CAIXA Loterias na cidade de S\u00e3o Paulo: <\/p>\n<h2>N\u00fameros Sorteados Lotofacil 2299<\/h2>\n<table>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">01<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">03<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">05<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">07<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">08<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">09<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">11<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">12<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">14<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">15<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">16<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">20<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">21<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">23<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">25<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Premia\u00e7\u00e3o Lotofacil 2299<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad.<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td>15<\/td>\n<td>6<\/td>\n<td align=right>204.012,39<\/td>\n<\/tr>\n<tr>\n<td>14 <\/td>\n<td>818<\/td>\n<td align=right> 448,23<\/td>\n<\/tr>\n<tr>\n<td> 13 <\/td>\n<td>14.200<\/td>\n<td align=right> 25,00<\/td>\n<\/tr>\n<tr>\n<td> 12 <\/td>\n<td>135.685<\/td>\n<td align=right> 10,00<\/td>\n<\/tr>\n<tr>\n<td> 11 <\/td>\n<td>659.179<\/td>\n<td align=right> 5,00<\/td>\n<\/tr>\n<\/table>\n<h2>Pr\u00f3ximo Sorteio<\/h2>\n<p>O pr\u00f3ximo sorteio, Lotofacil 2300, ser\u00e1 realizado Quinta-feira 05\/08\/2021, no Espa\u00e7o CAIXA Loterias na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 4.000.000,00.<\/p>\n<h2>Lotofacil da Independ\u00eancia<\/h2>\n<p>A Lotofacil da Independ\u00eancia tem, at\u00e9 o momento, acumulado  R$ 94.871.084,40.<\/p>\n<h2>Cidades Ganhadoras da Lotofacil 2299<\/h2>\n<p>As apostas vencedoras foram realizadas nas seguintes cidades:<\/p>\n<table>\n<tr>\n<th>Cidade<\/th>\n<th>UF<\/th>\n<th>Ganhadores<\/th>\n<\/tr>\n<tr>\n<td>Rio de Janeiro<\/td>\n<td>RJ<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>Blumenau<\/td>\n<td>SC<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>I\u00e7ara<\/td>\n<td>SC<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>Bilac<\/td>\n<td>SP<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>Santana de Parna\u00edba<\/td>\n<td>SP<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td>S\u00e3o Jos\u00e9 do Rio Preto<\/td>\n<td>SP<\/td>\n<td>1<\/td>\n<\/tr>\n<\/table>\n<h2>\u00daltimos Resultados da Lotofacil<\/h2>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2298-de-03-08-2021\/209044\">Lotofacil 2298<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2297-de-02-08-2021\/209004\">Lotofacil 2297<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2296-de-31-07-2021\/208969\">Lotofacil 2296<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2295-de-30-07-2021\/208927\">Lotofacil 2295<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2294-de-29-07-2021\/208905\">Lotofacil 2294<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Resumo do sorteio da Lotofacil 2299<\/h2>\n<ul>\n<li>Dos n\u00fameros sorteados neste concurso da Lotofacil o que mais saiu nos \u00faltimos 12 meses foi o 20, sorteado 198 vezes.<\/li>\n<li>O que menos saiu foi o n\u00famero 23, sorteado apenas 161 vezes.<\/li>\n<li>Das 25 dezenas, a que est\u00e1 h\u00e1 mais tempo sem ser sorteada \u00e9 a 19 que n\u00e3o sai tem 6  dias.<\/li>\n<li>O pr\u00eamio de maior valor pago neste per\u00edodo, sem contar o da Lotofacil da Independ\u00eancia, foi de R$ 8.516.088,52 correspondente ao concurso 2080, sorteado em 12\/11\/2020.<\/li>\n<li>Nos \u00faltimos 12 meses foram realizados 297 sorteios e premiadas 740 pessoas que acertaram os 25 n\u00fameros da Lotofacil.<\/li>\n<li>Neste per\u00edodo a Lotofacil n\u00e3o teve acertadores em 60 oportunidades.<\/li>\n<\/ul>\n<\/ul>\n<h3>Hist\u00f3rico dos n\u00fameros sorteados neste concurso da Lotofacil<\/h3>\n<p>Nesta tabela voc\u00ea ir\u00e1 encontrar as seguintes informa\u00e7\u00f5es relativas aos sorteios da Lotofacil dos \u00faltimos 12 meses:<br \/>A quantidade de vezes que o n\u00famero foi sorteado na Lotofacil,<br \/>A quantidade de sorteios que este n\u00famero saiu e o concurso teve ganhador,<br \/>A data do \u00faltimo sorteio na Lotofacil desta dezena.<\/p>\n<table>\n<tr>\n<th>Dezena<\/th>\n<th>Total<\/th>\n<th>Premiada<\/th>\n<th>Data<\/th>\n<\/tr>\n<tr>\n<td>01<\/td>\n<td>167<\/td>\n<td>131<\/td>\n<td>03\/08\/2021<\/td>\n<\/tr>\n<tr>\n<td>03<\/td>\n<td>180<\/td>\n<td>141<\/td>\n<td>03\/08\/2021<\/td>\n<\/tr>\n<tr>\n<td>05<\/td>\n<td>171<\/td>\n<td>143<\/td>\n<td>28\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>07<\/td>\n<td>165<\/td>\n<td>129<\/td>\n<td>02\/08\/2021<\/td>\n<\/tr>\n<tr>\n<td>08<\/td>\n<td>177<\/td>\n<td>143<\/td>\n<td>31\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>09<\/td>\n<td>186<\/td>\n<td>151<\/td>\n<td>02\/08\/2021<\/td>\n<\/tr>\n<tr>\n<td>11<\/td>\n<td>182<\/td>\n<td>146<\/td>\n<td>02\/08\/2021<\/td>\n<\/tr>\n<tr>\n<td>12<\/td>\n<td>180<\/td>\n<td>151<\/td>\n<td>03\/08\/2021<\/td>\n<\/tr>\n<tr>\n<td>14<\/td>\n<td>189<\/td>\n<td>153<\/td>\n<td>03\/08\/2021<\/td>\n<\/tr>\n<tr>\n<td>15<\/td>\n<td>169<\/td>\n<td>133<\/td>\n<td>02\/08\/2021<\/td>\n<\/tr>\n<tr>\n<td>16<\/td>\n<td>175<\/td>\n<td>140<\/td>\n<td>03\/08\/2021<\/td>\n<\/tr>\n<tr>\n<td>20<\/td>\n<td>198<\/td>\n<td>161<\/td>\n<td>03\/08\/2021<\/td>\n<\/tr>\n<tr>\n<td>21<\/td>\n<td>174<\/td>\n<td>133<\/td>\n<td>03\/08\/2021<\/td>\n<\/tr>\n<tr>\n<td>23<\/td>\n<td>161<\/td>\n<td>130<\/td>\n<td>03\/08\/2021<\/td>\n<\/tr>\n<tr>\n<td>25<\/td>\n<td>192<\/td>\n<td>151<\/td>\n<td>03\/08\/2021<\/td>\n<\/tr>\n<\/table>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lotofacil 2299 &#8211; Resultado, rateio e ganhadores da Lotofacil 2299 sorteado em 04\/08\/2021.<\/p>\n","protected":false},"author":3,"featured_media":196331,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,357],"tags":[],"class_list":{"0":"post-209076","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-loto-facil","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/lotofacil-resultado.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/209076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=209076"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/209076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196331"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=209076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=209076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=209076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}