{"id":208497,"date":"2021-07-16T22:30:46","date_gmt":"2021-07-17T01:30:46","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2283-de-16-07-2021\/208497"},"modified":"2021-07-16T22:30:46","modified_gmt":"2021-07-17T01:30:46","slug":"resultado-da-lotofacil-2283-de-16-07-2021","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2283-de-16-07-2021\/208497","title":{"rendered":"Resultado da Lotofacil 2283 de 16\/07\/2021"},"content":{"rendered":"<p>Resultado da Lotofacil 2283 realizado na  Sexta-feira dia 16\/07\/2021 no Espa\u00e7o CAIXA Loterias na cidade de S\u00e3o Paulo: <\/p>\n<h2>N\u00fameros Sorteados Lotofacil 2283<\/h2>\n<table>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">01<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">02<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">05<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">07<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">09<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">10<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">11<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">15<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">17<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">18<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"numberCircleLotoFacil\">19<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">20<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">22<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">23<\/span><\/td>\n<td><span class=\"numberCircleLotoFacil\">25<\/span><\/td>\n<\/tr>\n<\/table>\n<h2>Premia\u00e7\u00e3o Lotofacil 2283<\/h2>\n<table>\n<tr>\n<th>Acertos<\/th>\n<th>Ganhad.<\/th>\n<th>Pr\u00eamio<\/th>\n<\/tr>\n<tr>\n<td>15<\/td>\n<td>1<\/td>\n<td align=right>1.201.677,20<\/td>\n<\/tr>\n<tr>\n<td>14 <\/td>\n<td>355<\/td>\n<td align=right> 1.013,94<\/td>\n<\/tr>\n<tr>\n<td> 13 <\/td>\n<td>12.881<\/td>\n<td align=right> 25,00<\/td>\n<\/tr>\n<tr>\n<td> 12 <\/td>\n<td>142.782<\/td>\n<td align=right> 10,00<\/td>\n<\/tr>\n<tr>\n<td> 11 <\/td>\n<td>719.363<\/td>\n<td align=right> 5,00<\/td>\n<\/tr>\n<\/table>\n<h2>Pr\u00f3ximo Sorteio<\/h2>\n<p>O pr\u00f3ximo sorteio, Lotofacil 2284, ser\u00e1 realizado S\u00e1bado 17\/07\/2021, no Espa\u00e7o CAIXA Loterias na cidade de S\u00e3o Paulo. O pr\u00eamio previsto \u00e9 de R$ 1.500.000,00.<\/p>\n<h2>Lotofacil da Independ\u00eancia<\/h2>\n<p>A Lotofacil da Independ\u00eancia tem, at\u00e9 o momento, acumulado  R$ 89.776.212,64.<\/p>\n<h2>Cidades Ganhadoras da Lotofacil 2283<\/h2>\n<p>As apostas vencedoras foram realizadas nas seguintes cidades:<\/p>\n<table>\n<tr>\n<th>Cidade<\/th>\n<th>UF<\/th>\n<th>Ganhadores<\/th>\n<\/tr>\n<tr>\n<td>Rio de Janeiro<\/td>\n<td>SP<\/td>\n<td>1<\/td>\n<\/tr>\n<\/table>\n<h2>\u00daltimos Resultados da Lotofacil<\/h2>\n<p><lu><\/p>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2282-de-15-07-2021\/208474\">Lotofacil 2282<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2281-de-14-07-2021\/208438\">Lotofacil 2281<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2280-de-13-07-2021\/208406\">Lotofacil 2280<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2279-de-12-07-2021\/208362\">Lotofacil 2279<\/a><\/li>\n<li><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2021\/resultado-da-lotofacil-2278-de-10-07-2021\/208300\">Lotofacil 2278<\/a><\/li>\n<p><\/lu><\/p>\n<h2>Resumo do sorteio da Lotofacil 2283<\/h2>\n<ul>\n<li>Dos n\u00fameros sorteados neste concurso da Lotofacil o que mais saiu nos \u00faltimos 12 meses foi o 20, sorteado 195 vezes.<\/li>\n<li>O que menos saiu foi o n\u00famero 23, sorteado apenas 154 vezes.<\/li>\n<li>Das 25 dezenas, a que est\u00e1 h\u00e1 mais tempo sem ser sorteada \u00e9 a 8 que n\u00e3o sai tem 4  dias.<\/li>\n<li>O pr\u00eamio de maior valor pago neste per\u00edodo, sem contar o da Lotofacil da Independ\u00eancia, foi de R$ 8.516.088,52 correspondente ao concurso 2080, sorteado em 12\/11\/2020.<\/li>\n<li>Nos \u00faltimos 12 meses foram realizados 290 sorteios e premiadas 723 pessoas que acertaram os 25 n\u00fameros da Lotofacil.<\/li>\n<li>Neste per\u00edodo a Lotofacil n\u00e3o teve acertadores em 59 oportunidades.<\/li>\n<\/ul>\n<\/ul>\n<h3>Hist\u00f3rico dos n\u00fameros sorteados neste concurso da Lotofacil<\/h3>\n<p>Nesta tabela voc\u00ea ir\u00e1 encontrar as seguintes informa\u00e7\u00f5es relativas aos sorteios da Lotofacil dos \u00faltimos 12 meses:<br \/>A quantidade de vezes que o n\u00famero foi sorteado na Lotofacil,<br \/>A quantidade de sorteios que este n\u00famero saiu e o concurso teve ganhador,<br \/>A data do \u00faltimo sorteio na Lotofacil desta dezena.<\/p>\n<table>\n<tr>\n<th>Dezena<\/th>\n<th>Total<\/th>\n<th>Premiada<\/th>\n<th>Data<\/th>\n<\/tr>\n<tr>\n<td>01<\/td>\n<td>160<\/td>\n<td>125<\/td>\n<td>15\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>02<\/td>\n<td>162<\/td>\n<td>135<\/td>\n<td>15\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>05<\/td>\n<td>169<\/td>\n<td>141<\/td>\n<td>15\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>07<\/td>\n<td>163<\/td>\n<td>128<\/td>\n<td>14\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>09<\/td>\n<td>181<\/td>\n<td>147<\/td>\n<td>14\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>10<\/td>\n<td>190<\/td>\n<td>148<\/td>\n<td>15\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>11<\/td>\n<td>177<\/td>\n<td>142<\/td>\n<td>15\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>15<\/td>\n<td>162<\/td>\n<td>126<\/td>\n<td>14\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>17<\/td>\n<td>183<\/td>\n<td>142<\/td>\n<td>14\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>18<\/td>\n<td>180<\/td>\n<td>138<\/td>\n<td>15\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>19<\/td>\n<td>184<\/td>\n<td>145<\/td>\n<td>13\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>20<\/td>\n<td>195<\/td>\n<td>158<\/td>\n<td>15\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>22<\/td>\n<td>173<\/td>\n<td>139<\/td>\n<td>13\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>23<\/td>\n<td>154<\/td>\n<td>123<\/td>\n<td>15\/07\/2021<\/td>\n<\/tr>\n<tr>\n<td>25<\/td>\n<td>187<\/td>\n<td>147<\/td>\n<td>13\/07\/2021<\/td>\n<\/tr>\n<\/table>\n<h3>Nota<\/h3>\n<p> A divulga\u00e7\u00e3o do resultado pela RedeNoticia.com.br foi cercada de todos os cuidados para informa-lo corretamente e com precis\u00e3o,<br \/>\n        entretanto o resultado oficial \u00e9 o divulgado no site da Caixa Econ\u00f4mica Federal e pelas casas lot\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lotofacil 2283 &#8211; Resultado, rateio e ganhadores da Lotofacil 2283 sorteado em 16\/07\/2021.<\/p>\n","protected":false},"author":3,"featured_media":196331,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,357],"tags":[],"class_list":["post-208497","post","type-post","status-publish","format-standard","has-post-thumbnail","category-loteria","category-loto-facil","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/lotofacil-resultado.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/208497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=208497"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/208497\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/196331"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=208497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=208497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=208497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}