{"id":20116,"date":"2009-12-16T13:52:29","date_gmt":"2009-12-16T17:52:29","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=20116"},"modified":"2009-12-16T13:52:29","modified_gmt":"2009-12-16T17:52:29","slug":"inova-unicamp-busca-gerente","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/inova-unicamp-busca-gerente\/20116","title":{"rendered":"Inova Unicamp busca gerente"},"content":{"rendered":"<p>A ag\u00eancia de inova\u00e7\u00e3o <strong><em>Inova Unicamp<\/em><\/strong>, da Universidade Estadual de Campinas, est\u00e1 selecionando candidatos para uma <strong><em>vaga de gerente de projetos<\/em><\/strong>.\u00a0De acordo com a ag\u00eancia, o selecionado dever\u00e1 gerenciar processos de avalia\u00e7\u00e3o do potencial inovativo de tecnologias desenvolvidas em sete institui\u00e7\u00f5es de pesquisa de S\u00e3o Paulo: Centro T\u00e9cnico Aeroespacial, Instituto de Pesquisas Tecnol\u00f3gicas, Universidade Federal de S\u00e3o Carlos, Universidade Estadual Paulista, Universidade de S\u00e3o Paulo e Unicamp.<\/p>\n<p>Para isso, o profissional dever\u00e1 interagir com os N\u00facleos de Inova\u00e7\u00e3o Tecnol\u00f3gica (NIT) de cada uma das institui\u00e7\u00f5es. O gerenciamento do projeto Pr\u00f3-NIT envolve a remunera\u00e7\u00e3o de R$ 3.169,37 para uma carga hor\u00e1ria de 40 horas semanais e a dura\u00e7\u00e3o \u00e9 de 12 meses.<\/p>\n<p>Os candidatos devem ter doutorado ou quatro anos de experi\u00eancia comprovada em pesquisa e desenvolvimento, al\u00e9m de conhecimentos em gerenciamento de projetos, dom\u00ednio de aplicativos de inform\u00e1tica (MS Office) e n\u00edvel avan\u00e7ado de ingl\u00eas. S\u00e3o desej\u00e1veis: espanhol n\u00edvel intermedi\u00e1rio e conhecimentos de gest\u00e3o da inova\u00e7\u00e3o.<\/p>\n<p>Os interessados devem enviar curr\u00edculo at\u00e9 o dia 16 de dezembro para <a href=\"mailto:%20rhinova@inova.unicamp.br\" target=\"_blank\">rhinova@inova.unicamp.br<\/a>, indicando no campo assunto \u201cGerente do projeto pr\u00f3-NIT\u201d.<\/p>\n<p>Ag\u00eancia FAPESP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ag\u00eancia de inova\u00e7\u00e3o Inova Unicamp, da Universidade Estadual de Campinas, est\u00e1 selecionando candidatos para uma vaga de gerente de projetos.\u00a0De acordo com a ag\u00eancia, o selecionado dever\u00e1 gerenciar processos de avalia\u00e7\u00e3o do potencial inovativo de tecnologias desenvolvidas em sete institui\u00e7\u00f5es de pesquisa de S\u00e3o Paulo: Centro T\u00e9cnico Aeroespacial, Instituto de Pesquisas Tecnol\u00f3gicas, Universidade Federal [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[370,353],"tags":[],"class_list":["post-20116","post","type-post","status-publish","format-standard","category-inscricao","category-oportunidades","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/20116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=20116"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/20116\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=20116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=20116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=20116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}