{"id":19662,"date":"2009-12-09T16:48:21","date_gmt":"2009-12-09T20:48:21","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=19662"},"modified":"2009-12-09T16:48:21","modified_gmt":"2009-12-09T20:48:21","slug":"3-465-vagas-de-emprego-em-guarulhos","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/3-465-vagas-de-emprego-em-guarulhos\/19662","title":{"rendered":"3.465 vagas de emprego em Guarulhos"},"content":{"rendered":"<p>O Centro Integrado de Emprego, Trabalho e Renda (CIET) de <strong><em>Guarulhos,<\/em><\/strong> na regi\u00e3o metropolitana de S\u00e3o Paulo, oferece nesta semana 3.465 <strong><em>postos de trabalho<\/em><\/strong>. Os cargos com maior n\u00famero de vagas s\u00e3o para auxiliar de produ\u00e7\u00e3o (369), operador de telemarketing (231), ajudante de carga e descarga (226), motorista de caminh\u00e3o (114), auxiliar de limpeza (88), atendente de balc\u00e3o (76) e operador de caixa (53).<\/p>\n<p>A carga hor\u00e1ria, os benef\u00edcios e a escolaridade variam de acordo com os cargos pretendidos. A faixa salarial varia de R$ 465 (atendente de lanchonete, auxiliar de administra\u00e7\u00e3o, auxiliar de limpeza, lavador de carros e office-boy) a R$ 3.600 (desenhista projetista mec\u00e2nico). H\u00e1 tamb\u00e9m vagas com remunera\u00e7\u00e3o mais alta, como analista de custos (R$ 3.500), gerente de dep\u00f3sito (R$ 3.000), ferramenteiro (R$ 2.675) e supervisor de transportes (R$ 2.500).<\/p>\n<p>Do total de vagas abertas, 521 s\u00e3o para portadores de defici\u00eancia em ocupa\u00e7\u00f5es como operador de supermercado (180), auxiliar de linha de produ\u00e7\u00e3o (110) e auxiliar de limpeza (39). Os sal\u00e1rios variam de R$ 471 (ajudante de cozinha) a R$ 1.200 (t\u00e9cnico mec\u00e2nico).<\/p>\n<p>Os requisitos necess\u00e1rios para preencher os postos de trabalho variam de acordo com o cargo. Para se candidatar, \u00e9 preciso comparecer, das 8h \u00e0s 17h, de segunda \u00e0 sexta-feira, em um dos quatro postos do Centro Integrado de Emprego, Trabalho e Renda de Guarulhos (Posto Centro &#8211; Rua S\u00e3o Vicente de Paula, 163 \/ Posto Cumbica &#8211; Rua Capit\u00e3o Aviador Walter Ribeiro, 359 \/ Posto Vila Augusta &#8211; Rua Ant\u00f4nio Iervolino, 225 \/ Posto Pimentas &#8211; Avenida Juscelino Kubitscheck, 2760).<\/p>\n<p>Os interessados podem fazer o cadastro gratuitamente e devem levar carteira profissional, CPF, RG, t\u00edtulo de eleitor e n\u00famero do PIS. A rela\u00e7\u00e3o completa das vagas do Centro Integrado de Emprego, Trabalho e Renda, que s\u00e3o atualizadas diariamente, pode ser consultada no site <a href=\"http:\/\/www.guarulhos.sp.gov.br\/\" target=\"_blank\">www.guarulhos.sp.gov.br<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Centro Integrado de Emprego, Trabalho e Renda (CIET) de Guarulhos, na regi\u00e3o metropolitana de S\u00e3o Paulo, oferece nesta semana 3.465 postos de trabalho. Os cargos com maior n\u00famero de vagas s\u00e3o para auxiliar de produ\u00e7\u00e3o (369), operador de telemarketing (231), ajudante de carga e descarga (226), motorista de caminh\u00e3o (114), auxiliar de limpeza (88), [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[370,353],"tags":[],"class_list":["post-19662","post","type-post","status-publish","format-standard","category-inscricao","category-oportunidades","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/19662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=19662"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/19662\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=19662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=19662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=19662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}