{"id":193103,"date":"2020-05-26T00:04:57","date_gmt":"2020-05-26T03:04:57","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=193103"},"modified":"2020-05-25T20:58:35","modified_gmt":"2020-05-25T23:58:35","slug":"quina-5279-sorteio-nesta-terca-feira-26-05","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2020\/quina-5279-sorteio-nesta-terca-feira-26-05\/193103","title":{"rendered":"\u201cQuina\u201d 5279: sorteio nesta ter\u00e7a-feira, 26\/05"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-149254\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/quina-resultado-400x300.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/quina-resultado-400x300.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/quina-resultado-250x187.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/quina-resultado-150x113.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/quina-resultado-265x198.jpg 265w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/quina-resultado.jpg 500w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/> O resultado do sorteio da <strong><em>\u201cQuina\u201d 5279<\/em><\/strong> ser\u00e1 conhecido nesta ter\u00e7a-feira, 26\/05, ap\u00f3s a auditoria do concurso pelo p\u00fablico presente e agentes nomeados. O pr\u00eamio do concurso pode ultrapassar o valor estimado em R$ 3.300.000,00. <\/p>\n<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/2020\/veja-como-apostar-na-quina-de-sao-joao-2020-premio-ja-ultrapassa-r-104-milhoes\/192151\">Quina 5299 &#8220;Quina de S\u00e3o Jo\u00e3o&#8221;: pr\u00eamio para 27\/06 pode ultrapassar R$ 140 milh\u00f5es<\/a><\/p>\n\n<p>Sempre que os n\u00fameros \u201cQuina\u201d s\u00e3o divulgados, o portal RedeNot\u00edcia apresenta um hist\u00f3rico das dezenas sorteadas para orientar os apostadores. Al\u00e9m disso, ap\u00f3s o rateio apresentamos an\u00e1lise sobre valores e locais dos pr\u00eamios.<\/p>\n<p>Parte do total arrecadado com os jogos da &#8220;Quina&#8221; s\u00e3o revertidos para fundos e programas sociais do governo federal nas \u00e1reas de seguridade social, cultura, seguran\u00e7a p\u00fablica e esporte.<\/p>\n<p>O Concurso Especial da \u201cQuina\u201d (&#8220;Quina de S\u00e3o Jo\u00e3o&#8221;) \u00e9 realizado sempre no dia 24 de junho de cada ano civil, exceto quando a data cair no domingo. N\u00e3o existindo aposta premiada na 1\u00aa faixa (quina), este valor ser\u00e1 somado ao valor da 2\u00aa faixa e rateado entre as apostas que contiverem 4 progn\u00f3sticos certos (quadra). N\u00e3o existindo apostas premiadas nas quatro faixas de premia\u00e7\u00e3o, os valores acumulam para o concurso seguinte, na 1\u00aa faixa de premia\u00e7\u00e3o.<\/p>\n<p>O recibo da aposta \u201cQuina\u201d \u00e9 o \u00fanico documento que comprova o registro da aposta no sistema de loterias e que habilita ao recebimento dos pr\u00eamios. Sobre o pagamento do pr\u00eamio incidir\u00e1 uma al\u00edquota a t\u00edtulo de Imposto de Renda, conforme legisla\u00e7\u00e3o tribut\u00e1ria vigente. A tributa\u00e7\u00e3o dos pr\u00eamios \u00e9 efetuada diretamente na fonte, cabendo aos ganhadores os valores l\u00edquidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O resultado do sorteio da \u201cQuina\u201d 5279 ser\u00e1 conhecido nesta ter\u00e7a-feira, 26\/05, ap\u00f3s a auditoria do concurso pelo p\u00fablico presente e agentes nomeados. O pr\u00eamio do concurso pode ultrapassar o valor estimado em R$ 3.300.000,00. Quina 5299 &#8220;Quina de S\u00e3o Jo\u00e3o&#8221;: pr\u00eamio para 27\/06 pode ultrapassar R$ 140 milh\u00f5es Sempre que os n\u00fameros \u201cQuina\u201d s\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":177897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,358],"tags":[476,531],"class_list":{"0":"post-193103","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-quina","9":"tag-loteria","10":"tag-numeros-sorteados","11":"entry","12":"gs-1","13":"gs-odd","14":"gs-even","15":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-premio-quina.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/193103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=193103"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/193103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/177897"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=193103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=193103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=193103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}