{"id":19111,"date":"2009-12-03T15:01:20","date_gmt":"2009-12-03T19:01:20","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=19111"},"modified":"2009-12-03T15:01:20","modified_gmt":"2009-12-03T19:01:20","slug":"terminam-amanha-as-inscricoes-para-a-sp-escola-de-teatro","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/terminam-amanha-as-inscricoes-para-a-sp-escola-de-teatro\/19111","title":{"rendered":"Terminam amanh\u00e3 as inscri\u00e7\u00f5es para a SP Escola de Teatro"},"content":{"rendered":"<p>Terminam nesta sexta-feira, 4, as <strong><em>inscri\u00e7\u00f5es para a SP Escola de Teatro<\/em><\/strong> &#8211; Centro de Forma\u00e7\u00e3o das Artes do Palco, j\u00e1 em funcionamento em S\u00e3o Paulo, no bairro do Br\u00e1s. A institui\u00e7\u00e3o oferecer\u00e1 oito cursos regulares &#8211; atua\u00e7\u00e3o, cenografia e figurino, dire\u00e7\u00e3o, dramaturgia, humor, ilumina\u00e7\u00e3o, sonoplastia e t\u00e9cnicas de palco, com dura\u00e7\u00e3o de dois anos. Os cursos ser\u00e3o gratuitos e cada turma ter\u00e1 25 alunos. Ser\u00e3o oferecidos tamb\u00e9m cursos livres, de seis meses, nas mesmas habilidades, com 50 alunos por turma. A escola, iniciativa da Secretaria de Cultura, oferecer\u00e1 1,2 mil vagas ao ano. Duzentas delas para alunos regulares e as demais destinadas aos alunos de cursos de difus\u00e3o cultural.<br \/>\nDurante nove meses, a Oficina Am\u00e1cio Mazzaropi, inteiramente reformada e adaptada para pessoas com defici\u00eancia, ser\u00e1 sede da SP Escola de Teatro, enquanto outro espa\u00e7o, na Pra\u00e7a Roosevelt, tamb\u00e9m passa por reformas para abrigar a escola em definitivo, a partir de agosto de 2010.<\/p>\n<p>No dia seguinte \u00e0 inaugura\u00e7\u00e3o, que aconteceu em 25 de novembro, a Escola de Teatro abriu suas portas para o p\u00fablico, com uma movimentada programa\u00e7\u00e3o cultural que incluiu diversas confer\u00eancias, exposi\u00e7\u00f5es e espet\u00e1culos, al\u00e9m das inscri\u00e7\u00f5es. Destaque para a sele\u00e7\u00e3o dos professores.<\/p>\n<p>A anima\u00e7\u00e3o e o entusiasmo tomaram conta dos primeiros candidatos que foram \u00e0 Oficina Am\u00e1cio Mazzaropi, a maioria com alguma experi\u00eancia na \u00e1rea, como as amigas Nani Cattapreta, Cristina Vilela e Elza de Melo. Nani trabalhou anos em cenografia e figurino, agora quer atuar, enquanto as duas amigas pretendem fazer humor. &#8220;S\u00e3o tantas as op\u00e7\u00f5es que fiquei na d\u00favida para decidir entre dire\u00e7\u00e3o e humor&#8221;, diz Cristina.<\/p>\n<p>J\u00e1 Rog\u00e9rio dos Santos Prado, inspetor de qualidade, gosta de sonoplastia, mas preferiu optar por atua\u00e7\u00e3o. Para ele, que fez a Escola Macuna\u00edma, esta \u00e9 uma oportunidade \u00fanica de retornar. &#8220;Muito positivo uma escola com esse grau de inclus\u00e3o, principalmente para as pessoas de baixa renda que poder\u00e3o solicitar bolsa de estudos&#8221;. Poder\u00e1 concorrer \u00e0 bolsa e receber R$ 545 mensalmente durante o per\u00edodo em que estiver na escola o aluno que estuda ou estudou integralmente em escola p\u00fablica e que tenha renda de at\u00e9 R$ 1.090 por m\u00eas na fam\u00edlia.<\/p>\n<p>Jady Peres Fortes, 20 anos, segundo ano de artes c\u00eanicas em universidade particular, acompanhada da colega de Faculdade, Andr\u00e9a Dian Vieira, foi atra\u00edda pelos bons profissionais e pela possibilidade de exercer a arte c\u00eanica de maneira mais pr\u00e1tica. &#8220;Sem contar, \u00e9 claro, o fato de ser gratuito. Vou economizar R$ 1 mil da mensalidade do curso superior&#8221;.<\/p>\n<p>Os coordenadores que desenvolveram e pensaram o projeto s\u00e3o pedagogos que trabalham h\u00e1 anos nas suas \u00e1reas. Muitos s\u00e3o egressos da Escola de Arte Dram\u00e1tica, de forma\u00e7\u00e3o cl\u00e1ssica, ou da Escola Livre de Teatro de Santo Andr\u00e9, outro modelo, e apostam numa forma\u00e7\u00e3o mais din\u00e2mica. N\u00e3o quer\u00edamos que a SP Escola de Teatro tivesse s\u00f3 um olhar, mas v\u00e1rios, explica Cabral. Por isso, criou-se o eixo tem\u00e1tico e operador em que s\u00e3o trabalhados desde o realismo, o \u00e9pico e o perform\u00e1tico, aos quais se juntou o curso de humor.<\/p>\n<p>Os alunos devem percorrer quatro est\u00e1gios, ou m\u00f3dulos, inspirados nas cores do Metr\u00f4: vermelho, amarelo, azul e verde. O curso se fecha em cada bloco desses. Isso significa que o aluno pode escolher o m\u00f3dulo que desejar: come\u00e7ar no vermelho, ir para o verde, o azul e terminar no amarelo.<\/p>\n<p>Servi\u00e7o<\/p>\n<p>SP Escola de Teatro &#8211; Avenida Rangel Pestana, 2.401 &#8211; Br\u00e1s<br \/>\nMais informa\u00e7\u00f5es podem ser obtidas pelo telefone 2292-7988<br \/>\nAs aulas come\u00e7am no dia 20 de fevereiro de 2010<\/p>\n<p>Da Ag\u00eancia Imprensa oficial<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Terminam nesta sexta-feira, 4, as inscri\u00e7\u00f5es para a SP Escola de Teatro &#8211; Centro de Forma\u00e7\u00e3o das Artes do Palco, j\u00e1 em funcionamento em S\u00e3o Paulo, no bairro do Br\u00e1s. A institui\u00e7\u00e3o oferecer\u00e1 oito cursos regulares &#8211; atua\u00e7\u00e3o, cenografia e figurino, dire\u00e7\u00e3o, dramaturgia, humor, ilumina\u00e7\u00e3o, sonoplastia e t\u00e9cnicas de palco, com dura\u00e7\u00e3o de dois anos. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[370,353],"tags":[],"class_list":["post-19111","post","type-post","status-publish","format-standard","category-inscricao","category-oportunidades","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/19111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=19111"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/19111\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=19111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=19111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=19111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}