{"id":18433,"date":"2009-11-25T17:52:44","date_gmt":"2009-11-25T21:52:44","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=18433"},"modified":"2009-11-25T17:52:44","modified_gmt":"2009-11-25T21:52:44","slug":"3-040-vagas-de-emprego-em-guarulhos","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/3-040-vagas-de-emprego-em-guarulhos\/18433","title":{"rendered":"3.040 vagas de emprego em Guarulhos"},"content":{"rendered":"<p>O <strong>Centro Integrado de Emprego, Trabalho e Renda<\/strong> (<strong>CIET<\/strong>) de Guarulhos, na regi\u00e3o metropolitana de S\u00e3o Paulo, oferece nesta semana 3.040 postos de trabalho. Os cargos com maior n\u00famero de vagas s\u00e3o para auxiliar de produ\u00e7\u00e3o (269), ajudante de carga e descarga (226), operador de telemarketing (113), operador de supermercado (101), motorista de caminh\u00e3o (84), consultor de vendas (45), a\u00e7ougueiro (37) e despachante de embarque (30).<\/p>\n<p>A carga hor\u00e1ria, os benef\u00edcios e a escolaridade variam de acordo com os cargos pretendidos. A faixa salarial varia de R$ 465 (atendente de lanchonete, auxiliar de limpeza, lavador de carros, office-boy e passadeira) a R$ 4.500 (controlador de qualidade). H\u00e1 tamb\u00e9m vagas com remunera\u00e7\u00e3o mais alta, como desenhista projetista mec\u00e2nico (R$ 3.600), analista de custos (R$ 3.500), controlador de or\u00e7amento (R$ 3.000), ferramenteiro (R$ 2.675) e vendedor interno (R$ 2.300).<\/p>\n<p>Do total de vagas abertas, 464 s\u00e3o para portadores de defici\u00eancia em ocupa\u00e7\u00f5es como auxiliar de linha de produ\u00e7\u00e3o (142), cobrador de transportes coletivos (65) e auxiliar administrativo (33). Os sal\u00e1rios variam de R$ 471 (ajudante de cozinha) a R$ 2.200 (mec\u00e2nico de manuten\u00e7\u00e3o de m\u00e1quina industrial).<\/p>\n<p>Os requisitos necess\u00e1rios para preencher os postos de trabalho variam de acordo com o cargo. Para se candidatar, \u00e9 preciso comparecer, das 8h \u00e0s 17h, de segunda \u00e0 sexta-feira, em um dos quatro postos do Centro Integrado de Emprego, Trabalho e Renda de Guarulhos (Posto Centro &#8211; Rua S\u00e3o Vicente de Paula, 163 \/ Posto Cumbica &#8211; Rua Capit\u00e3o Aviador Walter Ribeiro, 359 \/ Posto Vila Augusta &#8211; Rua Ant\u00f4nio Iervolino, 225 \/ Posto Pimentas &#8211; Avenida Juscelino Kubitscheck, 2760).<\/p>\n<p>Os interessados podem fazer o cadastro gratuitamente e devem levar carteira profissional, CPF, RG, t\u00edtulo de eleitor e n\u00famero do PIS. A rela\u00e7\u00e3o completa das vagas do Centro Integrado de Emprego, Trabalho e Renda, que s\u00e3o atualizadas diariamente, pode ser consultada no site www.guarulhos.sp.gov.br.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Centro Integrado de Emprego, Trabalho e Renda (CIET) de Guarulhos, na regi\u00e3o metropolitana de S\u00e3o Paulo, oferece nesta semana 3.040 postos de trabalho. Os cargos com maior n\u00famero de vagas s\u00e3o para auxiliar de produ\u00e7\u00e3o (269), ajudante de carga e descarga (226), operador de telemarketing (113), operador de supermercado (101), motorista de caminh\u00e3o (84), [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[370,353],"tags":[],"class_list":{"0":"post-18433","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-inscricao","7":"category-oportunidades","8":"entry","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/18433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=18433"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/18433\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=18433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=18433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=18433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}