{"id":183969,"date":"2019-10-31T23:40:44","date_gmt":"2019-11-01T02:40:44","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=183969"},"modified":"2019-11-01T19:25:23","modified_gmt":"2019-11-01T22:25:23","slug":"a-fazenda-11-2019-votacao-em-bifao-e-diego-movimenta-a-enquete-da-roca","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2019\/a-fazenda-11-2019-votacao-em-bifao-e-diego-movimenta-a-enquete-da-roca\/183969","title":{"rendered":"&#8220;A Fazenda&#8221; 11 (2019): vota\u00e7\u00e3o em Bif\u00e3o e Diego movimentou a enquete da ro\u00e7a"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-182421\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/a-fazenda-enquete-resultado-316x300.jpg\" alt=\"\" width=\"316\" height=\"300\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/a-fazenda-enquete-resultado-316x300.jpg 316w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/a-fazenda-enquete-resultado-197x187.jpg 197w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/a-fazenda-enquete-resultado.jpg 520w\" sizes=\"auto, (max-width: 316px) 100vw, 316px\" \/> <strong><em>&#8220;A Fazenda&#8221; 11 (2019) enquete<\/em><\/strong> sobre a vota\u00e7\u00e3o em Bif\u00e3o e Diego, que movimentou a vota\u00e7\u00e3o: Em 31\/10, Diego recebeu a maioria dos votos do p\u00fablico, 59,05%, e continua no jogo. Bif\u00e3o se despediu de &#8220;A Fazenda&#8221; 2019. A forma\u00e7\u00e3o da sexta ro\u00e7a desta edi\u00e7\u00e3o come\u00e7ou quando o apresentador Marcos Mion chamou os pe\u00f5es para a \u00e1rea de vota\u00e7\u00e3o. Com o resultado da enquete sobre a Chama Vermelha, o dono do poder deve imunizar um pe\u00e3o \u00e0 Ro\u00e7a (exceto ele mesmo). Rodrigo abriu o Lampi\u00e3o e ficou com o poder da Chama Verde. Ele deu o poder da Chama Vermelha para o Diego. O pe\u00e3o imunizou Sabrina. O Fazendeiro Lucas indicou Bif\u00e3o.<\/p>\n<p>Os pe\u00f5es de &#8220;A Fazenda&#8221; 11 apresentaram seus votos nos concorrentes da sede: Netto, Rodrigo e Thayse votaram no Diego, que votou na Thayse. Viny e Andr\u00e9a votaram na Thayse. Guilherme e Bif\u00e3o votaram no Rodrigo. Sabrina votou na Hari, que votou no Diego. Ap\u00f3s ir para a ro\u00e7a, Diego indicou Netto. Rodrigo usou o poder da Chama Verde e mandou Bif\u00e3o direto para a vota\u00e7\u00e3o. Netto e Diego disputaram a prova do Fazendeiro nesta ter\u00e7a (29): vendados, os pe\u00f5es precisaram ultrapassar um circuito de obst\u00e1culos para transportar e encaixar bast\u00f5es. Diego se machucou, Netto conquistou o chap\u00e9u do Fazendeiro e se livrou da ro\u00e7a. Veja o resultado da vota\u00e7\u00e3o na enquete:<\/p>\n<p><script type=\"text\/javascript\" charset=\"utf-8\" data-cfasync=\"false\" src=\"https:\/\/secure.polldaddy.com\/p\/10445653.js\"><\/script><br \/>\n<noscript><a href=\"https:\/\/poll.fm\/10445653\">Quem deve continuar em &#8220;A Fazenda&#8221;?<\/a><\/noscript><\/p>\n<p>O voto v\u00e1lido \u00e9 registrado no portal oficial do programa.<\/p>\n<p>&#8212;<br \/>\nEquipe Sol 2019 &#8211; Aricia Silva (eliminada), Andr\u00e9a N\u00f3brega, Guilherme Le\u00e3o, Drika Marinho (eliminada), Phellipe Haagensen (substitu\u00eddo por Jorge Souza, eliminado), Viny Vieira, Bif\u00e3o (eliminada) e Netto.<\/p>\n<p>Equipe Lua 2019 &#8211; Thayse Teixeira, Hari Almeida, Sabrina Paiva, Lucas Viana, Tati Dias (eliminada), Rodrigo Phavanello, T\u00falio Maravilha (eliminado) e Diego Grossi.<\/p>\n<p>&#8212;<br \/>\nPe\u00f5es de 2019<\/p>\n<p>01 &#8211; Andr\u00e9a N\u00f3brega, ex-mulher de Carlos Alberto, fez parte de A Pra\u00e7a \u00c9 Nossa;<br \/>\n02 &#8211; Aricia Silva, do P\u00e2nico (eliminada);<br \/>\n03 &#8211; Diego Grossi, do BBB;<br \/>\n04 &#8211; Drika Marinho, do Power Couple (eliminada);<br \/>\n05 &#8211; Guilherme Le\u00e3o, modelo, o &#8220;seguran\u00e7a gato do Metr\u00f4&#8221;;<br \/>\n06 &#8211; Hari Almeida, do BBB;<br \/>\n07 &#8211; Jhenyfer Dulz, conhecida como Bif\u00e3o, do De F\u00e9rias Com o Ex (eliminada);<br \/>\n08 &#8211; Lucas Viana, do Are You The One? Brasil, reality de forma\u00e7\u00e3o de casais;<br \/>\n09 &#8211; Netto Rodrigues, que usa o nome art\u00edstico de NettoDJ;<br \/>\n10 &#8211; Phellipe Haagensen, ator (expulso);<br \/>\n11 &#8211; Rodrigo Phavanello, ator;<br \/>\n12 &#8211; Sabrina Paiva, Miss S\u00e3o Paulo em 2016;<br \/>\n13 &#8211; Tati Dias, do De F\u00e9rias Com o Ex (eliminada);<br \/>\n14 &#8211; Thayse Teixeira, influenciadora digital, conhecida como a &#8220;Dona do Cariri&#8221;;<br \/>\n15 &#8211; T\u00falio Maravilha, ex-jogador de futebol (eliminado);<br \/>\n16 &#8211; Viny Vieira, o Gluglu do P\u00e2nico;<br \/>\n17 &#8211; Jorge Souza, organizador de eventos (eliminado).<\/p>\n<p>Nesta edi\u00e7\u00e3o, ap\u00f3s cada elimina\u00e7\u00e3o haver\u00e1 uma live transmitida em todas as redes sociais do programa, comandada pelo humorista Lucas Salles, ao lado dos youtubers Tati e Marcelo da WebTVBrasileira.<\/p>\n<p>O reality show tem dire\u00e7\u00e3o do n\u00facleo de realities de Rodrigo Carelli, dire\u00e7\u00e3o geral de Fernando Viudez e produ\u00e7\u00e3o da Teleimage.<\/p>\n<p>&#8220;A Fazenda&#8221; Record<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;A Fazenda&#8221; 11 (2019) enquete sobre a vota\u00e7\u00e3o em Bif\u00e3o e Diego, que movimentou a vota\u00e7\u00e3o: Em 31\/10, Diego recebeu a maioria dos votos do p\u00fablico, 59,05%, e continua no jogo. Bif\u00e3o se despediu de &#8220;A Fazenda&#8221; 2019. A forma\u00e7\u00e3o da sexta ro\u00e7a desta edi\u00e7\u00e3o come\u00e7ou quando o apresentador Marcos Mion chamou os pe\u00f5es para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":182419,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[406,371,343],"tags":[521],"class_list":{"0":"post-183969","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-a-fazenda","8":"category-rede-record","9":"category-televisao","10":"tag-enquete","11":"entry","12":"gs-1","13":"gs-odd","14":"gs-even","15":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/a-fazenda-quem-sai.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/183969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=183969"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/183969\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/182419"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=183969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=183969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=183969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}