{"id":180617,"date":"2019-08-16T00:03:56","date_gmt":"2019-08-16T03:03:56","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=180617"},"modified":"2019-08-15T20:17:20","modified_gmt":"2019-08-15T23:17:20","slug":"lotomania-1996-sorteio-da-loteria-nesta-sexta-16-08","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2019\/lotomania-1996-sorteio-da-loteria-nesta-sexta-16-08\/180617","title":{"rendered":"&#8220;Lotomania&#8221; 1996: sorteio da loteria nesta sexta, 16\/08"},"content":{"rendered":"<p>O resultado do sorteio da <strong><em>&#8220;Lotomania&#8221; 1996 <\/em><\/strong>ser\u00e1 conhecido hoje, sexta, 16\/08, ap\u00f3s a auditoria do concurso pelo p\u00fablico presente e agentes nomeados. O pr\u00eamio do concurso pode ultrapassar o valor estimado em R$ 1.900.000,00. Sempre que os n\u00fameros &#8220;Lotomania&#8221; s\u00e3o divulgados, o portal RedeNot\u00edcia apresenta um hist\u00f3rico das dezenas sorteadas para orientar os apostadores. Al\u00e9m disso, ap\u00f3s o rateio apresentamos an\u00e1lise sobre valores e locais dos pr\u00eamios.<\/p>\n\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-149248\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio-lotomania-400x225.jpg\" alt=\"Resultado da Lotomania\" width=\"400\" height=\"225\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio-lotomania-400x225.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio-lotomania-250x140.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio-lotomania-768x432.jpg 768w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio-lotomania-150x84.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio-lotomania-696x392.jpg 696w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio-lotomania.jpg 940w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>Parte do total arrecadado com os jogos da &#8220;Lotomania&#8221; s\u00e3o revertidos para fundos e programas sociais do governo federal nas \u00e1reas de seguridade social, cultura, seguran\u00e7a p\u00fablica e esporte.<\/p>\n<p>O recibo &#8220;Lotomania&#8221; \u00e9 o \u00fanico documento que comprova o registro da aposta no sistema de loterias e que habilita ao recebimento dos pr\u00eamios. Sobre o pagamento do pr\u00eamio incidir\u00e1 uma al\u00edquota a t\u00edtulo de Imposto de Renda, conforme legisla\u00e7\u00e3o tribut\u00e1ria vigente. A tributa\u00e7\u00e3o dos pr\u00eamios \u00e9 efetuada diretamente na fonte, cabendo aos ganhadores os valores l\u00edquidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O resultado do sorteio da &#8220;Lotomania&#8221; 1996 ser\u00e1 conhecido hoje, sexta, 16\/08, ap\u00f3s a auditoria do concurso pelo p\u00fablico presente e agentes nomeados. O pr\u00eamio do concurso pode ultrapassar o valor estimado em R$ 1.900.000,00. Sempre que os n\u00fameros &#8220;Lotomania&#8221; s\u00e3o divulgados, o portal RedeNot\u00edcia apresenta um hist\u00f3rico das dezenas sorteadas para orientar os apostadores. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":177899,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,359],"tags":[476,531],"class_list":["post-180617","post","type-post","status-publish","format-standard","has-post-thumbnail","category-loteria","category-loto-mania","tag-loteria","tag-numeros-sorteados","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-premio-lotomania.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/180617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=180617"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/180617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/177899"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=180617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=180617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=180617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}