{"id":172700,"date":"2019-03-21T16:35:55","date_gmt":"2019-03-21T19:35:55","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=172700"},"modified":"2019-03-21T16:35:58","modified_gmt":"2019-03-21T19:35:58","slug":"previsao-do-tempo-na-regiao-sul-22-03-e-23-03","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2019\/previsao-do-tempo-na-regiao-sul-22-03-e-23-03\/172700","title":{"rendered":"Previs\u00e3o do tempo na Regi\u00e3o Sul 22\/03 e 23\/03"},"content":{"rendered":"<p><strong><em> Previs\u00e3o do tempo<\/em><\/strong> na Regi\u00e3o <em><strong>Sul<\/strong><\/em>, segundo o CPTEC\/INPE, em 22\/03\/2019: No litoral norte de SC e litoral do PR haver\u00e1 muitas nuvens e chuvas isoladas. No centro-oeste do RS e no oeste do PR o sol aparecer\u00e1 entre poucas nuvens. Nas demais \u00e1reas da regi\u00e3o haver\u00e1 nebulosidade vari\u00e1vel com possibilidade de pancadas de chuva a partir da tarde. Temperatura est\u00e1vel.<\/p>\n<p>23\/03\/2019: No oeste do RS e do PR o sol predominar\u00e1. No litoral do RS e de SC o dia ficar\u00e1 nublado com pancadas de chuva. No leste e nordeste do RS, leste de SC e no litoral do PR haver\u00e1 muitas nuvens e chuvas isoladas. Nas demais \u00e1reas da regi\u00e3o o sol aparecer\u00e1 entre poucas nuvens. Temperatura est\u00e1vel.<\/p>\n<p>Previs\u00e3o do tempo CPTEC\/INPE\/MCTI<\/p>\n<p>&#8212;<\/p>\n<p>O CPTEC (Centro de Previs\u00e3o de Tempo e Estudos Clim\u00e1ticos) do INPE (Instituto Nacional de Pesquisas Espaciais) \u00e9 o passaporte do Brasil para o primeiro mundo das previs\u00f5es meteorol\u00f3gicas. Com o novo supercomputador (CRAY XT6), rec\u00e9m adquirido, ser\u00e1 poss\u00edvel ao Centro melhorar a resolu\u00e7\u00e3o espacial dos modelos de previs\u00e3o de tempo, de clima sazonal, ambiental (qualidade do ar) e de proje\u00e7\u00f5es de cen\u00e1rios de mudan\u00e7as clim\u00e1ticas. O CPTEC j\u00e1 vem aperfei\u00e7oando seus modelos para que o novo supercomputador tamb\u00e9m possa gerar previs\u00f5es com mais dias de anteced\u00eancia, al\u00e9m de prever chuvas e eventos extremos com maior confiabilidade.<\/p>\n<p>O cluster UNA com 1100 processadores tem capacidade de processar at\u00e9 5.7 trilh\u00f5es de opera\u00e7\u00f5es aritm\u00e9ticas em ponto flutuante por segundo. Tudo isso, significa possibilidade de utilizar modelos num\u00e9ricos para simula\u00e7\u00e3o de tempo e clima, integrando informa\u00e7\u00f5es atmosf\u00e9ricas e oce\u00e2nicas. O resultado disso s\u00e3o previs\u00f5es de tempo confi\u00e1veis, para todo o pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo na Regi\u00e3o Sul, segundo o CPTEC\/INPE, em 22\/03\/2019: No litoral norte de SC e litoral do PR haver\u00e1 muitas nuvens e chuvas isoladas. No centro-oeste do RS e no oeste do PR o sol aparecer\u00e1 entre poucas nuvens. Nas demais \u00e1reas da regi\u00e3o haver\u00e1 nebulosidade vari\u00e1vel com possibilidade de pancadas de chuva [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":148079,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-172700","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"entry","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/previsao-sul.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/172700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=172700"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/172700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/148079"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=172700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=172700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=172700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}