{"id":171690,"date":"2019-03-09T20:15:52","date_gmt":"2019-03-09T23:15:52","guid":{"rendered":"https:\/\/www.redenoticia.com.br\/noticia\/?p=171690"},"modified":"2019-03-12T20:30:03","modified_gmt":"2019-03-12T23:30:03","slug":"resultado-dia-de-sorte-122-veja-os-numeros-deste-sabado-09-03","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2019\/resultado-dia-de-sorte-122-veja-os-numeros-deste-sabado-09-03\/171690","title":{"rendered":"Resultado &#8220;Dia de Sorte&#8221; 122: veja os n\u00fameros deste s\u00e1bado (09\/03)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-149250\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio--400x225.jpg\" alt=\"\" width=\"400\" height=\"225\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio--400x225.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio--250x141.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio--768x432.jpg 768w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio--696x392.jpg 696w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio--150x84.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/loteria-resultado-sorteio-.jpg 940w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/> Os resultados <strong><em>&#8220;Dia de Sorte&#8221;<\/em><\/strong> s\u00e3o divulgados nas ter\u00e7as, quintas e s\u00e1bados. O sorteio do concurso 122, com pr\u00eamio estimado em R$ 1.200.000,00, aconteceu na noite deste s\u00e1bado (09\/03). O resultado foi divulgado ap\u00f3s o sorteio e os pr\u00eamios distribu\u00eddos entre os acertadores, mediante rateio.<\/p>\n\n<p>Com a confirma\u00e7\u00e3o do resultado, os vencedores devem retirar seus pr\u00eamios em at\u00e9 90 dias ap\u00f3s o sorteio. Ao t\u00e9rmino desse prazo, o bilhete premiado est\u00e1 prescrito e os valores s\u00e3o repassados ao Fundo de Financiamento ao Estudante do Ensino Superior (Fies).<\/p>\n<p>Todas as cotas participantes de uma aposta fracionada, Bol\u00e3o, tem exatamente os mesmos valores e probabilidades de premia\u00e7\u00e3o, o que resulta no direito dos apostadores a receberem a mesma premia\u00e7\u00e3o, em caso de aposta premiada, sendo facultado ao cliente a compra de uma ou mais cotas. Cada bol\u00e3o somente pode conter apostas referentes a uma modalidade de loteria. As modalidades de progn\u00f3sticos num\u00e9ricos que permitem esta forma de apostas s\u00e3o: Mega-Sena, Quina, Lotof\u00e1cil, Dupla Sena e &#8220;Dia de Sorte&#8221;.<\/p>\n<p>O apostador pode escolher o tipo de jogo com o qual mais se identifica. As Loterias oferecem modalidades de apostas para atender a diferentes perfis: dos f\u00e3s de futebol, que acompanham os campeonatos oficiais, aos apostadores que n\u00e3o abrem m\u00e3o de seus n\u00fameros da sorte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os resultados &#8220;Dia de Sorte&#8221; s\u00e3o divulgados nas ter\u00e7as, quintas e s\u00e1bados. O sorteio do concurso 122, com pr\u00eamio estimado em R$ 1.200.000,00, aconteceu na noite deste s\u00e1bado (09\/03). O resultado foi divulgado ap\u00f3s o sorteio e os pr\u00eamios distribu\u00eddos entre os acertadores, mediante rateio. Com a confirma\u00e7\u00e3o do resultado, os vencedores devem retirar seus [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":148113,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[478,335,492],"tags":[476,531],"class_list":{"0":"post-171690","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dia-de-sorte","8":"category-loteria","9":"category-resultado","10":"tag-loteria","11":"tag-numeros-sorteados","12":"entry","13":"gs-1","14":"gs-odd","15":"gs-even","16":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-dia-de-sorte-loteria.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/171690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=171690"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/171690\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/148113"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=171690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=171690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=171690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}