{"id":17089,"date":"2009-11-12T13:47:24","date_gmt":"2009-11-12T17:47:24","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=17089"},"modified":"2009-11-12T13:47:24","modified_gmt":"2009-11-12T17:47:24","slug":"ola-turista-chega-a-sao-paulo","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/ola-turista-chega-a-sao-paulo\/17089","title":{"rendered":"Ol\u00e1, turista! chega a S\u00e3o Paulo"},"content":{"rendered":"<p>Para receber com qualidade os turistas estrangeiros na <strong><em>Copa do Mundo de 2014<\/em><\/strong>, o <strong>Programa Ol\u00e1, Turista<\/strong>! oferecer\u00e1, em 2010, cursos online gratuitos de ingl\u00eas e espanhol para 80 mil profissionais ligados ao Turismo. O lan\u00e7amento do programa, uma parceria do Minist\u00e9rio do Turismo (MTur) com a Funda\u00e7\u00e3o Roberto Marinho, acontece nesta sexta-feira (13), \u00e0s 10h, no Museu do Futebol, no Est\u00e1dio Pacaembu, em S\u00e3o Paulo (SP). O Ol\u00e1, Turista! foi lan\u00e7ado em agosto no Rio de Janeiro, Salvador, Manaus e Fortaleza. O pr\u00f3ximo lan\u00e7amento ser\u00e1 em Recife.<\/p>\n<p>Estar\u00e3o presentes no evento o ministro do Turismo, Luiz Barretto, o presidente da Funda\u00e7\u00e3o Roberto Marinho, Jos\u00e9 Roberto Marinho, o presidente da S\u00e3o Paulo Turismo (SPTuris), Caio Luiz de Carvalho e o secret\u00e1rio de Estado de Esporte, Lazer e Turismo, Claury Santos Alves da Silva. O objetivo \u00e9 mobilizar as associa\u00e7\u00f5es locais ligadas \u00e0 cadeia do Turismo e promover a ades\u00e3o ao programa.<\/p>\n<p>O evento ter\u00e1 uma apresenta\u00e7\u00e3o c\u00f4mica do ator Luiz Sal\u00e9m, que mostrar\u00e1, de forma bem-humorada, a import\u00e2ncia da boa comunica\u00e7\u00e3o no atendimento ao turista estrangeiro. Um v\u00eddeo no qual profissionais ligados ao turismo contam suas expectativas sobre o curso tamb\u00e9m ser\u00e1 exibido.<\/p>\n<p>Ol\u00e1, Turista! &#8211; O programa ser\u00e1 implementado em treze cidades do Rio de Janeiro, Amazonas e Bahia, incluindo as capitais, e, agora, segue para outras tr\u00eas cidades-sede da Copa do Mundo de 2014: Fortaleza, Recife e S\u00e3o Paulo.<\/p>\n<p>O curso \u00e9 composto pelos m\u00f3dulos b\u00e1sico, profissional e regional. Os alunos que cumprirem os m\u00f3dulos obrigat\u00f3rios &#8211; que poder\u00e3o ser conclu\u00eddos no per\u00edodo de um ano -, receber\u00e3o um certificado. Trata-se da primeira a\u00e7\u00e3o concreta do MTur para a capacita\u00e7\u00e3o profissional motivada pela Copa do Mundo de 2014. O objetivo \u00e9 envolver o setor tur\u00edstico e a popula\u00e7\u00e3o brasileira numa ampla campanha de aprimoramento do receptivo tur\u00edstico.<\/p>\n<p>P\u00fablico do Ol\u00e1, Turista! &#8211; O Ol\u00e1, Turista! \u00e9 voltado aos profissionais do turismo que trabalham em contato direto com o turista como recepcionistas, telefonistas, gar\u00e7ons, balconistas, taxistas, atendentes, artes\u00e3os e outros. Para participar, \u00e9 necess\u00e1rio que o trabalhador esteja ligado a alguma entidade do setor.<\/p>\n<p>A English Town \u00e9 respons\u00e1vel pela plataforma e pelo m\u00f3dulo b\u00e1sico do Ol\u00e1, Turista!. A Funda\u00e7\u00e3o Roberto Marinho desenvolveu, junto a consultores, os m\u00f3dulos espec\u00edficos.<\/p>\n<p>As Inscri\u00e7\u00f5es &#8211; As entidades de Fortaleza, Recife, S\u00e3o Paulo, Amazonas, Rio de Janeiro e Bahia que quiserem solicitar vagas para 2010 podem se cadastrar at\u00e9 o dia 31 de dezembro no portal Ol\u00e1, Turista! &#8211; <a href=\"http:\/\/www.olaturista.org.br\" target=\"_blank\">www.olaturista.org.br<\/a> &#8211; e solicitar as vagas para seus associados. Os cursos come\u00e7am em janeiro de 2010.<\/p>\n<p>Mais informa\u00e7\u00f5es &#8211; O Ol\u00e1, Turista! prev\u00ea a parceria com telecentros locais para facilitar aos participantes o acesso \u00e0 internet. No site do programa, esses parceiros ficar\u00e3o mapeados como colaboradores e ter\u00e3o a logomarca da empresa vis\u00edvel no portal. Nos telecentros parceiros, chamados Salas de Conex\u00e3o, os alunos que desejarem ter\u00e3o ainda suporte t\u00e9cnico de monitores para acessar a escola virtual.<\/p>\n<p>A iniciativa marca tamb\u00e9m a cria\u00e7\u00e3o de um selo de qualidade no Turismo. A proposta \u00e9 instituir uma marca visual a ser concedida pelo Minist\u00e9rio do Turismo (MTur) a todas as institui\u00e7\u00f5es que aderirem \u00e0 forma\u00e7\u00e3o em l\u00ednguas estrangeiras a fim de melhorar o atendimento aos turistas. Nesse sentido, o selo ser\u00e1 tamb\u00e9m um instrumento importante para a consolida\u00e7\u00e3o da rede que se pretende construir com a implementa\u00e7\u00e3o do programa.<\/p>\n<p>Servi\u00e7o<\/p>\n<p>Evento: Lan\u00e7amento Ol\u00e1, Turista! S\u00e3o Paulo<\/p>\n<p>Dia: sexta-feira (13\/11)<\/p>\n<p>Hora: 10h<\/p>\n<p>Local: Museu do Futebol &#8211; Pra\u00e7a Charles Miller, s\/n\u00b0- Pacaembu &#8211; S\u00e3o Paulo (SP) &#8211; Est\u00e1dio do Pacaembu &#8211; Port\u00e3o principal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para receber com qualidade os turistas estrangeiros na Copa do Mundo de 2014, o Programa Ol\u00e1, Turista! oferecer\u00e1, em 2010, cursos online gratuitos de ingl\u00eas e espanhol para 80 mil profissionais ligados ao Turismo. O lan\u00e7amento do programa, uma parceria do Minist\u00e9rio do Turismo (MTur) com a Funda\u00e7\u00e3o Roberto Marinho, acontece nesta sexta-feira (13), \u00e0s [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[370,353],"tags":[],"class_list":{"0":"post-17089","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-inscricao","7":"category-oportunidades","8":"entry","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/17089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=17089"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/17089\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=17089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=17089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=17089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}