{"id":16873,"date":"2009-11-11T09:47:47","date_gmt":"2009-11-11T13:47:47","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=16873"},"modified":"2009-11-11T09:47:47","modified_gmt":"2009-11-11T13:47:47","slug":"o-mito-esta-de-volta-renault-relanca-a-grife-gordini","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/o-mito-esta-de-volta-renault-relanca-a-grife-gordini\/16873","title":{"rendered":"O mito est\u00e1 de volta: Renault relan\u00e7a a grife &#8220;Gordini&#8221;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-16874\" title=\"gordini\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/gordini-249x187.jpg\" alt=\"gordini\" width=\"249\" height=\"187\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/gordini-249x187.jpg 249w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/gordini-250x187.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/gordini.jpg 400w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/gordini-150x113.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/gordini-265x198.jpg 265w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/gordini-149x112.jpg 149w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/>S\u00edmbolo do triunfo franc\u00eas, o &#8220;<strong>Gordini<\/strong>&#8221; fez vibrar v\u00e1rias gera\u00e7\u00f5es de motoristas na busca de sensa\u00e7\u00f5es e emo\u00e7\u00f5es esportivas. A pintura, que mesclava o azul com as listras brancas, e a grade com quatro far\u00f3is redondos, se tornaram s\u00edmbolo de uma importante heran\u00e7a esportiva da hist\u00f3ria do Grupo <strong>Renault<\/strong>.<\/p>\n<p>Dentro de alguns meses, o emblem\u00e1tico nome &#8220;Gordini&#8221; voltar\u00e1 \u00e0s ruas. O Grupo Renault lan\u00e7ar\u00e1 novas vers\u00f5es assinadas &#8220;Gordini&#8221;, que complementar\u00e3o a gama de modelos Renault Sport, refor\u00e7ando assim, a oferta de produtos da marca Renault no segmento de esportivos compactos.<\/p>\n<p>Com estr\u00e9ia programada para o dia 25 de novembro, no Atelier Renault &#8211; situado na avenida Champs Elys\u00e9es (Paris), o Twingo Gordini R.S. ser\u00e1 o primeiro produto Renault Sport a ostentar a grife &#8220;Gordini&#8221;.<\/p>\n<p>Desenvolvidos a partir de modelos esportivos cujos desempenhos est\u00e3o, reconhecidamente, entre os melhores, as vers\u00f5es com a assinatura &#8220;Gordini&#8221; ser\u00e3o destinadas aos amantes das sensa\u00e7\u00f5es de dirigir e do design marcante. Para isso, a grife &#8220;Gordini&#8221; manter\u00e1 os valores de exclusividade e esportividade que foram o s\u00edmbolo do seu sucesso no passado hist\u00f3rico do Grupo Renault.<\/p>\n<p>Para refazer do mito &#8220;Gordini&#8221; uma realidade, o Grupo Renault naturalmente contou com o apoio da &#8220;Renault Sport Tecnologies&#8221;, subsidi\u00e1ria esportiva do Grupo Renault, que mant\u00e9m com sucesso a heran\u00e7a &#8220;Gordini&#8221; atrav\u00e9s de duas reconhecidas compet\u00eancias: a competi\u00e7\u00e3o automotiva e o desenvolvimento dos derivados esportivos.<\/p>\n<p>A &#8220;Renault Sport Tecnologies&#8221; foi a primeira a organizar competi\u00e7\u00f5es automobil\u00edsticas no mundo: a categoria World Series by Renault disputada em v\u00e1rios pa\u00edses reuniram, desde 2005, aproximadamente 3 milh\u00f5es de f\u00e3s, enquanto as disputas do M\u00e9gane Trophy e da Copa Clio, al\u00e9m da organiza\u00e7\u00e3o das &#8220;Jornadas da Paix\u00e3o&#8221;, fazem da &#8220;Renault Sport Tecnologies&#8221; uma presen\u00e7a marcante no setor.<\/p>\n<p>Tanto em competi\u00e7\u00f5es, como em produ\u00e7\u00e3o de ve\u00edculos em larga escala, os derivados esportivos, tais como: M\u00e9gane R.S., Clio R.S. e Twingo R.S., desenvolvidos pela &#8220;Renault Sport Tecnologies&#8221; est\u00e3o entre os modelos que, reconhecidamente, proporcionam o melhor desempenho em suas respectivas categorias.<\/p>\n<p>Gordini, a heran\u00e7a esportiva da marca Renault<br \/>\nCom aproximadamente 200.000 ve\u00edculos desenvolvidos em 20 anos para a Renault, Am\u00e9d\u00e9e Gordini escreveu uma das mais belas p\u00e1ginas da hist\u00f3ria esportiva da marca.<\/p>\n<p>Nascido em 1899, apenas um ano ap\u00f3s a comercializa\u00e7\u00e3o do primeiro Renault, Am\u00e9d\u00e9e Gordini provou sua genialidade em mec\u00e2nica desde a adolesc\u00eancia. Demonstrando, a princ\u00edpio, seus talentos de mec\u00e2nico em monopostos, permitiu \u00e0 Renault classificar quatro modelos R8 Gordini em 1\u00ba, 3\u00ba, 4\u00ba e 5\u00ba lugares do Rali da C\u00f3rsega, em 1964. Em 1966, a vers\u00e3o 1300 inaugurou a Copa Gordini: o R8 Gordini fez vibrar os amantes da dire\u00e7\u00e3o esportiva durante toda uma d\u00e9cada.<\/p>\n<p>Com apari\u00e7\u00f5es no cinema ao lado de figuras c\u00e9lebres, tais como Romy Schneider, Alain Delon ou Lino Ventura, o primeiro pequeno sed\u00e3 esportivo franc\u00eas tamb\u00e9m se destacava nas ruas junto aos jovens condutores. Assim nascia um movimento. O Gordini tornou-se o s\u00edmbolo do triunfo de toda uma gera\u00e7\u00e3o, que remete a um estado de esp\u00edrito: o de uma Fran\u00e7a que ganha e compartilha seus sucessos com todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00edmbolo do triunfo franc\u00eas, o &#8220;Gordini&#8221; fez vibrar v\u00e1rias gera\u00e7\u00f5es de motoristas na busca de sensa\u00e7\u00f5es e emo\u00e7\u00f5es esportivas. A pintura, que mesclava o azul com as listras brancas, e a grade com quatro far\u00f3is redondos, se tornaram s\u00edmbolo de uma importante heran\u00e7a esportiva da hist\u00f3ria do Grupo Renault. Dentro de alguns meses, o emblem\u00e1tico [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-16873","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"has-post-thumbnail","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=16873"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16873\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=16873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=16873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=16873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}