{"id":16773,"date":"2009-11-10T19:25:27","date_gmt":"2009-11-10T23:25:27","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=16773"},"modified":"2009-11-10T19:25:27","modified_gmt":"2009-11-10T23:25:27","slug":"menopausa-aumenta-riscos-de-disturbios-de-sono","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/menopausa-aumenta-riscos-de-disturbios-de-sono\/16773","title":{"rendered":"Menopausa aumenta riscos de dist\u00farbios de sono"},"content":{"rendered":"<p>Estudo aponta que ap\u00f3s a menopausa aumentam em 50% as chances das mulheres terem ins\u00f4nia e queixas de ronco. <strong>Tratamentos<\/strong> complementares como <strong>ioga<\/strong>, <strong>RPG<\/strong> e <strong>acupuntura<\/strong> podem ajudar muito na melhoria da qualidade sono na <strong>menopausa.\u00a0<span style=\"font-weight: normal;\">Uma nova pesquisa ser\u00e1 apresentada durante o 3\u00ba Congresso Mundial de Medicina do Sono. O estudo foi feito pela pesquisadora Helena Hachul no Instituto do Sono\/Unifesp e avaliou 931 mulheres de 50 a 65 anos na cidade de S\u00e3o Paulo com queixas de diversos de problemas de sono. Comparando mulheres na pr\u00e9-menopausa com mulheres na p\u00f3s-menopausa, as queixas de ronco e de dist\u00farbio respirat\u00f3rio foram respectivamente de 81,9% e 37,4% contra 68,8% e 28,9% nas mulheres na pr\u00e9-menopausa.<\/span><\/strong><\/p>\n<p>A pesquisa consistiu na elabora\u00e7\u00e3o de um question\u00e1rio sobre sono, menopausa, ciclo menstrual e polissonografia (exame que revela se a pessoa tem algum dist\u00farbio relacionado ao sono). A ins\u00f4nia, por causa da perda hormonal, e a apneia, pela diminui\u00e7\u00e3o da progesterona &#8211; um horm\u00f4nio estimulante, s\u00e3o os problemas mais frequentes nessa fase da vida da mulher. Os dist\u00farbios de sono no per\u00edodo p\u00f3s-menopausa, segundo a pesquisadora, atingem seis em cada dez mulheres e cerca de 50% das mulheres com queixa de ins\u00f4nia apresentam um dist\u00farbio respirat\u00f3rio do sono.<\/p>\n<p>Tratamentos alternativos<\/p>\n<p>Uma noite tranquila de sono est\u00e1 tamb\u00e9m relacionada diretamente ao dia a dia da mulher na p\u00f3s-menopausa. Alguns fatores indicam a necessidade de orienta\u00e7\u00e3o m\u00e9dica: indisposi\u00e7\u00e3o na hora das atividades cotidianas, dores de cabe\u00e7a e sono fragmentado durante a noite s\u00e3o indicativos de alguma altera\u00e7\u00e3o no organismo.<\/p>\n<p>Durante o 3\u00ba Congresso Mundial de Medicina do Sono, a m\u00e9dica respons\u00e1vel pelo ambulat\u00f3rio de dist\u00farbios do sono no climat\u00e9rio da Unifesp, Helena Hachul, destacar\u00e1 ainda os aspectos positivos da utiliza\u00e7\u00e3o da medicina alternativa, como massagem terap\u00eautica, ioga, fisioterapia, RPG, psicoterapia, e acupuntura, al\u00e9m da quest\u00e3o nutricional, que podem contribuir de forma decisiva na hora do tratamento para os dist\u00farbios relacionados com a menopausa. &#8220;Apostamos que ser\u00e1 uma tend\u00eancia. O dist\u00farbio do sono n\u00e3o pode ser encarado apenas como uma quest\u00e3o org\u00e2nica. Temos que olhar a mulher como um todo. Nesse contexto, a medicina alternativa e complementar pode ser valiosa para melhorar a qualidade de vida e, consequentemente, uma noite de sono&#8221;, explica a m\u00e9dica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudo aponta que ap\u00f3s a menopausa aumentam em 50% as chances das mulheres terem ins\u00f4nia e queixas de ronco. Tratamentos complementares como ioga, RPG e acupuntura podem ajudar muito na melhoria da qualidade sono na menopausa.\u00a0Uma nova pesquisa ser\u00e1 apresentada durante o 3\u00ba Congresso Mundial de Medicina do Sono. O estudo foi feito pela pesquisadora [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":{"0":"post-16773","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-saude-e-vida","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=16773"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16773\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=16773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=16773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=16773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}