{"id":16747,"date":"2009-11-09T19:06:23","date_gmt":"2009-11-09T23:06:23","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=16747"},"modified":"2009-11-09T19:08:31","modified_gmt":"2009-11-09T23:08:31","slug":"shimon-peres-estara-em-sp-nesta-quinta-feira-12","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/shimon-peres-estara-em-sp-nesta-quinta-feira-12\/16747","title":{"rendered":"Shimon Peres estar\u00e1 em SP nesta quinta-feira (12)"},"content":{"rendered":"<p>Nesta quinta-feira (12), a partir das 15 horas, o presidente de Israel, <strong>Shimon Peres<\/strong>, estar\u00e1 na Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de S\u00e3o Paulo (Fiesp) para encontro com o presidente da entidade, Paulo Skaf. Esta \u00e9 a primeira visita de um presidente de Israel ao Brasil em mais de 40 anos.\u00a0<\/p>\n<p>Shimon Peres estar\u00e1 acompanhado de 40 empres\u00e1rios israelenses nas \u00e1reas de tecnologia de \u00e1gua, agricultura, comunica\u00e7\u00f5es, energia, sa\u00fade e seguran\u00e7a. O ministro de Turismo, Stas Misezhnikov, tamb\u00e9m acompanha a delega\u00e7\u00e3o.<\/p>\n<p>Na ocasi\u00e3o, a Fiesp e a Associa\u00e7\u00e3o de Manufatureiros de Israel assinar\u00e3o acordo de coopera\u00e7\u00e3o econ\u00f4mica e de transfer\u00eancia tecnol\u00f3gica. A parceria entre as duas entidades servir\u00e1 de base para que os governos dos dois pa\u00edses intensifiquem as negocia\u00e7\u00f5es entre Mercosul e Israel, que ainda precisam ser ratificadas pelos pa\u00edses do bloco.<\/p>\n<p>Ap\u00f3s o encerramento do encontro, \u00e0s 17h45, Paulo Skaf e Shimon Peres participar\u00e3o de coletiva de imprensa. Os jornalistas interessados na cobertura, favor enviar pedido de credenciamento para fabio.rocha@fiesp.org.br, impreterivelmente at\u00e9 quarta-feira (11), \u00e0s 16 horas.<\/p>\n<p>Economia Israelense<\/p>\n<p>Ap\u00f3s crescer em m\u00e9dia 5,2% por quatro anos consecutivos, o Produto Interno Bruto (PIB) de Israel sentiu a crise financeira e fechou 2008 com alta de 3,9%. Proje\u00e7\u00f5es do FMI apontam um cen\u00e1rio de queda de 1,7% no PIB para este ano.<\/p>\n<p>A crise trouxe queda para a taxa b\u00e1sica de juros de Israel, que saiu de 4,% em agosto de 2008 para 0,5% em junho deste ano. Por outro lado, o \u00edndice de produ\u00e7\u00e3o industrial apresentou alta na compara\u00e7\u00e3o com o in\u00edcio da crise, apresentando um crescimento de 1,4% de agosto de 2008 at\u00e9 mar\u00e7o deste ano, mas sofreu queda de 5,4% em rela\u00e7\u00e3o a mar\u00e7o do ano passado.<\/p>\n<p>A corrente de com\u00e9rcio de Israel teve alta de 91,7% em 6 anos, saindo de US$ 66 bilh\u00f5es em 2003 para mais de US$ 126 bilh\u00f5es em 2008. No entanto, a balan\u00e7a comercial foi deficit\u00e1ria em todo este per\u00edodo, com saldo negativo de US$ 3,8 bilh\u00f5es.<\/p>\n<p>Os EUA s\u00e3o o principal parceiro comercial de Israel, respons\u00e1veis por absorver 32,6% das exporta\u00e7\u00f5es israelenses e teve participa\u00e7\u00e3o de 12,3% nas importa\u00e7\u00f5es. Em 2008 as vendas de Israel somaram US$ 61,3 bilh\u00f5es, com 32,5% de suas exporta\u00e7\u00f5es concentradas em pedras e metais preciosos. Do lado das compras, a pauta divide-se em setores como combust\u00edveis minerais (19,7%), pedras e metais preciosos (14,9%) e maquin\u00e1rio (10,8%), somando US$ 65,1 bilh\u00f5es em 2008.<\/p>\n<p>Atualmente, cerca de 80% das exporta\u00e7\u00f5es de Israel \u00e9 coberta por acordos comerciais. Al\u00e9m do acordo firmado com o Mercosul, Israel possui acordos de livre com\u00e9rcio com Canad\u00e1, Estados Unidos, M\u00e9xico, Turquia e Uni\u00e3o Europ\u00e9ia.<\/p>\n<p>Com\u00e9rcio Brasil-Israel<\/p>\n<p>O Brasil \u00e9 deficit\u00e1rio na balan\u00e7a comercial com Israel, fechando 2008 com saldo negativo de US$ 823 milh\u00f5es. A corrente comercial mais que triplicou nos seis \u00faltimos anos, saindo de US$ 506 milh\u00f5es em 2003 para mais de US$ 1,6 bilh\u00e3o em 2008. No ano passado, as exporta\u00e7\u00f5es somaram US$ 399 milh\u00f5es e as importa\u00e7\u00f5es US$ 1.2 bilh\u00e3o.<\/p>\n<p>Do lado das vendas, o Brasil exporta para Israel principalmente carnes (34,8%), e nas importa\u00e7\u00f5es a pauta \u00e9 altamente concentrada em adubos e fertilizantes (61,9%) e produtos qu\u00edmicos org\u00e2nicos (10,2%).<\/p>\n<p>Acordo de Livre Com\u00e9rcio Mercosul-Israel<br \/>\nO Acordo firmado em 2007 prev\u00ea a liberaliza\u00e7\u00e3o de mais de 90% do com\u00e9rcio entre as duas regi\u00f5es. Os produtos foram divididos em quatro cestas, com prazos diferenciados para o fim das tarifas de importa\u00e7\u00e3o: imediato, quatro, oito e dez anos.<\/p>\n<p>Um percentual de 5% e 8% estar\u00e1 sujeito a cotas de importa\u00e7\u00e3o; entram nesta lista produtos agr\u00edcolas como a\u00e7\u00facar, carnes e latic\u00ednios. Um percentual de 2% dos produtos ficar\u00e1 fora das negocia\u00e7\u00f5es.<\/p>\n<p>O Acordo foi aprovado pelo Uruguai em setembro de 2006 e pelo Paraguai em maio de 2008. Ainda est\u00e1 pendente de aprova\u00e7\u00e3o pelo Brasil e Argentina. No Brasil, o tema est\u00e1 em processo de aprova\u00e7\u00e3o no \u00e2mbito do Congresso Nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quinta-feira (12), a partir das 15 horas, o presidente de Israel, Shimon Peres, estar\u00e1 na Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de S\u00e3o Paulo (Fiesp) para encontro com o presidente da entidade, Paulo Skaf. Esta \u00e9 a primeira visita de um presidente de Israel ao Brasil em mais de 40 anos.\u00a0 Shimon Peres estar\u00e1 acompanhado [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-16747","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=16747"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/16747\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=16747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=16747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=16747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}